{"id":15084,"date":"2024-06-19T19:09:34","date_gmt":"2024-06-19T17:09:34","guid":{"rendered":"http:\/\/startitkbs.org\/?p=15084"},"modified":"2024-06-19T19:31:11","modified_gmt":"2024-06-19T17:31:11","slug":"lhistoire-de-serge-gainsbourg","status":"publish","type":"post","link":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/","title":{"rendered":"L\u2019HISTOIRE DE SERGE GAINSBOURG"},"content":{"rendered":"\n<p><strong>RAPIDE PR\u00c9SENTATION DE L\u2019ARTISTE :<\/strong><\/p>\n\n\n\n<p><strong>Serge Gainsbourg<\/strong>, n\u00e9 <strong>Lucien Ginsburg<\/strong> le 2 avril 1928 \u00e0 Paris et d\u00e9c\u00e9d\u00e9 le 2 mars 1991 est une figure embl\u00e9matique de la musique fran\u00e7aise. Auteur-compositeur-interpr\u00e8te, acteur et r\u00e9alisateur, il est c\u00e9l\u00e8bre pour ses textes audacieux et provocateurs. Il commence sa carri\u00e8re musicale dans les ann\u00e9es 1950 avec un style m\u00ealant chanson fran\u00e7aise et jazz. Les ann\u00e9es 1960 marquent sa collaboration avec <strong>Brigitte Bardot<\/strong> et le succ\u00e8s de &#8220;<em>Je t&#8217;aime\u2026 moi non plus<\/em>&#8221; avec <strong>Jane Birkin<\/strong>. Dans les ann\u00e9es 1970, il explore le rock et le reggae, notamment avec l&#8217;album controvers\u00e9 &#8220;<em>Aux armes et c\u00e6tera<\/em>&#8220;.<\/p>\n\n\n\n<p>Gainsbourg est reconnu pour ses jeux de mots, son ironie et sa capacit\u00e9 \u00e0 provoquer. Son \u0153uvre, traversant divers genres musicaux, continue d&#8217;influencer de nombreux artistes. Parmi ses titres les plus notables figurent &#8220;<em>Le Poin\u00e7onneur des Lilas<\/em>&#8221; (1958), &#8220;<em>La Javanaise<\/em>&#8221; (1963) et &#8220;<em>Histoire de Melody Nelson<\/em>&#8221; (1971). Malgr\u00e9 un comportement autodestructeur en fin de vie, <strong>Gainsbourg<\/strong> reste un pilier de la culture musicale fran\u00e7aise,<br>symbole de cr\u00e9ativit\u00e9 et de libert\u00e9 d&#8217;expression.<\/p>\n\n\n\n<p><strong>ANALYSE DE SA CARRI\u00c8RE :<\/strong><\/p>\n\n\n\n<p>La carri\u00e8re musicale du futur <strong>Serge Gainsbourg<\/strong> ne commence pourtant pas \u00e0 ses 30 ans en 1958. D\u2019abord activit\u00e9 \u00e0 but lucratif, la musique va progressivement gagner en importance pour <strong>Lucien Ginsburg<\/strong> qui commence m\u00eame \u00e0 composer des chansons. En 1954, il franchit le cap et d\u00e9pose ses premiers textes \u00e0 la Soci\u00e9t\u00e9 des auteurs, compositeurs et \u00e9diteurs de musique (Sacem) sous le nom de <strong>Julien Gris<\/strong>. Une r\u00e9f\u00e9rence \u00e0 <strong>Julien Sorel<\/strong>, le personnage principal du roman de <strong>Stendahl<\/strong> &#8220;<em>le Rouge et le Noir<\/em>&#8220;. Parmi les titres enregistr\u00e9s, ce morceau intitul\u00e9  &#8220;<em>De Vienne \u00e0 Vienne<\/em>&#8221; restera longtemps un in\u00e9dit avant d\u2019\u00eatre enregistr\u00e9 en 1961. Mais <strong>Lucien<\/strong> n\u2019est d\u00e9j\u00e0 plus <strong>Julien Gris<\/strong>, rev\u00eatant depuis 1958 les habits de gloire, de son nouveau personnage, <strong>Serge Gainsbourg<\/strong>.<\/p>\n\n\n\n<p>La gloire ne tombe pas sur <strong>Serge Gainsbourg<\/strong> instantan\u00e9ment mais son premier album &#8220;<em>Du chant \u00e0 la une !<\/em>&#8221; sorti en 1958 lui vaut un succ\u00e8s d\u2019estime. <strong>Serge Gainsbourg<\/strong> retient l\u2019attention d\u2019artistes de l\u2019\u00e9poque comme <strong>Boris Vian<\/strong> ou <strong>Marcel Aym\u00e9<\/strong>. Avec &#8220;<em>Le Poin\u00e7onneur des Lilas<\/em>&#8220;, premier titre de l\u2019album, il s\u2019assure aussi son premier classique.<\/p>\n\n\n\n<p>Avant les autres artistes de sa g\u00e9n\u00e9ration, <strong>Serge Gainsbourg<\/strong> sait sentir les sons et leur ambiance, n&#8217;h\u00e9sitant pas \u00e0 aller \u00e0 l&#8217;\u00e9tranger enregistrer ses disques afin de mieux sentir l&#8217;air du temps. Il passe pour la premi\u00e8re fois en vedette \u00e0 l&#8217;Olympia en 1963. Quand la vague y\u00e9y\u00e9 d\u00e9ferle sur le pays, il est d&#8217;abord d\u00e9stabilis\u00e9 mais tr\u00e8s vite, il va prouver son talent pour devancer les \u00e9volutions dans les go\u00fbts musicaux de son public. Il d\u00e9couvre <strong>France Gall<\/strong> et lance <strong>R\u00e9gine<\/strong>, <strong>Petula Clark<\/strong>, <strong>Dalida<\/strong> , <strong>Anna Karina<\/strong>, <strong>Fran\u00e7oise Hardy<\/strong> ou encore <strong>Catherine Deneuve<\/strong> .<\/p>\n\n\n\n<p>Il vit \u00e9galement une Passion artistique avec <strong>Brigitte Bardot<\/strong> , qui culmine avec &#8220;<em>Je t&#8217;aime moi non plus<\/em>&#8220;. La vedette, effray\u00e9e par les cons\u00e9quences que cela pourrait avoir sur son mariage avec <strong>Gunter Sachs<\/strong>, lui demande de ne pas la sortir. Sa rencontre avec <strong>Jane Birkin<\/strong> va marquer leurs vies respectives ainsi que le patrimoine de la Chanson fran\u00e7aise. C&#8217;est avec elle qu&#8217;il r\u00e9-enregistra &#8220;<em>Je t&#8217;aime moi non plus<\/em>&#8220;. La Chanson sort et provoque un \u00e9norme scandale. Apr\u00e8s deux mariages \u00e9ph\u00e9m\u00e8res, <strong>Serge Gainsbourg<\/strong> vit avec <strong>Jane Birkin<\/strong> et leur fille <strong>Charlotte<\/strong> une vie de famille plus calme.<\/p>\n\n\n\n<p>A partir des ann\u00e9es 70, ses probl\u00e8mes cardiaques, sa clope \u00e9ternellement au bec, sa barbe de trois jours et ses probl\u00e8mes d&#8217;alcool cr\u00e9ent l&#8217;image d&#8217;un dandy &#8220;grunge&#8221; avant l&#8217;heure de plus en plus populaire aupr\u00e8s de plusieurs g\u00e9n\u00e9rations qui semblent lui pardonner tous ses &#8220;\u00e9carts&#8221; de conduite. Eternel provocateur, il n&#8217;h\u00e9site pas \u00e0 proposer une version tr\u00e8s reggae de &#8220;<em>La Marseillaise<\/em>&#8221; qui \u00e9meut beaucoup les conservateurs de tout poil. Apr\u00e8s une douzaine d&#8217;ann\u00e9es de vie communes, <strong>Jane Birkin<\/strong> et <strong>Serge Gainsbourg<\/strong> se s\u00e9parent en bons amis. Une ultime femme s&#8217;appr\u00eate \u00e0 entrer dans sa vie et elle a pour nom <strong>Bambou<\/strong>.<\/p>\n\n\n\n<p>D\u2019outrances en exc\u00e8s, <strong>Serge Gainsbourg<\/strong> se consume petit \u00e0 petit c\u00e9dant \u00e0 ses nombreuses addictions. Ses apparitions t\u00e9l\u00e9vis\u00e9es tournent \u00e0 la caricature, le chanteur \u00e9tant le plus souvent ivre. <strong>Serge Gainsbourg<\/strong> s\u2019\u00e9teint pour laisser la place \u00e0 <strong>Gainsbarre<\/strong> qu\u2019il pr\u00e9sente au grand public dans son titre \u00ab <em>Ecce homo<\/em> \u00bb sorti en 1981 sur l\u2019album &#8220;<em>Mauvaises nouvelles des \u00e9toiles<\/em>&#8220;.<\/p>\n\n\n\n<p>Avec la soixantaine, la sant\u00e9 de <strong>Serge Gainsbourg<\/strong> devient de plus en plus fragile et les alertes cardiaques se succ\u00e8dent. Il doit aussi arr\u00eater de boire. Ce ne sera pas suffisant et le 2 mars 1991, il succombe \u00e0 une ultime attaque. L&#8217;hommage \u00e0 cet artiste est unanime. Quelques semaines apr\u00e8s son d\u00e9c\u00e8s, <strong>Jane Birkin<\/strong> monte sur la sc\u00e8ne du casino de Paris. Sa Muse sortira \u00e9galement &#8220;<em>Arabesque<\/em>&#8220;. Un album aux arrangements arabisants dans lequel elle reprend quelques unes des \u0153uvres de <strong>Serge Gainsbourg<\/strong> .<\/p>\n\n\n\n<p>En conclusion, <strong>Serge Gainsbourg<\/strong>, par son audace et son \u00e9clectisme, a profond\u00e9ment marqu\u00e9 la musique fran\u00e7aise. Ses collaborations, ses explorations musicales vari\u00e9es, et ses textes provocateurs continuent d&#8217;influencer la sc\u00e8ne contemporaine. Il demeure une ic\u00f4ne de cr\u00e9ativit\u00e9 et de libert\u00e9 d&#8217;expression, laissant un h\u00e9ritage ind\u00e9l\u00e9bile.<\/p>\n\n\n\n<p><br>Enjoy and stay tuned<\/p>\n\n\n\n<p><br>Mac\u00e9o Germain<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RAPIDE PR\u00c9SENTATION DE L\u2019ARTISTE : Serge Gainsbourg, n\u00e9 Lucien Ginsburg le 2 avril 1928 \u00e0 Paris et d\u00e9c\u00e9d\u00e9 le 2 mars 1991 est une figure embl\u00e9matique de la musique fran\u00e7aise. Auteur-compositeur-interpr\u00e8te, acteur et r\u00e9alisateur, il est c\u00e9l\u00e8bre pour ses textes audacieux et provocateurs. Il commence sa carri\u00e8re musicale dans les ann\u00e9es 1950 avec un style &#8230; <a title=\"L\u2019HISTOIRE DE SERGE GAINSBOURG\" class=\"read-more\" href=\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/\">Lire la suite <span class=\"screen-reader-text\">L\u2019HISTOIRE DE SERGE GAINSBOURG<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":15121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[15,2559,2554,2546,2561,32,2558,2553,546,2560,2562,2544,2548,2547,2551,2552,2545,2555,12,2556,2557,2550,2543],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It<\/title>\n<meta name=\"description\" content=\"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd&#039;hui en d\u00e9tail la vie de ce monument de la musique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It\" \/>\n<meta property=\"og:description\" content=\"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd&#039;hui en d\u00e9tail la vie de ce monument de la musique.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T17:09:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T17:31:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg\",\"contentUrl\":\"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg\",\"width\":2560,\"height\":1379},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#webpage\",\"url\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/\",\"name\":\"L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#primaryimage\"},\"datePublished\":\"2024-06-19T17:09:34+00:00\",\"dateModified\":\"2024-06-19T17:31:11+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"description\":\"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd'hui en d\u00e9tail la vie de ce monument de la musique.\",\"breadcrumb\":{\"@id\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019HISTOIRE DE SERGE GAINSBOURG\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"http:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It","description":"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd'hui en d\u00e9tail la vie de ce monument de la musique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It","og_description":"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd'hui en d\u00e9tail la vie de ce monument de la musique.","og_url":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2024-06-19T17:09:34+00:00","article_modified_time":"2024-06-19T17:31:11+00:00","og_image":[{"width":2560,"height":1379,"url":"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#primaryimage","inLanguage":"fr-FR","url":"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg","contentUrl":"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/06\/serge-gainsbourg-et-jane-birkin-scaled.jpg","width":2560,"height":1379},{"@type":"WebPage","@id":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#webpage","url":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/","name":"L\u2019HISTOIRE DE SERGE GAINSBOURG - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#primaryimage"},"datePublished":"2024-06-19T17:09:34+00:00","dateModified":"2024-06-19T17:31:11+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"description":"Retour sur la vie de Serge Gainsbourg, ses succ\u00e8s mais aussi ses exc\u00e8s. D\u00e9couvrez aujourd'hui en d\u00e9tail la vie de ce monument de la musique.","breadcrumb":{"@id":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/startitkbs.org\/index.php\/2024\/06\/19\/lhistoire-de-serge-gainsbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"L\u2019HISTOIRE DE SERGE GAINSBOURG"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"http:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15084"}],"collection":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=15084"}],"version-history":[{"count":2,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15084\/revisions"}],"predecessor-version":[{"id":15120,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15084\/revisions\/15120"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/15121"}],"wp:attachment":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=15084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=15084"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=15084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}