{"id":15195,"date":"2024-10-17T18:30:39","date_gmt":"2024-10-17T16:30:39","guid":{"rendered":"http:\/\/startitkbs.org\/?p=15195"},"modified":"2024-10-17T18:30:41","modified_gmt":"2024-10-17T16:30:41","slug":"mac-miller-la-legende-rattrape-par-ses-demons","status":"publish","type":"post","link":"http:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/","title":{"rendered":"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons"},"content":{"rendered":"\n<p><strong>Mac Miller<\/strong> \u00e9tait un producteur, rappeur, \u00e9crivain et chanteur respect\u00e9 par le monde de la musique et aim\u00e9 par des millions de fans. Il a cr\u00e9\u00e9 tout un univers sonore autour de l&#8217;exp\u00e9rience chaotique d&#8217;un jeune artiste plong\u00e9 dans la gloire. Sa musique a explor\u00e9 la d\u00e9pression, l&#8217;isolement et l&#8217;addiction en m\u00eame temps qu&#8217;il gravissait les \u00e9chelons et devenait une star internationale. Sa capacit\u00e9 \u00e0 jouer tous les r\u00f4les dans le processus de production musicale a donn\u00e9 \u00e0 ses chansons un sentiment vif et color\u00e9 parce qu&#8217;il n&#8217;a pas seulement fait des chansons exprimant ses luttes, il a aussi fait des ballades R&amp;B romantiques, du slow smooth jazz et de v\u00e9ritables chansons \u00e0 succ\u00e8s.<\/p>\n\n\n\n<p><strong>Mac Miller <\/strong>\u00e9tait un v\u00e9ritable artiste et cela se voit dans la quantit\u00e9 apparemment infinie de mixtapes, de projets parall\u00e8les, d&#8217;albums, de singles et d&#8217;in\u00e9dits qu&#8217;il a produits tout au long de sa carri\u00e8re, qui sont tous de magnifiques fen\u00eatres sur son \u00e2me. Entrons dans l&#8217;histoire de <strong>Mac Miller<\/strong> et d\u00e9couvrons ce qui a fait de lui un artiste aussi impactant pour de nombreux auditeurs.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong>Un enfant vou\u00e9 \u00e0 devenir artiste<\/strong><\/h2>\n\n\n\n<p><strong>Malcolm James McCormick<\/strong> est n\u00e9 dans le quartier de Point Breeze \u00e0 Pittsburgh le <strong>19 janvier 1992<\/strong>. Son p\u00e8re \u00e9tait architecte et sa m\u00e8re photographe. Ayant \u00e9t\u00e9 \u00e9lev\u00e9 par deux artistes, il n\u2019est pas \u00e9tonnant qu&#8217;il en soit devenu un. C\u2019est en d\u00e9couvrant la guitare \u00e0 l\u2019\u00e2ge de 6 ans que son amour de la musique s\u2019est d\u00e9velopp\u00e9. Il a alors commenc\u00e9 \u00e0 toucher \u00e0 tout, du piano, \u00e0 la batterie jusqu\u2019\u00e0 la basse.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Thanks For Coming Out (But My Mackin&#039; Ain&#039;t Easy) (OG)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/QGI5J7ADmww?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Cependant c\u2019est en entrant au lyc\u00e9e que <strong>Mac<\/strong> d\u00e9couvre le hip-hop. Il va sortir une premi\u00e8re mixtape, intitul\u00e9e <strong><em>But My Mackin&#8217; Ain&#8217;t Easy<\/em><\/strong>, sous le nom de <strong>Eazy Mac<\/strong>, qu\u2019il a vendue \u00e0 environ 70 copies mais son projet suivant a \u00e9t\u00e9 t\u00e9l\u00e9charg\u00e9 30,000 fois en ligne. Cela lui a fait manquer des cours au lyc\u00e9e \u00e0 tel point qu&#8217;il a failli ne pas obtenir son dipl\u00f4me \u00e0 cause de la fr\u00e9quence \u00e0 laquelle il \u00e9tait engag\u00e9 pour des concerts en raison de la popularit\u00e9 de ce projet. Il a sorti six mixtapes avant son premier album studio et il s&#8217;est constitu\u00e9 une fanbase assez importante mais les critiques le d\u00e9testaient. En m\u00eame temps, sa base de fans continuait de grandir parce qu&#8217;il faisait ce qui \u00e9tait cool et amusant pour lui. <strong>Mac<\/strong> \u00e9tait en fait fid\u00e8le \u00e0 lui-m\u00eame et c&#8217;est exactement ce qui plaisait.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><strong><em>Kids<\/em>, ses s\u00e9rieux d\u00e9buts dans la musique<\/strong><\/strong><\/h2>\n\n\n\n<p>Avec cette popularit\u00e9 grandissante, <strong>Mac<\/strong> va commencer \u00e0 recevoir des offres de grands labels pour signer avec eux. Il va d\u00e9cider d&#8217;opter pour <strong>Rostrom<\/strong> <strong>records<\/strong>, un label totalement ind\u00e9pendant, beaucoup plus petit que certains labels avec lesquels il aurait pu travailler. <strong>Rostrom<\/strong> \u00e9tait bas\u00e9 dans sa ville natale et \u00e9tait d\u00e9j\u00e0 associ\u00e9 \u00e0 <strong>Wiz Khalifa<\/strong>, un autre rappeur de Pittsburgh que <strong>Mac<\/strong> consid\u00e9rait comme un mentor \u00e0 l&#8217;\u00e9poque.<\/p>\n\n\n\n<p>C\u2019est sous ce label que <strong>Mac<\/strong> va sortir sa mixtape la plus connue, <strong><em>Kids<\/em><\/strong>. Cette mixtape est un parfait exemple de ce que les gens aimaient et n&#8217;aimaient pas chez <strong>Mac<\/strong> \u00e0 l&#8217;\u00e9poque. Des chansons comme <strong><em>Senior Skip Day<\/em><\/strong> ont des rythmes tr\u00e8s pop, assez l\u00e9gers. Dans l\u2019ensemble <strong>Mac<\/strong> ne fait que rapper sur des th\u00e8mes tr\u00e8s simples, sa vie d\u2019\u00e9tudiant finalement. Le fait de s\u00e9cher les cours et de s&#8217;amuser avec des filles, ou encore l\u2019alcool et la weed.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Senior Skip Day\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/h7NJfuVk9hY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Pour beaucoup, <strong>Mac<\/strong> \u00e9tait alors un rappeur fade et superficiel. Cependant le public de <strong>Mac<\/strong> n&#8217;a cess\u00e9 de cro\u00eetre gr\u00e2ce \u00e0 la popularit\u00e9 du sous-genre Frat rap qui, malgr\u00e9 le fait qu&#8217;il soit d\u00e9test\u00e9 par presque tout le monde, avait encore assez de fans dans le milieu universitaire pour faire de <strong>Mac<\/strong> une star. Malgr\u00e9 les th\u00e8mes tr\u00e8s l\u00e9gers de beaucoup de chansons sur la mixtape <strong><em>Kids<\/em><\/strong>, c\u2019est un album que j\u2019appr\u00e9cie particuli\u00e8rement et rend nostalgique. Ce sera un succ\u00e8s commercial pour Mac avec <strong>800 000 t\u00e9l\u00e9chargements<\/strong>.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>Best Day Ever<\/em> et l\u2019explosion \u00e0 international<\/strong><\/h2>\n\n\n\n<p>Seulement six mois apr\u00e8s la sortie de <strong><em>Kids<\/em><\/strong>, <strong>Mac Miller<\/strong> va sortir la mixtape <strong><em>Best Day Ever<\/em><\/strong>. <strong><em>Donald Trump <\/em><\/strong>va devenir viral sur YouTube, recueillant <strong>20 millions de vues<\/strong> en seulement deux mois. Beaucoup l\u2019ont d\u00e9couvert gr\u00e2ce \u00e0 ce hit. La chanson s\u2019est class\u00e9e sur le <strong>Billboard Hot 100<\/strong> et a \u00e9t\u00e9 <strong>certifi\u00e9e platine<\/strong>. Ce hit a catapult\u00e9 <strong>Mac<\/strong> dans la conscience du public et solidifi\u00e9 sa position comme l&#8217;un des rappeurs les plus influents de l\u2019\u00e9poque.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Donald Trump\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/74TFS8r_SMI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>15 jours apr\u00e8s la sortie de sa mixtape <strong><em>Best Day Ever<\/em><\/strong>, il sort encore un EP 6 titres, <strong><em>On and On and Beyond<\/em>. <\/strong>Il entame dans les semaines qui suivent une autre mixtape nomm\u00e9e <strong><em>I Love Life, Thank You<\/em><\/strong> o\u00f9 il sort un son tous les paliers de 100 000 abonn\u00e9s sur Twitter jusqu&#8217;au million. C&#8217;est un des premiers rappeurs \u00e0 utiliser les r\u00e9seaux sociaux de cette mani\u00e8re. Ce marketing ing\u00e9nieux lui a permis de grimper et de consolider sa fanbase par la m\u00eame occasion.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>Blue Slide Park<\/em>, son premier album studio<\/strong><\/h2>\n\n\n\n<p>Lorsque <strong>Mac<\/strong> a sorti son premier album studio, il est devenu le premier album ind\u00e9pendant \u00e0 se classer num\u00e9ro un au Billboard en 16 ans, sans aucun featuring, mais il n&#8217;a pas battu les all\u00e9gations sans talent. Son single principal <strong><em>Frick Park Market<\/em><\/strong> va se hisser dans les charts encore plus haut que <strong><em>Donald Trump<\/em><\/strong> et le <strong>magazine XXL<\/strong> va le classer dans les rappeurs \u00e0 suivre en <strong>2011<\/strong> aux c\u00f4t\u00e9s de <strong>Meek Mill<\/strong>, <strong>Kendrick Lamar <\/strong>et <strong>YG<\/strong>. Cela dit l&#8217;industrie de la musique et sa communaut\u00e9 ne vont pas bien recevoir l\u2019album. Pour beaucoup <strong><em>Blue Slide Park<\/em><\/strong> \u00e9tait au mieux ennuyeux. <strong>Pitchfork<\/strong> a \u00e9crit une critique incroyablement n\u00e9gative de cet album en lui attribuant une note de <strong>1 sur 10<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Frick Park Market\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/KJ19PJ7-SWc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Il n&#8217;y a rien de mal \u00e0 cela, c&#8217;est de la musique, mais cela soul\u00e8ve la question de savoir pourquoi <strong>Mac Miller <\/strong>\u00e9tait si populaire. Pour la majorit\u00e9 \u00e0 cette \u00e9poque, ce n&#8217;est qu&#8217;une version fade de <strong>Wiz Khalifa<\/strong>. Il \u00e9tait un frat rapper blanc d&#8217;un beau quartier de Pittsburgh, sa musique n&#8217;\u00e9tait pas int\u00e9ressante ou complexe et il n&#8217;avait rien fait d&#8217;assez bon jusqu&#8217;\u00e0 pr\u00e9sent pour que les gens le prennent au s\u00e9rieux. Honn\u00eatement, <strong><em>Blue Slide Park<\/em><\/strong> n&#8217;est pas assez mauvais pour justifier les r\u00e9actions de l&#8217;\u00e9poque. <strong>Mac Miller<\/strong> n&#8217;a pas disparu apr\u00e8s la r\u00e9ception n\u00e9gative de son album. Il a au contraire pris les critiques au s\u00e9rieux, embrass\u00e9 son v\u00e9ritable talent pour la musique qu&#8217;il avait d\u00e9velopp\u00e9 depuis qu&#8217;il \u00e9tait enfant et cr\u00e9\u00e9 un nouveau son qui \u00e9tait plus authentique, plus mature \u00e9motionnellement et plus int\u00e9ressant musicalement.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><strong>Un rebondissement apr\u00e8s une chute compliqu\u00e9e<\/strong><\/strong><\/h2>\n\n\n\n<p><strong>Mac<\/strong> ne savait manifestement pas trop quoi faire \u00e0 ce moment-l\u00e0, il n&#8217;avait que 19 ans, mais il \u00e9tait aussi l&#8217;un des jeunes rappeurs les plus populaires de l&#8217;industrie et le monde entier d\u00e9testait sa musique en m\u00eame temps. En <strong>2012<\/strong> il va sortir <strong><em>Macadelic<\/em><\/strong>. Une mixtape comportant des sons abstraits, mais aussi des featuring de <strong>Lil Wayne<\/strong>, <strong>Juicy Jay<\/strong> et <strong>Camron<\/strong>. On d\u00e9couvre alors un <strong>Mac<\/strong> beaucoup plus sombre et beaucoup plus introspectif. <strong><em>Fight The Feeling<\/em><\/strong> met en sc\u00e8ne <strong>Kendrick Lamar <\/strong>et <strong>Iman Omari<\/strong>. <strong>Mac<\/strong> rappe sur le poids de son succ\u00e8s et l&#8217;instabilit\u00e9 de sa carri\u00e8re sur un rythme m\u00e9lancolique<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller ft. Kendrick Lamar &amp; Iman Omari - Fight The Feeling\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/As_cvwAMYi4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Ce morceau montre une fen\u00eatre dans l&#8217;\u00e2me de <strong>Mac Miller<\/strong> qui est \u00e9tonnamment profonde et claire surtout pour un artiste qui n&#8217;avait que 20 ans quand il l&#8217;a \u00e9crite. L&#8217;ancien <strong>Mac Miller<\/strong> disparaissait et un nouveau avec plus de poids sur ses \u00e9paules et plus de choses \u00e0 dire grandissait. Et c&#8217;est ce qui a fait de <strong><em>Macadelic<\/em><\/strong> un projet vraiment sp\u00e9cial. <strong>Mac Miller<\/strong> n&#8217;est pas devenu fade et n&#8217;est pas rentr\u00e9 dans sa coquille, il s&#8217;est ouvert davantage et a permis aux gens de p\u00e9n\u00e9trer plus profond\u00e9ment dans son monde, devenant plus identifiable et plus honn\u00eate en m\u00eame temps.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong>Ses autres identit\u00e9es<\/strong><\/h2>\n\n\n\n<p>En 2012, alors qu&#8217;il travaillait dur sur son retour officiel apr\u00e8s <strong><em>Blue Slide Park<\/em><\/strong>, il a officieusement sorti une chanson sous un autre Alter Ego, <strong>Larry Fisherman<\/strong>. C\u2019est \u00e0 ce jour l&#8217;une des chansons les plus sombres et les plus introspectives qu&#8217;il ait jamais faites. <strong><em>Doodling in the key of C sharp<\/em><\/strong> est un \u00e9norme changement par rapport \u00e0 tout ce qu&#8217;il a fait auparavant. <strong>Mac<\/strong> s&#8217;est compl\u00e8tement ouvert sur cette chanson. La fa\u00e7on dont <strong>Mac<\/strong> rape sur la pression d&#8217;avoir tant d&#8217;attention n\u00e9gative sur lui offre un niveau d&#8217;honn\u00eatet\u00e9 in\u00e9gal\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Doodling In The Key of C Sharp (prod. Larry Fisherman)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/JrqOekC_KZs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Tr\u00e8s peu de temps apr\u00e8s la sortie de <strong><em>Macadelic<\/em><\/strong>, Mac va sortir un EP sous le nom de <strong>Larry Lovestein<\/strong>. C\u2019est un EP de jazz qu\u2019on pourrait presque qualifier de loundge music. On y d\u00e9couvre un <strong>Mac<\/strong> tr\u00e8s romantique s\u2019essayant au jazz et c\u2019est tr\u00e8s rafraichissant.<\/p>\n\n\n\n<p><strong>Delusional Thomas <\/strong>est la plus r\u00e9cente des identit\u00e9es cr\u00e9\u00e9es par <strong>Mac Miller<\/strong>. Elle ne ressemble \u00e0 rien de ce que <strong>Mac Miller<\/strong> a pu sortir auparavant, ni \u00e0 rien de ce qu&#8217;il a pu faire par la suite. C&#8217;est un contraste frappant avec <strong><em>The Divine Feminine<\/em><\/strong>, un album sorti \u00e0 peine deux ans plus tard et rempli de belles chansons n\u00e9o-soul et R&amp;B. Cette mixtape \u00e9ponyme est une d\u00e9couverte dans un genre tr\u00e8s sombre, presque acidique.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>Watching Movies With The Sound Off<\/em><\/strong><\/h2>\n\n\n\n<p><strong><em>Watching Movies With The Sound Off<\/em><\/strong> est le deuxi\u00e8me album studio de <strong>Mac Miller<\/strong>. Il est sorti peu apr\u00e8s <strong><em>Doodling In The Key of C Sharp<\/em><\/strong>, le <strong>18<\/strong> <strong>juin 2013<\/strong>. C&#8217;\u00e9tait un autre grand pas en avant dans le cadre de sa croissance en tant qu&#8217;artiste. Il a fait son propre chemin et a trouv\u00e9 son propre son. Il a pris la t\u00eate du d\u00e9veloppement de l&#8217;ensemble du projet. Une longue liste d&#8217;artistes a aid\u00e9 \u00e0 fa\u00e7onner l&#8217;album, des producteurs comme <strong>Flying Lotus<\/strong>, <strong>The Alchemist<\/strong>, <strong>Clams Casino<\/strong>, <strong>Pharrell<\/strong>\u2026 Ils ont tous contribu\u00e9 \u00e0 cr\u00e9er l&#8217;esth\u00e9tique que <strong>Mac<\/strong> recherchait. Des artistes comme <strong>Earl Sweatshirt<\/strong>, <strong>Action Bronson<\/strong>, <strong>Schoolboy<\/strong> <strong>Q<\/strong> et <strong>Ab-Soul<\/strong> ont figur\u00e9 sur ses chansons.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller: The Space Migration Sessions - Objects In The Mirror (with The Internet)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/9Gbl-IDp1qc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Pharell<\/strong> a produit <strong><em>Objects In The Mirror<\/em><\/strong>, certainement ma chanson pr\u00e9f\u00e9r\u00e9e de <strong>Mac<\/strong>. C\u2019est une chanson \u00e0 l&#8217;allure jazzy calme, avec des sons d\u2019animaux dans le mix et des notes de guitare \u00e9lectrique lointaines. <strong><meta charset=\"utf-8\"><strong><em>Watching Movies With The Sound Off<\/em><\/strong><\/strong> a fini par \u00eatre un carrefour majeur dans la carri\u00e8re de <strong>Mac<\/strong>. C&#8217;\u00e9tait un tout nouveau son compar\u00e9 \u00e0 <strong><em>Blue Slide Park<\/em> <\/strong>qui a \u00e9t\u00e9 d\u00e9truit par les critiques et bien s\u00fbr c&#8217;\u00e9tait la direction qu&#8217;il voulait prendre. Cependant il n&#8217;\u00e9tait pas vraiment clair si le nouveau son de <strong>Mac<\/strong> serait bien re\u00e7u par qui que ce soit. Un album studio complet d&#8217;\u00e9criture philosophique introspective et de production jazzy c&#8217;\u00e9tait un risque mais le risque a fini par payer totalement. <meta charset=\"utf-8\"><strong><strong><em>Watching Movies With The Sound Off<\/em><\/strong><\/strong> a \u00e9t\u00e9 le moment o\u00f9 <strong>Mac Miller<\/strong> a prouv\u00e9 qu&#8217;il valait la peine d&#8217;\u00eatre pris au s\u00e9rieux et qu&#8217;il avait fait quelque chose d&#8217;ind\u00e9niablement int\u00e9ressant dans le monde de la musique m\u00eame s&#8217;il ne s&#8217;\u00e9tait pas class\u00e9 num\u00e9ro un ou n&#8217;avait pas eu de grand succ\u00e8s. Son influence et son respect en tant que v\u00e9ritable artiste commen\u00e7aient \u00e0 grandir.<\/p>\n\n\n\n<div style=\"height:101px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><strong><em>Faces<\/em>, sa mixtape phare<\/strong><\/strong><\/h2>\n\n\n\n<p>\u00c0 mi-chemin de l&#8217;enregistrement de <strong><em>Watching Movies With The Sound Off<\/em><\/strong>, <strong>Mac Miller <\/strong>a quitt\u00e9 sa maison de Pittsburgh pour s&#8217;installer dans une maison \u00e0 Studio City, \u00e0 Los Angeles, appel\u00e9e le Sanctuaire. Durant cette \u00e9poque, il est devenu ami avec <strong>Odd Future<\/strong> et <strong>Tyler the Creator<\/strong>, <strong>Earl<\/strong> <strong>Sweatshirt<\/strong> et <strong>Vince<\/strong> <strong>Staples<\/strong>. Il y avait des visiteurs r\u00e9guliers, m\u00eame <strong>Schoolboy Q<\/strong>, <strong>Ab Soul<\/strong> et <strong>Kendrick Lamar<\/strong> venaient le voir. <strong>Mac Miller<\/strong> n&#8217;a eu le studio que pendant un an, mais c&#8217;est aussi l\u00e0 qu&#8217;il a enregistr\u00e9 <strong><em>Faces<\/em><\/strong>, une mixtape qui a fait beaucoup de bruit. C\u2019est pour beaucoup de fans (moi \u00e9galement) l\u2019un de ses projets les plus aboutis.<\/p>\n\n\n\n<p><strong><em>Faces<\/em><\/strong> a \u00e9t\u00e9 r\u00e9alis\u00e9 sans label mais c&#8217;est vraiment un projet sp\u00e9cial. Une production jazzy, une narration qui tourne autour de la solitude, l\u2019addiction, la mort, c&#8217;est un chef d&#8217;\u0153uvre. La capacit\u00e9 de <strong>Mac<\/strong> \u00e0 cr\u00e9er un univers sonore en produisant la majorit\u00e9 du projet lui-m\u00eame avec l&#8217;aide de <strong>Earl<\/strong> <strong>Sweatshirt<\/strong>, <strong>Thundercat<\/strong> et plus, c&#8217;est vraiment <strong><em>Faces<\/em><\/strong> qui prend vie. Sur <strong><em>Colors and Shapes<\/em><\/strong>, certainement l\u2019un de ses meilleurs titres, il chante l&#8217;exp\u00e9rience d&#8217;\u00eatre sous LSD et on a l&#8217;impression de flotter dans la production. Les sons montent et descendent avec le flux de la m\u00e9lodie.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Colors and Shapes\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/K22_5LBuB9Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Mac<\/strong> s&#8217;est enferm\u00e9 dans le sanctuaire pour faire <strong><em>Faces<\/em><\/strong>. Ses amis ont m\u00eame dit qu&#8217;ils ont d\u00fb le faire sortir de son propre studio. C&#8217;\u00e9tait un grand contraste par rapport aux ann\u00e9es pr\u00e9c\u00e9dentes o\u00f9 il avait fait 100 ou 200 concerts chaque ann\u00e9e. <strong><em>Faces<\/em><\/strong> \u00e9tait une introspection sur la sant\u00e9 mentale de <strong>Mac<\/strong> \u00e0 l&#8217;\u00e9poque, et il n&#8217;\u00e9tait pas en grande forme. Les longues journ\u00e9es et nuits au sanctuaire, l&#8217;usage constant de drogues, les hallucinations, sa fixation sur la mort, sachant que c&#8217;\u00e9tait la conclusion logique du style de vie qu&#8217;il menait. Mais en d\u00e9pit de tout cela, <strong><em>Faces<\/em><\/strong> a une sorte de sentiment \u00e9nergique et vivant \u00e0 travers beaucoup de chansons. Il a fini par vivre avec <strong>Rick Rubin<\/strong> pendant un mois pour l&#8217;aider \u00e0 redescendre et \u00e0 r\u00e9organiser son esprit. Lors d&#8217;une interview, il a d\u00e9clar\u00e9 que <strong>Rick Rubin<\/strong> \u00e9tait quelqu&#8217;un qui avait vraiment contribu\u00e9 \u00e0 l&#8217;aider \u00e0 aller mieux.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>GO:OD AM<\/em>, un troisi\u00e8me album r\u00e9ussi<\/strong><\/h2>\n\n\n\n<p>Avec un meilleur mood et une pause d&#8217;un an, <strong>Mac<\/strong> a sorti <strong><em>GO:OD AM<\/em><\/strong> en <strong>2015<\/strong>, un projet beaucoup plus optimiste que <strong><em>Faces<\/em><\/strong>. La production est propre et polie et pleine de chansons pop grandiloquentes comme <strong><em>Brand Name <\/em><\/strong>ou <strong><em>100 Grandkids<\/em><\/strong>. Mais il y a aussi des morceaux plus sombres comme <strong><em>Perfect Circle \/ God Speed<\/em><\/strong> et <strong><em>Ascension<\/em><\/strong>. <strong><em>Perfect Circle \/ God Speed<\/em><\/strong> est un morceau tr\u00e8s sp\u00e9cial o\u00f9 il admet librement et se vante presque de sa d\u00e9pendance \u00e0 la drogue tout en ignorant les dommages qu&#8217;elle lui fait subir ainsi qu&#8217;\u00e0 ses proches. Mais dans la deuxi\u00e8me partie du son, <strong><em>God Speed<\/em><\/strong>, un sample d\u2019un message vocal de son fr\u00e8re retentit et <strong>Mac<\/strong> se met alors \u00e0 rapper sur le ridicule de ses addictions et que cela le nuit. Il sait qu&#8217;il doit arr\u00eater avant que cela ne le tue.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Perfect Circle \/ God Speed\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/2UkrJ0YjjUY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>GO:OD AM <\/em><\/strong>est un album tr\u00e8s abordable pour d\u00e9couvrir l\u2019univers de <strong>Mac<\/strong>, assez pop. <strong>Mac<\/strong> n&#8217;a pas eu beaucoup produit sur cet album et bien que les rythmes soient bons, il n&#8217;y a pas cette marque psych\u00e9d\u00e9lique et jazzy qui fait les meilleurs travaux de <strong>Mac<\/strong>. Cependant cet album est la preuve qu\u2019il est capable de rapper sur un ton plus joyeux et plus tout en faisant de la bonne musique.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><strong><em>The Divine Feminine<\/em>, la lettre d\u2019amour \u00e0 Ariana<\/strong><\/strong><\/h2>\n\n\n\n<p>En <strong>2012<\/strong>, <strong>Mac Miller<\/strong> et <strong>Ariana Grande<\/strong> sont devenus amis lorsqu&#8217;ils ont fait une reprise de <strong><em>Baby It\u2019s Cold Outside<\/em><\/strong>. Ils sont rest\u00e9s en contact et ont collabor\u00e9 \u00e0 plusieurs reprises jusqu&#8217;en <strong>2016<\/strong>, date \u00e0 laquelle ils sont apparus publiquement en tant que couple. Cette relation a eu une influence significative sur le reste de la vie de <strong>Mac<\/strong> et sur toute la musique qu&#8217;il a produite \u00e0 partir de ce moment-l\u00e0. <strong><em>The Divine Feminine<\/em><\/strong>, le quatri\u00e8me album de <strong>Mac<\/strong>, est d\u00e9di\u00e9 \u00e0 leur relation. M\u00eame si une grande partie a \u00e9t\u00e9 \u00e9crite avant qu&#8217;ils ne soient ensemble<strong> Ariana Grande<\/strong> a d\u00e9finitivement laiss\u00e9 une marque sur cette p\u00e9riode de la carri\u00e8re de <strong>Mac<\/strong>. On y d\u00e9couvre un <strong>Mac<\/strong> plus funk, plus optimiste et un album qui tourne autour de l\u2019amour. <strong>Ariana<\/strong> fait \u00e9galement une apparition sur <strong><em>My Favorite Part<\/em><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - My Favorite Part (feat. Ariana Grande) (Live)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Ndf-eMyEVG8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>Swimming<\/em>, le sommet de son art<\/strong><\/h2>\n\n\n\n<p><strong><em>Swimming<\/em><\/strong> qui est sorti en <strong>ao\u00fbt<\/strong> <strong>2018<\/strong> repr\u00e9sente le point culminant de la croissance de la carri\u00e8re de <strong>Mac<\/strong> au cours des 6 derni\u00e8res ann\u00e9es. C\u2019est tr\u00e8s certainement mon projet pr\u00e9f\u00e9r\u00e9 de <strong>Mac Miller<\/strong>, avec cependant une r\u00e9ception m\u00e9diocre de la critique. <strong><em>Swimming<\/em><\/strong> explore les th\u00e8mes de la solitude, de la d\u00e9pendance et des \u00e9checs personnels tout en se concentrant \u00e9galement sur l&#8217;amour de soi, la croissance et l&#8217;optimisme. L&#8217;accent est mis dans la narration sur son nouveau sens de l&#8217;espoir et l&#8217;influence de sa relation avec <strong>Ariana Grande<\/strong>. Sur <strong><em>Swimming<\/em><\/strong> on d\u00e9couvre un <strong>Mac Miller <\/strong>qui semble avoir err\u00e9 dans l&#8217;obscurit\u00e9 pendant longtemps mais il a finalement vu la lumi\u00e8re.<\/p>\n\n\n\n<p>L&#8217;album commence avec <strong><em>Come Back to Earth<\/em><\/strong> qui sert d&#8217;introduction calme et dans cette chanson <strong>Mac<\/strong> chante la valeur de la vie malgr\u00e9 ses d\u00e9fis et comment il a \u00e9t\u00e9 capable de trouver un \u00e9quilibre. La derni\u00e8re chanson de l&#8217;album, <strong><em>So It Goes<\/em><\/strong> est un morceau rebondissant et m\u00e9lancolique nomm\u00e9 d&#8217;apr\u00e8s une ligne du livre <strong><em>Slaughterhouse-Five<\/em><\/strong>, de <strong>Kurt Vonnegut<\/strong>. Il \u00e9crit <strong>So It Goes<\/strong> chaque fois que quelqu&#8217;un meurt symbolisant l&#8217;acceptation. Cette chanson repr\u00e9sente la derni\u00e8re \u00e9tape de l&#8217;acceptation dans le voyage de <strong>Mac<\/strong>, essayant d&#8217;accepter les probl\u00e8mes de la vie et d&#8217;embrasser la n\u00e9cessit\u00e9 de continuer \u00e0 avancer.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - So It Goes\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Uf24Uk6ZMLQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Swimming<\/em><\/strong> est un moment charni\u00e8re dans le voyage de <strong>Mac<\/strong> en tant qu&#8217;artiste et personne. Cet album est celui o\u00f9 il essaie de s&#8217;appuyer sur l&#8217;id\u00e9e qu&#8217;il est normal de se sentir seul, il est normal d&#8217;\u00eatre isol\u00e9, triste et d\u00e9prim\u00e9 et de subir des pertes, mais il n&#8217;est pas normal de stagner ou de se conforter dans sa mis\u00e8re. Il essayait vraiment de puiser un sens significatif d&#8217;acceptation des probl\u00e8mes, un sens de la vie. <strong><em>Swimming<\/em><\/strong> \u00e9tait le moyen pour <strong>Mac<\/strong> de nous faire savoir que tout irait bien. Malheureusement, un mois apr\u00e8s la sortie de <strong><em>Swimming<\/em><\/strong>, le <strong>7 septembre 2018<\/strong>, <strong>Mac Miller <\/strong>est d\u00e9c\u00e9d\u00e9 dans sa maison de Studio City \u00e0 Los Angeles. Il \u00e9tait cens\u00e9 tourner un clip le m\u00eame jour, et il avait une tourn\u00e9e qui devait commencer le mois suivant. Il est d\u00e9c\u00e9d\u00e9 d&#8217;une overdose accidentelle de fentanyl.<\/p>\n\n\n\n<p>Il est impossible de nier l&#8217;impact que la mort de <strong>Mac Miller<\/strong> a eu sur l&#8217;industrie de la musique. <strong>Mac<\/strong> \u00e9tait respect\u00e9 par tant d&#8217;artistes pendant sa carri\u00e8re que lorsque ses amis et ses collaborateurs ont organis\u00e9 un concert hommage \u00e0 sa m\u00e9moire le nombre de personnes qui sont venues lui montrer leur respect et se produire a \u00e9t\u00e9 tr\u00e8s \u00e9lev\u00e9. <strong>Anderson Pack<\/strong>, <strong>Miguel<\/strong>, <strong>Earl Sweatshirt<\/strong>, <strong>John Mayor<\/strong>, <strong>Travis Scott<\/strong>, <strong>SZA<\/strong>, <strong>Thundercat<\/strong> <strong>Schoolboy<\/strong> <strong>Q<\/strong>, <strong>J.I.D<\/strong>, <strong>Vince Staples<\/strong>\u2026 Tous ces gens sont venus c\u00e9l\u00e9brer leur ami et sa vie. L&#8217;amour que les autres artistes avaient pour <strong>Mac Miller<\/strong> \u00e9tait vraiment unique. Aujourd&#8217;hui sa famille est d\u00e9vou\u00e9e \u00e0 continuer son h\u00e9ritage de la meilleure fa\u00e7on possible.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong><em>CIRCLES<\/em>, un album posthume frappant<\/strong><\/h2>\n\n\n\n<p>Son dernier album studio <strong><em>Circles<\/em><\/strong> est sorti apr\u00e8s sa mort en janvier 2020. Il avait \u00e9crit <strong><em>Swimming<\/em><\/strong> et <strong><em>Circles<\/em><\/strong> en m\u00eame temps, <strong><em>Circles<\/em><\/strong> \u00e9tait en quelque sorte termin\u00e9 quand <strong>Mac<\/strong> est d\u00e9c\u00e9d\u00e9. Son producteur <strong>John Brian<\/strong> qui avait travaill\u00e9 en \u00e9troite collaboration avec <strong>Mac<\/strong> pendant la r\u00e9alisation de ces albums a termin\u00e9 <strong><em>Circles<\/em><\/strong> en se basant sur le mat\u00e9riel existant qu&#8217;ils avaient. Bien qu&#8217;il n&#8217;ait pas \u00e9t\u00e9 termin\u00e9 par <strong>Mac<\/strong> lui-m\u00eame, <strong><em>Circles<\/em><\/strong> montre que <strong>Mac<\/strong> approchait de son pic cr\u00e9atif.<\/p>\n\n\n\n<p>Chaque chanson sur <strong><em>Circles<\/em><\/strong> est belle et unique \u00e0 sa fa\u00e7on. Elles sont toutes remplies \u00e0 ras bord d&#8217;\u00e9motions profondes.<strong><em> Good News<\/em><\/strong> est le premier single \u00e0 \u00eatre sorti apr\u00e8s la mort de <strong>Mac<\/strong>. Cette musique est charg\u00e9e d\u2019\u00e9motions, elle est incroyablement douce. Les paroles d\u00e9crivent \u00e0 quel point <strong>Mac<\/strong> \u00e9tait fatigu\u00e9 vers la fin de sa carri\u00e8re, mais aussi \u00e0 quel point il trouvait la vie belle.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mac Miller - Good News\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/aIHF7u9Wwiw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Sur <strong><em>Swimming<\/em><\/strong>, <strong>Mac<\/strong> avait atteint un point d&#8217;\u00e9quilibre dans sa vie et il l&#8217;exprime avec enthousiasme. <strong><em>Circles<\/em><\/strong> est tr\u00e8s similaire mais beaucoup plus doux dans sa production. Le ton de son \u00e9criture est un peu plus calme. <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2><strong>Une empreinte ind\u00e9l\u00e9bile<\/strong><\/h2>\n\n\n\n<p>La carri\u00e8re de <strong>Mac Miller<\/strong> n&#8217;a m\u00eame pas dur\u00e9 une d\u00e9cennie, il n&#8217;a \u00e9t\u00e9 dans l&#8217;\u0153il du public que pendant environ 8 ans. Mais avant sa mort, il a r\u00e9alis\u00e9 d&#8217;innombrables projets. Tous remplis d\u2019\u00e9motions fortes et de messages vraiment magnifiques sur la fa\u00e7on dont la vie devrait \u00eatre v\u00e9cue et sur ce qu&#8217;il faut faire pour aspirer \u00e0 plus. <strong>Mac<\/strong> \u00e9tait un leader. Il a aid\u00e9 des millions de personnes \u00e0 traverser des p\u00e9riodes tr\u00e8s sombres dans leurs propres vies, et il continue \u00e0 le faire aujourd&#8217;hui gr\u00e2ce \u00e0 sa musique, \u00e0 son optimisme in\u00e9branlable, \u00e0 son amour de la vie et \u00e0 son amour pour les autres.<\/p>\n\n\n\n<p>Son optimisme implacable face \u00e0 des luttes r\u00e9elles \u00e9tait si inspirant et il a fait tout cela tout en produisant certaines des meilleures musiques les plus cr\u00e9atives et d\u00e9taill\u00e9es de la d\u00e9cennie. Tout le monde peut s&#8217;identifier \u00e0 <strong>Mac Miller <\/strong>d&#8217;une mani\u00e8re ou d&#8217;une autre, parce qu&#8217;il a mis tout son \u00eatre dans sa musique. Il serait difficile de ne pas se voir dans les chansons qu&#8217;il a \u00e9crites.<\/p>\n\n\n\n<p>Enjoy and stay tuned,<\/p>\n\n\n\n<p class=\"has-drop-cap\">Quentin Gellato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mac Miller \u00e9tait un producteur, rappeur, \u00e9crivain et chanteur respect\u00e9 par le monde de la musique et aim\u00e9 par des millions de fans. Il a cr\u00e9\u00e9 tout un univers sonore autour de l&#8217;exp\u00e9rience chaotique d&#8217;un jeune artiste plong\u00e9 dans la gloire. Sa musique a explor\u00e9 la d\u00e9pression, l&#8217;isolement et l&#8217;addiction en m\u00eame temps qu&#8217;il gravissait &#8230; <a title=\"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons\" class=\"read-more\" href=\"http:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/\">Lire la suite <span class=\"screen-reader-text\">Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":15217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[15,2620,2622,2603,2625,2621,2604,2623,390,2605,157,2619,2624,2627,291,2618,13,12,41,2602,2626,2628],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It<\/title>\n<meta name=\"description\" content=\"Plongez dans l&#039;histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It\" \/>\n<meta property=\"og:description\" content=\"Plongez dans l&#039;histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T16:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T16:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg\",\"contentUrl\":\"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg\",\"width\":2560,\"height\":1344},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/\",\"name\":\"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#primaryimage\"},\"datePublished\":\"2024-10-17T16:30:39+00:00\",\"dateModified\":\"2024-10-17T16:30:41+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"description\":\"Plongez dans l'histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.\",\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"http:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It","description":"Plongez dans l'histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/","og_locale":"fr_FR","og_type":"article","og_title":"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It","og_description":"Plongez dans l'histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.","og_url":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2024-10-17T16:30:39+00:00","article_modified_time":"2024-10-17T16:30:41+00:00","og_image":[{"width":2560,"height":1344,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#primaryimage","inLanguage":"fr-FR","url":"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg","contentUrl":"http:\/\/startitkbs.org\/wp-content\/uploads\/2024\/10\/Mac-Miller-Computer-Wallpaper-scaled.jpg","width":2560,"height":1344},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/","name":"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#primaryimage"},"datePublished":"2024-10-17T16:30:39+00:00","dateModified":"2024-10-17T16:30:41+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"description":"Plongez dans l'histoire tragique de Mac Miller, un artiste l\u00e9gendaire dont les difficult\u00e9s ont \u00e9clips\u00e9 le succ\u00e8s.","breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2024\/10\/17\/mac-miller-la-legende-rattrape-par-ses-demons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Mac Miller, la l\u00e9gende rattrap\u00e9 par ses d\u00e9mons"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"http:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15195"}],"collection":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=15195"}],"version-history":[{"count":4,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15195\/revisions"}],"predecessor-version":[{"id":15218,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/15195\/revisions\/15218"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/15217"}],"wp:attachment":[{"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=15195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=15195"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=15195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}