{"id":11994,"date":"2021-10-10T00:10:31","date_gmt":"2021-10-09T22:10:31","guid":{"rendered":"http:\/\/startitkbs.org\/?p=11994"},"modified":"2021-11-24T13:37:15","modified_gmt":"2021-11-24T12:37:15","slug":"rap-francais-inversion-des-valeurs","status":"publish","type":"post","link":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/","title":{"rendered":"Rap fran\u00e7ais, inversion des valeurs ?"},"content":{"rendered":"\n<p><em>Le rap, musique la plus \u00e9cout\u00e9e par les fran\u00e7ais. On \u00e9coute du rap de plus en plus t\u00f4t, on a acc\u00e8s \u00e0 des tablettes, ordinateurs et autres smartphones toujours plus jeunes.<br>Pour aller \u00e0 l\u2019\u00e9cole, dans le bus, \u00e0 pied ou \u00e0 v\u00e9lo, dans la cour de r\u00e9cr\u00e9ation, en allant au sport, en faisant du sport, en soir\u00e9e ou m\u00eame chez soi, on \u00e9coute de la musique et principalement du rap. L\u2019acc\u00e8s aux technologies modernes nous permet d\u2019\u00eatre en capacit\u00e9 d\u2019\u00e9couter de la musique partout et tout le temps<\/em>.<\/p>\n\n\n\n<p>Cette musique relativement r\u00e9cente d\u00e9passe compl\u00e8tement ce qu\u2019elle est en devenant un v\u00e9ritable fait de soci\u00e9t\u00e9, un facteur de conditionnement qui nous accompagne quotidiennement.<\/p>\n\n\n\n<p>Qui peut pr\u00e9tendre \u00e9couter en moyenne deux heures par jour des paroles pos\u00e9es sur une instrumentale sans qu\u2019il n\u2019y ait la moindre influence sur ce que nous sommes&nbsp;? Notre cerveau est plastique, notre environnement d\u00e9termine grandement ce que nous devenons, ce que l\u2019on \u00e9coute tous les jours aussi.<\/p>\n\n\n\n<p>Les valeurs mises en avant, le discours port\u00e9 que l\u2019on retrouve dans le rap a alors un impact consid\u00e9rable sur notre personnalit\u00e9 et \u00e0 plus grande \u00e9chelle, sur notre soci\u00e9t\u00e9.<br>C\u2019est pourquoi il est int\u00e9ressant de se pencher sur la question des valeurs v\u00e9hicul\u00e9es par le rap fran\u00e7ais ainsi que son \u00e9volution.<\/p>\n\n\n\n<h2><strong>&nbsp;Les d\u00e9buts du rap fran\u00e7ais<\/strong><\/h2>\n\n\n\n<p>Le rap fran\u00e7ais prend forme dans les ann\u00e9es 80, apr\u00e8s son av\u00e8nement dans les ghettos am\u00e9ricains des ann\u00e9es 70.<\/p>\n\n\n\n<p>Tout commence avec <strong>Kool Herc<\/strong>, DJ du bronx aux Etats-Unis lorsqu&#8217;il anime des soir\u00e9es funk\/\u00e9lectro dans les quartiers autour de chez lui.<br>C\u2019\u00e9tait l\u2019occasion pour les habitants de se r\u00e9unir et d\u2019oublier les probl\u00e8mes qui envahissaient leur vie. On y retrouvait des pratiques comme le Graffiti, le beatboxing, le Dj-ing et la danse bien s\u00fbr, dont une tout bonnement particuli\u00e8re qui jouera un r\u00f4le d\u00e9terminant dans l\u2019histoire de la musique&nbsp;: le break dance. Cette discipline vient de \u00ab&nbsp;Casser la danse&nbsp;\u00bb lors des solos de batterie qui duraient une quinzaine de secondes dans la musique funk. Ces solos de batterie peuvent ais\u00e9ment nous faire penser \u00e0 une instrumentale de rap avec nos oreilles modernes. C\u2019\u00e9tait une v\u00e9ritable d\u00e9monstration, une performance courte mais intense.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"dj kool herc - b-boy\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/Kb3Tg0N2k7M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Kool Herc<\/strong> a alors d\u00e9cid\u00e9 d\u2019aligner deux vinyles sur les platines et ainsi, de passer d\u2019un solo de batterie \u00e0 un autre. De fil en aiguille, des personnalit\u00e9s fortes qui repr\u00e9sentaient leurs quartiers alignaient leur voix sur l\u2019instrumentale lors des soir\u00e9es organis\u00e9es par <strong>Kool Herc<\/strong>. On ne peut pas encore parler de rap tant, les performances s\u2019\u00e9loignent de ce que sera cette musique telle qu\u2019on l\u2019entend.<\/p>\n\n\n\n<p>Apr\u00e8s de multiples soir\u00e9es, de multiples performances sur ces solos de batteries d\u00e9riv\u00e9es du funk, on arrive finalement au rap aux \u00c9tats-Unis dans les ann\u00e9es 70. Dix ans plus tard, cette musique novatrice, pleine d\u2019\u00e9nergie et de promesses traverse l\u2019Atlantique et s\u2019installe dans les quartiers fran\u00e7ais.<\/p>\n\n\n\n<p>Les DJ fran\u00e7ais vont se mettre \u00e0 scratcher des tubes de<strong> James Brown<\/strong> en alliant encore une fois danse et Graffiti lors de divers \u00e9v\u00e9nements.<\/p>\n\n\n\n<p>C\u2019est <strong>Patrick Duteil <\/strong>dit \u00ab&nbsp;<strong>Sidney<\/strong>&nbsp;\u00bb qui va montrer au grand jour le rap en France, encore cach\u00e9 dans quelques radios pirates. En 1984, TF1 propose sa nouvelle \u00e9mission \u00ab&nbsp;HIP HOP&nbsp;\u00bb anim\u00e9e par <strong>Sidney<\/strong>. Des open-mic se cr\u00e9ent, les danseurs et rappeurs se rassemblent et improvisent leur musique, il y a une v\u00e9ritable \u00e9mulation qui reste n\u00e9anmoins marginale malgr\u00e9 la passion entretenue.<\/p>\n\n\n\n<p>D\u2019ann\u00e9e en ann\u00e9e, des collectifs se forment, des petits rappeurs sortent la t\u00eate de l\u2019eau. La naissance d\u2019un certain <strong>Akhenaton<\/strong> \u00e0 Marseille voit le jour, <strong>Mc solaar<\/strong> \u00e0 Paris, <strong>Doc Gyneco<\/strong>, le fameux groupe <strong>NTM<\/strong> ou encore <strong>Assassin<\/strong>. Des radios comme radio Nova ou encore l\u2019\u00e9mission rapline vont participer \u00e0 l\u2019essor du mouvement rap qui trouve d\u00e9sormais sa place et son public. Pour illustrer ce succ\u00e8s, un simple chiffre est assez r\u00e9v\u00e9lateur de l\u2019ampleur du ph\u00e9nom\u00e8ne&nbsp;: <strong>Mc solaar<\/strong> en 1990 vend \u00e0 plus de 400&nbsp;000 exemplaires physiques avec son album \u00ab&nbsp;<em>Qui s\u00e8me le vent r\u00e9colte le tempo<\/em>&nbsp;\u00bb. Les titres sont revendicatifs, il y a une volont\u00e9 de d\u00e9noncer les in\u00e9galit\u00e9s auxquelles font face les habitants des quartiers fran\u00e7ais. Le rap porte un message, un message que beaucoup comprennent, c\u2019est une caisse de r\u00e9sonance pour ces jeunes d\u00e9laiss\u00e9s sans porte-parole. Leur d\u00e9put\u00e9 \u00e0 eux, c\u2019est le rappeur de leur quartier. Le rap c\u2019est se faire entendre, c\u2019est prendre parti, comme le dit si bien <strong>Arsenik<\/strong> dans <em>boxe avec les mots<\/em>&nbsp;: \u00ab&nbsp;Qui peut pr\u00e9tendre faire du rap sans prendre position&nbsp;?&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/hip-hop-annees-90.jpg\" alt=\"Rap-fran\u00e7ais-80\" class=\"wp-image-11996\" width=\"694\" height=\"507\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/hip-hop-annees-90.jpg 630w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/hip-hop-annees-90-300x219.jpg 300w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/figure>\n\n\n\n<p>Le rap fran\u00e7ais des ann\u00e9es 1990-2000 est tr\u00e8s influenc\u00e9 dans son esth\u00e9tique par le rap am\u00e9ricain de la c\u00f4te est. C\u2019est donc avec des instrumentales aux allures de jazz et de soul que les fran\u00e7ais performent. Parsem\u00e9 de quelques scratchs et de po\u00e9sie qui nous caract\u00e9rise tant, ce rap se d\u00e9marque en Europe o\u00f9 sommes la deuxi\u00e8me nation \u00e0 pratiquer cette musique et \u00e0 l\u2019\u00e9couter autant.<\/p>\n\n\n\n<p>L\u2019ann\u00e9e 1995 laissera une trace ind\u00e9l\u00e9bile dans le rap fran\u00e7ais, et ce, par la diffusion <em>de Time bomb Vol.1, <\/em>projet regroupant des artistes comme <strong>Booba<\/strong>, <strong>Ali<\/strong> ou encore <strong>Oxmo Puccino<\/strong>. On parle fran\u00e7ais, arabe et wolof, il y a une culture du verbe, une culture du phras\u00e9 m\u00e9lang\u00e9es \u00e0 des paroles crues et parfois tr\u00e8s violentes. &#8220;Time Bomb a apport\u00e9 une mani\u00e8re de traiter les sujets, avec un swing, des onomatop\u00e9es, des jeux de mots, des consonances. C\u2019est ce qui a fait la diff\u00e9rence&#8221; selon le rappeur <strong>Pit Baccardi<\/strong>.<\/p>\n\n\n\n<p>Au fur et \u00e0 mesure des ann\u00e9es, le rap fran\u00e7ais \u00e9volue avec l\u2019\u00e9mergence de nouveaux artistes comme <strong>Rohff<\/strong>, <strong>Lafouine<\/strong>, <strong>Sefyu<\/strong>, <strong>Soprano<\/strong> ou encore <strong>Kery James. <\/strong>Les ann\u00e9es 2000 voient le scratch mourir \u00e0 petit feu et la culture hip hop qui regroupaient les danseurs, les beatboxeurs, les Djs et les graffeurs s\u2019efface jour apr\u00e8s jour. C\u2019est un tournant dans l\u2019histoire du rap, car ce m\u00e9lange de discipline amenait une diversit\u00e9 dans les communaut\u00e9s regroup\u00e9es. C\u2019\u00e9tait l\u2019occasion pour beaucoup de se f\u00e9d\u00e9rer, d\u2019\u00e9changer, de s\u2019entraider mais aussi purement et simplement de passer un bon moment tous ensemble. A la fin des ann\u00e9es 90 et au d\u00e9but des ann\u00e9es 2000, ce ph\u00e9nom\u00e8ne de d\u00e9tachement du rap et de son av\u00e8nement a cass\u00e9 cette pr\u00e9c\u00e9dente dynamique pourtant vertueuse.<br>Le rap prend d\u00e9finitivement son envol.<\/p>\n\n\n\n<p>Dans les ann\u00e9es 2005-2010, un style de rap marginal devient presque une norme en France tant son succ\u00e8s est consid\u00e9rable&nbsp;; c\u2019est le \u00ab&nbsp;gangstarap&nbsp;\u00bb. Ce style peut \u00eatre d\u00e9fini comme un m\u00e9lange d\u2019\u00e9gotrip, de glorification de la violence, de d\u00e9finition de la femme comme un objet sexuel. C\u2019est une d\u00e9monstration de richesse comme en t\u00e9moigne les voitures, montres et autres bijoux montr\u00e9s avec insistance dans les clips musicaux de beaucoup d\u2019artistes. C\u2019est aussi une d\u00e9monstration de puissance pour montrer que dans un potentiel conflit, le rappeur et son \u00e9quipe sont pr\u00eats \u00e0 en d\u00e9coudre et mieux que \u00e7a, ils sont pr\u00e9par\u00e9s \u00e0 gagner. Les indicateurs explicites de cette id\u00e9e sont illustr\u00e9s par le fait de montrer l\u2019\u00e9quipe du rappeur en question en arri\u00e8re-plan, des armes, des muscles, des protagonistes qui semblent \u00eatre en plein entra\u00eenement de boxe ou encore des regards mena\u00e7ants accompagn\u00e9s de doigts d\u2019honneur envers la cam\u00e9ra et donc in fine, envers l\u2019auditeur.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Scarface-1024x576.jpg\" alt=\"Scarface-Booba\" class=\"wp-image-11997\" width=\"978\" height=\"551\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Scarface-1024x576.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Scarface-300x169.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Scarface-768x432.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Scarface.jpg 1280w\" sizes=\"(max-width: 978px) 100vw, 978px\" \/><\/figure>\n\n\n\n<p><strong>Booba<\/strong>, <strong>Gradur<\/strong>, <strong>Lacrim <\/strong>ou<strong> Kaaris<\/strong> en sont des dignes repr\u00e9sentants. Nous parlons ici de l\u2019esth\u00e9tique renvoy\u00e9e par le clip, des valeurs v\u00e9hicul\u00e9es, sans dire que les rappeurs sont talentueux ou non. Leur succ\u00e8s parle pour eux-m\u00eames.<\/p>\n\n\n\n<p>Chez ce type de rappeur, on ne sent pas vraiment l\u2019influence hip-hop des ann\u00e9es 80 avec le regroupement de disciplines dont nous parlons pr\u00e9c\u00e9demment. C\u2019est un rap diff\u00e9rent, nouveau en France.<\/p>\n\n\n\n<p>Dans cette m\u00eame \u00e9poque, on retrouve un oppos\u00e9 esth\u00e9tique et musical qui trouve et garde son public. Les th\u00e8mes abord\u00e9s sont politiques, on y parle d\u2019injustices, de mis\u00e8re, de fraternit\u00e9, d\u2019ambition et m\u00eame d\u2019amour. Les repr\u00e9sentants de cette musique qui correspond \u00e0 celle des ann\u00e9es 80-90 du rap fran\u00e7ais sont <strong>Kery James<\/strong>, <strong>Youssoupha<\/strong>, <strong>Keny Arkana<\/strong> et m\u00eame le collectif <strong>1995<\/strong>.<br>Ce collectif avec notamment<strong> Nekfeu<\/strong>, <strong>Guizmo<\/strong>, <strong>Jazzy Bazz<\/strong>, <strong>Sneazzy<\/strong> ou encore <strong>Alpha Wann<\/strong> est encore tr\u00e8s pr\u00e9sent actuellement. <strong>1995<\/strong> a accompagn\u00e9 l\u2019adolescence et plus g\u00e9n\u00e9ralement la jeunesse d\u2019une partie consid\u00e9rable de jeunes n\u00e9s dans les ann\u00e9es 95-2000. C\u2019\u00e9tait un rap \u00e0 l\u2019ancienne de jeunes parisiens tr\u00e8s normaux qui racontaient leurs gal\u00e8res, leur vie, leurs ambitions avec une culture de la technique et du phras\u00e9 incontestablement tr\u00e8s travaill\u00e9.<\/p>\n\n\n\n<p>Enfin, les ann\u00e9es 2010-2020 ont vu na\u00eetre un renouveau dans le rap fran\u00e7ais avec des artistes comme <strong>SCH<\/strong>, <strong>PNL<\/strong>, <strong>Ninho<\/strong>, <strong>Vald<\/strong>, <strong>13block<\/strong> ou encore <strong>Damso<\/strong>. De nouvelles esth\u00e9tiques, approches artistiques, sonorit\u00e9s musicales se sont invit\u00e9es \u00e0 la f\u00eate au plus grand bonheur des amateurs de rap qui voyaient cette musique tourner en rond et perdre en valeur les ann\u00e9es pr\u00e9c\u00e9dentes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/pnl-image-1024x683.jpg\" alt=\"PNL-The-Feader\" class=\"wp-image-11998\" width=\"908\" height=\"605\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/pnl-image-1024x683.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/pnl-image-300x200.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/pnl-image-768x512.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/pnl-image.jpg 1200w\" sizes=\"(max-width: 908px) 100vw, 908px\" \/><\/figure>\n\n\n\n<h2><strong>V\u00e9ritable inversion ou fantasme&nbsp;?<\/strong><\/h2>\n\n\n\n<p>L\u2019\u00e9volution du rap fran\u00e7ais a vu des changements significatifs \u00e0 travers le temps. Les d\u00e9buts du rap caract\u00e9ris\u00e9s par un discours revendicatif sur les difficult\u00e9s rencontr\u00e9es au quartier s\u2019est peu \u00e0 peu transform\u00e9 en \u00ab&nbsp;Gangstarap&nbsp;\u00bb banalis\u00e9. Il est essentiel de pr\u00e9ciser qu\u2019une multitude de style de rap coexistent et que ce fameux gangstarap n\u2019a aucun monopole.<\/p>\n\n\n\n<p>Un rappeur a travers\u00e9 les \u00e2ges, il a toujours eu un succ\u00e8s flamboyant. Sa long\u00e9vit\u00e9 inspire. Il a su se renouveler pour s\u2019adapter au march\u00e9 et garder son tr\u00f4ne. <strong>Booba<\/strong> est un exemple int\u00e9ressant pour analyser bri\u00e8vement comment le rap a \u00e9volu\u00e9.<\/p>\n\n\n\n<p><strong>Booba<\/strong> a toujours excell\u00e9 dans une forme de vulgarit\u00e9, dans le rap \u00ab&nbsp;cru&nbsp;\u00bb. A l\u2019\u00e9poque de Lunatic, dans les ann\u00e9es 2000, <strong>Booba <\/strong>avait d\u00e9j\u00e0 cette aura du jeune banlieusard qui rap sans concession. Il \u00e9tait aussi reconnu pour cette culture du phras\u00e9, une technique d\u00e9routante, une mani\u00e8re de poser singuli\u00e8re. <strong>Ali<\/strong>, par \u00e9quilibre \u00e9tait lui, le rappeur mature dans l\u2019histoire, celui qui prend du recul sur sa vie, qui traite de sujets plus intemporels et philosophiques. <strong>Booba<\/strong> est terre \u00e0 terre et le duo fait mouche.<br>Dans l\u2019esth\u00e9tique, dans ce qui est v\u00e9hicul\u00e9 visuellement, on a un <strong>Booba<\/strong> en capuche qui rap sa musique face cam\u00e9ra sans artifices, sans superficialit\u00e9. Son esth\u00e9tique refl\u00e8te pleinement sa musique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/booba-ali-lunatic.png\" alt=\"Booba-Ali-Lunatic\" class=\"wp-image-11999\" width=\"640\" height=\"383\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/booba-ali-lunatic.png 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/booba-ali-lunatic-300x180.png 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/booba-ali-lunatic-768x461.png 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>Avec son album <em>Panth\u00e9on<\/em> de 2004, le Duc arrive avec une nouvelle image, d\u00e9j\u00e0 tr\u00e8s inspir\u00e9 des Etats-Unis. Sur la cover, on retrouve du muscle, une montre on\u00e9reuse, une cha\u00eene et des tatouages.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon-1024x1024.jpg\" alt=\"Booba-Panth\u00e9on\" class=\"wp-image-12000\" width=\"605\" height=\"605\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon-1024x1024.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-pantheon.jpg 1400w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><\/figure>\n\n\n\n<p>En 2006, avec <em>Ouest side,<\/em> il sort le titre \u00ab&nbsp;<em>Pitbull&nbsp;<\/em>\u00bb qui reprend l\u2019instrumentale <em>de Mistral gagnant<\/em> de <strong>Renaud. <\/strong>Cet album est un succ\u00e8s qui traverse le temps. Le titre de l\u2019album est tr\u00e8s r\u00e9v\u00e9lateur de l\u2019influence am\u00e9ricaine. Dans le clip de <em>Pitbull<\/em>, on commence \u00e0 voir des femmes appara\u00eetre \u00e0 moiti\u00e9 d\u00e9nud\u00e9es dans un lit en talon haut avec <strong>Booba<\/strong>. C\u2019est le d\u00e9but d\u2019une nouvelle image \u00ab&nbsp;bling bling&nbsp;\u00bb d\u2019un homme au pouvoir infini.<\/p>\n\n\n\n<p>Les albums s\u2019encha\u00eenent et on arrive \u00e0 2011 avec <em>Autopsie.4<\/em>, mixtape dans laquelle on retrouve le titre <em>Scarface<\/em> qui aura marqu\u00e9 une g\u00e9n\u00e9ration. Au-del\u00e0 de l\u2019aspect musical, du talent de l\u2019artiste, ce qui nous int\u00e9resse, c\u2019est encore une fois le discours, les valeurs v\u00e9hicul\u00e9es.<br>Ce clip qui comptabilise plus de 36 millions de vues est un exemple parfait du st\u00e9r\u00e9otype qui arrive brillamment \u00e0 r\u00e9unir tous les clich\u00e9s. Nous y retrouvons le rappeur en pleine forme physique qui manie une arme, des gros bijoux en or, des femmes pulpeuses en petites tenues, des strip-teaseuses et bien entendu quelques liasses de billets sans oublier la grosse voiture tr\u00e8s ch\u00e8re. C\u2019est un magnifique cocktail qui r\u00e9sume ce qu\u2019\u00e9tait devenu une grande partie du rap \u00e0 cette p\u00e9riode.<\/p>\n\n\n\n<p>Si l\u2019on compare le <strong>Booba <\/strong>des ann\u00e9es 2005-2015 \u00e0 celui des ann\u00e9es 95-2000, on retrouve une inversion des valeurs assez symbolique. Difficile d\u2019imaginer le Booba \u00e0 la fin des ann\u00e9es 90 dire \u00ab Je n\u2019arr\u00eate pas de mater son cul, j\u2019y plongerai 25 fois par jours jusqu\u2019\u00e0 ce que la go appelle au secours, jusqu\u2019\u00e0 ce qu\u2019elle n\u2019en peuve plus&nbsp;\u00bb. N\u00e9anmoins, chez <strong>Booba<\/strong>, le discours s\u2019est certes vulgaris\u00e9, mais il a toujours \u00e9t\u00e9 violent et vulgaire, un discours cru. Ce discours \u00e9tait sans artifice, l\u2019influence am\u00e9ricaine a ramen\u00e9 quelques paillettes qui ont fait briller le rappeur.<\/p>\n\n\n\n<p>Aujourd\u2019hui, <strong>Booba<\/strong> avec par exemple le clip <em>RST <\/em>sorti en juillet 2021, se retrouve entour\u00e9 de bijoux, des grosses voitures, des femmes compl\u00e8tement d\u00e9nud\u00e9es qui twerkent, un ennemi qui se fait passer \u00e0 tabac. Le rappeur est toujours dans une volont\u00e9 d\u2019exposer sa puissance, de montrer le danger qu\u2019il repr\u00e9sente dans un potentiel conflit. Il montre aussi sa r\u00e9ussite financi\u00e8re, ses acquisitions mat\u00e9rielles, mais repr\u00e9sente aussi la femme comme rien d\u2019autre qu\u2019un objet sexuel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" id=\"Booba-RST\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-RST.jpg\" alt=\"Booba-RST\" class=\"wp-image-12001\" width=\"570\" height=\"308\" title=\"Booba RST\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-RST.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-RST-300x162.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/Booba-RST-768x414.jpg 768w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure>\n\n\n\n<p>Cette \u00e9tude de cas sur <strong>Booba<\/strong> est int\u00e9ressante car r\u00e9v\u00e9latrice de l\u2019\u00e9volution du rap dans le discours pos\u00e9. N\u00e9anmoins, <strong>Booba <\/strong>ne repr\u00e9sente pas l\u2019ensemble du rap, il y a toujours eu du rap conscient ou comme <strong>Guizmo<\/strong> l\u2019appelle, du rap \u00ab&nbsp;cens\u00e9&nbsp;\u00bb et il y en aura toujours. M\u00eame lors de la p\u00e9riode 2005-2010, il y avait <strong>Kery James<\/strong>, <strong>Youssoupha<\/strong> etc\u2026<\/p>\n\n\n\n<p>Nous sommes pass\u00e9 d\u2019un discours qui critique l\u2019\u00e9tat, qui d\u00e9nonce des injustices l\u00e9gitimes, qui met en perspective les exc\u00e8s du capitalisme, de la course \u00e0 l\u2019argent permanente \u00e0 un rap qui fait la promotion exacte de ce qui \u00e9tait d\u00e9nonc\u00e9. Le gangstarap qui s\u2019est compl\u00e8tement banalis\u00e9 fait la promotion d\u2019acquisitions mat\u00e9rielles on\u00e9reuses, fait la promotion de l\u2019individualisme, glorifie la violence, glorifie la paresse et fait au final la promotion de l\u2019ultra capitalisme et de ses exc\u00e8s.<\/p>\n\n\n\n<p>Le <strong>Booba<\/strong> de <em>scarface<\/em> est un pur produit de l\u2019ultra capitalisme am\u00e9ricain. Le rap des ann\u00e9es 90 d\u00e9non\u00e7aient exactement ce type de profil qui ne pense plus qu\u2019a la richesse et ne laisse rien \u00e0 des valeurs comme le partage, la bienveillance ou l\u2019engagement politique et social.<\/p>\n\n\n\n<p>C\u2019est une parfaite inversion dans le discours qui est pour le moins \u00e9tonnante.<\/p>\n\n\n\n<p><strong>IAM <\/strong>qui a jou\u00e9 un r\u00f4le d\u00e9terminant dans l\u2019histoire de notre rap n\u2019\u00e9tait pas toujours tendre. Il n\u2019y avait pas un rap doux et aujourd\u2019hui un rap hardcore, mais la mani\u00e8re de penser et de poser les drames de leurs vies est tout \u00e0 fait diff\u00e9rent.<br>L\u2019\u00e9quipe d\u2019<strong>IAM<\/strong> n\u2019avait pas la vie facile. Ils racontent dans leurs musiques leurs gal\u00e8res, leurs difficult\u00e9s, la vie au quartier comme beaucoup le font aujourd\u2019hui. Dans leur titre \u00ab&nbsp;<em>C\u2019est donc \u00e7a nos vies<\/em>&nbsp;\u00bb (1997), morceau assez triste qui parle de leur quotidien difficile rempli de violence, <strong>Freeman <\/strong>dit \u00ab&nbsp;Chez nous les c\u0153urs se glacent tr\u00e8s t\u00f4t<br>La peur se tasse, pour un rien les fr\u00e8res se fracassent<br>Les patates volent, les mauvais coups s&#8217;encha\u00eenent<br>Comme cette chienne de vie habitu\u00e9s au vacarme<br>Pour \u00e9viter les larmes, dans les poches les gosses y glissent des lames<br>Pas facile de vivre avec des drames&nbsp;\u00bb.<\/p>\n\n\n\n<p>C\u2019est d\u2019une violence extr\u00eame, mais malgr\u00e9 cela on retrouve cette culture fran\u00e7aise du phras\u00e9. Il y a bel et bien la volont\u00e9 de faire quelque chose de beau \u00e0 partir d\u2019une vie qui ne l\u2019est pas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"IAM-AKH\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/iam-2QUIPE-aKH2NATON-1024x576.jpg\" alt=\"IAM-Akh\u00e9naton\" class=\"wp-image-12002\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/iam-2QUIPE-aKH2NATON-1024x576.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/iam-2QUIPE-aKH2NATON-300x169.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/iam-2QUIPE-aKH2NATON-768x432.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/iam-2QUIPE-aKH2NATON.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Chez <strong>NTM<\/strong>, on retrouve encore plus de violence et de vulgarit\u00e9 dans les textes, mais les th\u00e8mes socio-politiques sont souvent abord\u00e9s. Il y a cette dimension revendicative propre au rap des ann\u00e9es 90. Dans le titre \u00e0 succ\u00e8s \u00ab&nbsp;<em>Tout n\u2019est pas si facile&nbsp;\u00bb<\/em>, le texte commence par une succession de phases qui r\u00e9sument plut\u00f4t bien l\u2019\u00e9nergie qui r\u00e9gnait autour du hip-hop :<\/p>\n\n\n\n<p>\u00ab&nbsp;1983, il y a plus de dix ans d\u00e9j\u00e0<br>Le Hip Hop en France faisait ses premiers pas<br>Il n&#8217;y avait pas de r\u00e8gle, pas de loi<br>Non surtout pas de contrat<br>Pas de probl\u00e8mes entre toi et moi<br>Tout \u00e9tait clair, du but \u00e0 la mani\u00e8re<br>Dont tout devait se faire, na\u00eff, novice, mais tellement fier<br>D&#8217;\u00e9voluer dans un syst\u00e8me parall\u00e8le<br>O\u00f9 les valeurs de base \u00e9taient p\u00eale-m\u00eale<br>Peace, Unity, Love and Having Fun<br>Le Hip Hop n&#8217;a jamais eu besoin de gun<br>Ni de gang, de toys ni de bande<br>Mais plut\u00f4t de la foi de ce qui en d\u00e9fendent<br>La m\u00e9moire et l&#8217;\u00e9thique, les valeurs essentielles&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"NTM-noir-et-blanc\"><img loading=\"lazy\" width=\"1024\" height=\"578\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NTM-noir-et-blanc-1024x578.jpg\" alt=\"NTM-Noir-blanc\" class=\"wp-image-12003\" title=\"NTM\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NTM-noir-et-blanc-1024x578.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NTM-noir-et-blanc-300x169.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NTM-noir-et-blanc-768x434.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NTM-noir-et-blanc.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La paix, l\u2019unit\u00e9 et l\u2019h\u00e9donisme sont mis \u00e0 l\u2019honneur avec le groupe <strong>NTM<\/strong>, pourtant consid\u00e9r\u00e9 comme l\u2019un des groupes les plus vulgaires, les plus hardcore de l\u2019\u00e9poque.<\/p>\n\n\n\n<p>Lorsque l\u2019on entend certaines phases du rap actuel, on se rend compte qu\u2019il n\u2019y a plus de limites \u00e9thiques et que les valeurs v\u00e9hicul\u00e9es par certains artistes sont compl\u00e8tement \u00e0 l\u2019oppos\u00e9 du Hip-hop traditionnel. Pour illustrer ce propos, voici une s\u00e9lection de phases de rap moderne qui choqueraient un auditeur de rap des ann\u00e9es 90.<\/p>\n\n\n\n<p><strong>Niska <\/strong>dans <em>Carjack Chiraque<\/em> \u00ab&nbsp;Jeune renoi sauvage, elles ont du sperme dans l&#8217;\u0153sophage (bando na bando) Le canon frotte mon p\u00e9nis, le vendredi je suis en qamis&nbsp;\u00bb. Voila qui est relativement vulgaire en mettant en avant son c\u00f4t\u00e9 sauvage et la r\u00e9duction de la femme \u00e0 un objet sexuel humili\u00e9. Il est absolument impensable de voir cela dans le rap fran\u00e7ais traditionnel et c\u2019est pourtant un morceau qui n\u2019a fait aucune pol\u00e9mique, qui est pass\u00e9 inaper\u00e7u tout en \u00e9tant tr\u00e8s \u00e9cout\u00e9.<\/p>\n\n\n\n<p>Un morceau tr\u00e8s \u00e9cout\u00e9, qui est pass\u00e9 en bo\u00eete de nuit ou m\u00eame en radio est le son \u00ab&nbsp;<em>Tchoin<\/em>&nbsp;\u00bb de <strong>Kaaris,<\/strong> tout simplement hallucinant au niveau du discours. Le refrain qui fait 40% du son dit \u00ab&nbsp;la go l\u00e0 c\u2019est peut-\u00eatre une fille bien, mais on pr\u00e9f\u00e8re les tchoins, tchoins, tchoins&nbsp;\u00bb. La &#8220;go&#8221; veut dire la &#8220;fille&#8221; et &#8220;tchoin&#8221;, qui vient de C\u00f4te d\u2019Ivoire veut dire prostitu\u00e9 ou plus vulgairement \u00ab&nbsp;salope&nbsp;\u00bb. Le rappeur glorifie donc la fille facile et r\u00e9duit la fille qui se respecte \u00e0 une personne inint\u00e9ressante et peu s\u00e9duisante. Aussi surr\u00e9aliste qu\u2019il n\u2019y paraisse, cette musique a fait des centaines de millions d\u2019\u00e9coutes.<\/p>\n\n\n\n<p>On peut continuer avec <strong>Sifax <\/strong>et <strong>Sofiane<\/strong> dans le titre \u00ab&nbsp;<em>Mecs de cit\u00e9<\/em>&nbsp;\u00bb dont le refrain est le suivant&nbsp;:&nbsp; \u00ab&nbsp;Eh ouai c\u2019est nous les mecs de cit\u00e9 et on va leur tirer dessus, j\u2019te fais pas la bise je suis arm\u00e9, j\u2019m\u2019en bats les couilles de ton v\u00e9cu&nbsp;\u00bb. Le rappeur r\u00e9duit les habitants des quartiers sensibles \u00e0 des potentiels criminels qui sont arm\u00e9s et qui n\u2019h\u00e9sitent pas \u00e0 tirer. Cette phrase est symptomatique de la glorification de la violence et de sa banalisation. Ce refrain est chant\u00e9 par <strong>Sifax,<\/strong> comme si c\u2019\u00e9tait festif et sympathique soit relativement banal.<\/p>\n\n\n\n<p>A l\u2019oppos\u00e9 de ce type de discours, un groupe de deux fr\u00e8res a su tirer son \u00e9pingle du jeu. Dans un climat de rap qui valorise l\u2019agressivit\u00e9 et la haine en chantant avec un grand sourire, <strong>PNL<\/strong> qui ont grandi dans un quartier particuli\u00e8rement sensible \u00e0 vendre de la drogue ont pris un contre-pied int\u00e9ressant en ayant une approche plus nuanc\u00e9e, plus complexe et plus honn\u00eate. L\u00e0 o\u00f9 beaucoup de rappeurs affichent leurs armes avec fiert\u00e9 et se vantent de vendre de la drogue, <strong>Ademo <\/strong>dit dans le titre \u00ab&nbsp;<em>oh lala<\/em>&nbsp;\u00bb \u00ab&nbsp;C\u2019est sale quand je vends la came, mais bon croyez pas que je kiff, des remords quand je suis \u00e0 table&nbsp;\u00bb, dans un ton dramatique. Les amateurs de rap y ont retrouv\u00e9 une bouff\u00e9e d\u2019air frais. Enfin, des rappeurs investis dans le trafic n\u2019en font pas la promotion, ils en sont d\u00e9sol\u00e9s, ils sont tout le contraire de Piaf.<br>De plus, ils n\u2019ont jamais montr\u00e9 de femmes d\u00e9nud\u00e9es dans leur clip, ils pr\u00e9f\u00e8rent montrer le monde et sa nature ou bien leur quartier des Tarter\u00eats. Encore une fois, ils n\u2019entrent pas dans le clich\u00e9 de montrer leur puissance financi\u00e8re par le fait d\u2019acqu\u00e9rir des femmes faciles, tout ce qu\u2019ils veulent c\u2019est faire plaisir \u00e0 leur famille et aider leur quartier. Ce sont des valeurs que l\u2019on retrouve compl\u00e8tement dans les d\u00e9buts du Hip-hop fran\u00e7ais. Pour finir, on voit <strong>NOS<\/strong> dans le morceau \u00ab&nbsp;<em>Dans ta rue<\/em>&nbsp;\u00bb qui passe devant une Ferrari et malgr\u00e9 un succ\u00e8s musical et donc financier, il ne la regarde m\u00eame pas, il va s\u2019assoir devant son hall et fumer son joint. Encore une fois, c\u2019est l\u2019exposition de valeurs simples, sans artifices, sans am\u00e9ricanisation.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"NOS-dans-ta-rue\"><img loading=\"lazy\" width=\"1024\" height=\"614\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NOS-dans-ta-rue-1024x614.jpg\" alt=\"NOS-dans-ta-rue\" class=\"wp-image-12004\" title=\"NOS-dans-ta-rue\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NOS-dans-ta-rue-1024x614.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NOS-dans-ta-rue-300x180.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NOS-dans-ta-rue-768x461.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/NOS-dans-ta-rue.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>De nos jours, on voit des rappeurs \u00e9mergents qui ont un avenir radieux devant eux comme <strong>Benjamin Epps<\/strong> qui allie l\u2019\u00e9go-trip du rap moderne avec la technique et la culture du phras\u00e9 \u00e0 l\u2019ancienne. Il est un pur m\u00e9lange qui saura ravir divers publics avec un discours violent mais fin, pr\u00e9tentieux mais ambitieux, un \u00e9go-trip saupoudr\u00e9 d\u2019humour qui fait mouche. <strong>Lesram,<\/strong> le rappeur Parisien lui aussi allie rap moderne et technique \u00e0 l\u2019ancienne, il nous offre un <a href=\"https:\/\/startitkbs.org\/index.php\/2020\/12\/18\/lesram-le-rap-entre-deux-epoques\/\" data-type=\"URL\" data-id=\"https:\/\/startitkbs.org\/index.php\/2020\/12\/18\/lesram-le-rap-entre-deux-epoques\/\" target=\"_blank\" rel=\"noreferrer noopener\">rap entre deux \u00e9poques<\/a>.<\/p>\n\n\n\n<p>Quoi qu\u2019il en soit, le rap est un fait de soci\u00e9t\u00e9 de par son succ\u00e8s vers les jeunes, c\u2019est une musique qui accompagne quotidiennement les fran\u00e7ais de plus en plus t\u00f4t et qui ne peut qu\u2019avoir une influence sur notre construction personnelle. Les valeurs, le discours v\u00e9hicul\u00e9 n\u2019est pas toujours fin et comme dit<strong> Jean Jass<\/strong>, il faut prendre du recul sur cette musique \u00ab&nbsp;j\u2019\u00e9coute trop de rap \u00e7a m\u2019abruti&nbsp;\u00bb.<\/p>\n\n\n\n<p>Enfin, le rap a toujours connu des artistes plus ou moins violents dans leurs discours et \u00e7a ne changera pas. Cependant, la popularit\u00e9 d\u2019un certain rap a \u00e9merg\u00e9 depuis les ann\u00e9es 2000-2005, il exerce une influence que l\u2019on peut consid\u00e9rer comme malsaine \u00e0 l\u2019\u00e9gard des femmes, qui divise plut\u00f4t qu\u2019il ne r\u00e9unit. L\u2019agressivit\u00e9 exerc\u00e9e n\u2019est plus cont\u00e9e pour \u00e9lever sa musique au rang d\u2019art, mais comme objet commercial sans \u00e2me particuli\u00e8re dans un nombre de cas innombrables. Il reste une partie consid\u00e9rable d\u2019artiste qui ne s\u2019inscrit pas dans cette optique et qui continue de faire vivre une branche du rap qui ne mourra jamais.<br>Le rap a chang\u00e9, l\u2019inversion des valeurs est r\u00e9elle mais n\u2019est pas totale.<\/p>\n\n\n\n<p>Dimitri Mazin<\/p>\n\n\n\n<p>Enjoy &amp; Stay tuned<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le rap fran\u00e7ais a \u00e9volu\u00e9, ses valeurs ont chang\u00e9es. Y&#8217;a-t-il une inversion des valeurs ou est-ce un simple fantasme ?<\/p>\n","protected":false},"author":2,"featured_media":12008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[1174,1031,1032,1173],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rap fran\u00e7ais, inversion des valeurs ? - Start It<\/title>\n<meta name=\"description\" content=\"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rap fran\u00e7ais, inversion des valeurs ? - Start It\" \/>\n<meta property=\"og:description\" content=\"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-09T22:10:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-24T12:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"621\" \/>\n\t<meta property=\"og:image:height\" content=\"346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png\",\"contentUrl\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png\",\"width\":621,\"height\":346,\"caption\":\"Le rap fr et ses valeurs\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/\",\"name\":\"Rap fran\u00e7ais, inversion des valeurs ? - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#primaryimage\"},\"datePublished\":\"2021-10-09T22:10:31+00:00\",\"dateModified\":\"2021-11-24T12:37:15+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"description\":\"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?\",\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rap fran\u00e7ais, inversion des valeurs ?\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"https:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rap fran\u00e7ais, inversion des valeurs ? - Start It","description":"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Rap fran\u00e7ais, inversion des valeurs ? - Start It","og_description":"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?","og_url":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2021-10-09T22:10:31+00:00","article_modified_time":"2021-11-24T12:37:15+00:00","og_image":[{"width":621,"height":346,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png","contentUrl":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/10\/rap-francais-1.png","width":621,"height":346,"caption":"Le rap fr et ses valeurs"},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/","name":"Rap fran\u00e7ais, inversion des valeurs ? - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#primaryimage"},"datePublished":"2021-10-09T22:10:31+00:00","dateModified":"2021-11-24T12:37:15+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"description":"Le rap fran\u00e7ais a \u00e9volu\u00e9 depuis son apparition en France, le discours aussi. Les valeurs transmises en font-elles partie ?","breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2021\/10\/10\/rap-francais-inversion-des-valeurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Rap fran\u00e7ais, inversion des valeurs ?"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"https:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/11994"}],"collection":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=11994"}],"version-history":[{"count":13,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/11994\/revisions"}],"predecessor-version":[{"id":12410,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/11994\/revisions\/12410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/12008"}],"wp:attachment":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=11994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=11994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=11994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}