{"id":12249,"date":"2021-11-12T17:26:39","date_gmt":"2021-11-12T16:26:39","guid":{"rendered":"http:\/\/startitkbs.org\/?p=12249"},"modified":"2021-11-15T10:22:58","modified_gmt":"2021-11-15T09:22:58","slug":"12249","status":"publish","type":"post","link":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/","title":{"rendered":"Le Rap en Amour"},"content":{"rendered":"\n<p style=\"font-size:17px\"><em>\u00ab&nbsp;Ton absence est la pire des pr\u00e9sences&nbsp;\u00bb, Nekfeu<\/em><\/p>\n\n\n\n<p>Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, compos\u00e9e uniquement de textes violents et haineux et faisant l\u2019apologie des drogues, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 cela. M\u00eame si la fronti\u00e8re entre le Rap et la Pop peut parfois para\u00eetre difficilement discernable, certains artistes comme <strong>Laylow<\/strong>, <strong>Dinos<\/strong> ou <strong>Nekfeu<\/strong> ont su prouver que le Rap avait une toute autre facette, tout en respectant les codes de la musique Hip Hop.<\/p>\n\n\n\n<p>Voici donc une analyse de trois morceaux de Rap fran\u00e7ais ayant bris\u00e9 des c\u0153urs, \u00e0 d\u00e9faut d\u2019avoir bris\u00e9 des chevilles.<\/p>\n\n\n\n<h2>I. Une ville sans soleil<\/h2>\n\n\n\n<p><strong>Dinos<\/strong> est aujourd\u2019hui per\u00e7u comme un des rappeurs les plus talentueux de sa g\u00e9n\u00e9ration. Depuis tout jeune, il fait parler de lui gr\u00e2ce \u00e0 son \u00e9criture. Entre ses punchlines incisives lors de ses battles et ses textes profonds et parlants de son premier projet \u00ab&nbsp;<em>l\u2019Alchimiste<\/em>&nbsp;\u00bb, Dinos fait de ses lyrics son identit\u00e9 et r\u00e9ussit \u00e0 charmer le public.<\/p>\n\n\n\n<p>Le 27 avril 2018, <strong>Dinos<\/strong> sort son premier album, \u00ab&nbsp;<em>Imany&nbsp;\u00bb<\/em> et s\u2019impose directement comme un pilier du Rap fran\u00e7ais gr\u00e2ce \u00e0 sa qualit\u00e9 artistique. Le 9<sup>e<\/sup> titre de l\u2019album s\u2019appelle &#8216;<em>Helsinki<\/em> &#8216;, et pour la premi\u00e8re fois l\u2019artiste y d\u00e9peint ses sentiments amoureux, ou plut\u00f4t ceux de son ex puisque l\u2019introduction du morceau est le r\u00e9pondeur de <strong>Dinos<\/strong>. Ici, c\u2019est donc elle qui s\u2019adresse \u00e0 l\u2019artiste.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Dinos - Helsinki (Clip Officiel)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/HM9w1pRFHmo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le titre du son fait r\u00e9f\u00e9rence \u00e0 la capitale Finlandaise, connue pour n\u2019\u00eatre quasiment pas \u00e9clair\u00e9e en Hiver. C\u2019est donc une ville sans lumi\u00e8re, sans Soleil, ce qui fait sens lorsqu\u2019elle la compare \u00e0 sa vie loin de celui qu\u2019elle aime, et il l\u2019affiche clairement dans son refrain&nbsp;:<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Les lumi\u00e8res s\u2019\u00e9teignent, en pleine apr\u00e8s-midi, l\u2019impression d\u2019\u00eatre une ville sans Soleil, Helsinki, Helsinki\u2026&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<p>Ce qui est int\u00e9ressant dans ce texte, c\u2019est l\u2019\u00e9volution des sentiments de cette femme \u00e0 travers les diff\u00e9rents couplets, ou peu \u00e0 peu, les sentiments se transforment en haine.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Si tu savais comme je te d\u00e9teste, tu saurais \u00e0 quel point je t\u2019aime&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<p>Petit clin d\u2019\u0153il \u00e0 cette punchline magnifique&nbsp;: <em>\u00ab&nbsp;Puis tu sais je suis irrit\u00e9e alors parfois je pleure de trop, en v\u00e9rit\u00e9 mes larmes ne servent qu\u2019\u00e0 irriter ma fleur de peau&nbsp;\u00bb<\/em>, en esp\u00e9rant qu\u2019elle vous fasse cogiter un peu&nbsp;!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos-1024x576.jpg\" alt=\"\" class=\"wp-image-12253\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos-1024x576.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos-300x169.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos-768x432.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos-1536x864.jpg 1536w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dinos.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2>II. Galat\u00e9e<\/h2>\n\n\n\n<p>En 2016 sort le deuxi\u00e8me album de <strong>Nekfeu<\/strong>, \u00ab&nbsp;<em>Cyborg&nbsp;\u00bb<\/em>, dans lequel se trouve le son \u00ab&nbsp;<em>Galat\u00e9e&nbsp;\u00bb<\/em>, un des morceaux phares du rappeur. L\u2019ancien membre du S-Crew est aussi connu pour ses qualit\u00e9s d\u2019\u00e9criture que de kickage. Il a \u00e9t\u00e9 l&#8217;un des premiers \u00e0 s\u2019\u00e9loigner des codes du rap \u00ab&nbsp;traditionnel&nbsp;\u00bb pour parler \u00e0 un public plus large, comme l\u2019avait fait <strong>Orelsan<\/strong> \u00e0 son \u00e9poque, ce qui explique son succ\u00e8s fulgurant.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"512\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/nekfeu-1024x512.jpg\" alt=\"\" class=\"wp-image-12252\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/nekfeu-1024x512.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/nekfeu-300x150.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/nekfeu-768x384.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/nekfeu.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Ici le titre fait r\u00e9f\u00e9rence \u00e0 un mythe grecque dans lequel un sculpteur, Pygmalion, tombe amoureux de sa cr\u00e9ation, Galat\u00e9e. <strong>Nekfeu<\/strong> se sert de ce mythe pour raconter sa relation tumultueuse avec une femme qu\u2019il a aim\u00e9e, mais qui est incapable de passer outre son succ\u00e8s.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Aujourd\u2019hui c\u2019est dur et demain c\u2019est pire, ta jalousie me donne envie de toutes les s\u00e9duire&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<p>Cela marque une incompatibilit\u00e9 entre ses relations amoureuses et son art, mais l\u2019artiste va plus loin. Si on se r\u00e9f\u00e8re aux lyrics de \u00ab&nbsp;<em>Plume&nbsp;\u00bb<\/em>, un morceau de son premier album dans lequel il admet qu\u2019il ne serait pas pr\u00eat \u00e0 abandonner d\u2019\u00e9crire pour une femme, on comprend que cette Galat\u00e9e n\u2019est pas la femme que le <em>Fennec<\/em> attend toute la soir\u00e9e, mais bien une personnification du Rap, qui lui procure une passion transcendante, contrairement aux amours risibles qu\u2019il d\u00e9peint dans &#8216;<em>Suga&#8217;.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Galat\u00e9e\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/ViCL1jMZNHc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2>III. Entre m\u00e9lancolie et parano\u00efa<\/h2>\n\n\n\n<p>Comment vous parler de chansons d\u2019amour sans \u00e9voquer <strong>Laylow, <\/strong>car<strong> Laylow, <\/strong>c\u2019est tout un univers, sombre, m\u00e9lancolique, marginal et complexe. Contrairement \u00e0 d\u2019autres artistes rap aux codes certes efficaces, mais d\u00e9j\u00e0 vus, l\u2019artiste nous propose d\u2019entrer dans un univers original et fantastique, que l\u2019on ne saurait inscrire dans une \u00e9poque. Il nous entraine dans un monde lugubre et, par des contrastes, r\u00e9ussit \u00e0 nous y d\u00e9peindre des tableaux color\u00e9s. <strong>Laylow<\/strong> crie, chuchote, s\u2019\u00e9nerve puis zozote\u2026 Son flow ne cesse de varier et va jusqu\u2019\u00e0 nous transporter l\u00e0 o\u00f9 il le veut, ceci lui permettant d\u2019aborder les th\u00e8mes qu\u2019il souhaite de mani\u00e8re profonde et originale.<\/p>\n\n\n\n<p>En effet, l\u2019artiste toulousain n\u2019a pas arr\u00eat\u00e9 de nous raconter ses peines de c\u0153urs sur des instrus m\u00e9lancoliques tout au long de ses projets, et c\u2019est ici le cas dans le 9<sup>\u00e8me<\/sup> son de l\u2019EP \u00ab&nbsp;<em>.RAW-Z<\/em>&nbsp;\u00bb sorti en 2018, \u00ab&nbsp;<em>Vent de l\u2019Est<\/em>&nbsp;\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z-1024x1024.jpg\" alt=\"\" class=\"wp-image-12254\" width=\"487\" height=\"487\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z-1024x1024.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/laylow-raw-z.jpg 1200w\" sizes=\"(max-width: 487px) 100vw, 487px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Laylow<\/strong> y raconte son r\u00e9veil dans une chambre d\u2019h\u00f4tel, ou il d\u00e9couvre que la fille avec qui il a pass\u00e9 la nuit l\u2019a quitt\u00e9 sans le pr\u00e9venir. <em>Jey<\/em> se met en sc\u00e8ne ivre chantant son malheur d\u2019avoir perdu cette derni\u00e8re et se sent une fois de plus abandonn\u00e9. Le terme <em>vent de l\u2019Est<\/em> d\u00e9crit tr\u00e8s bien l\u2019effet que lui procure cette rupture, puisqu\u2019il la qualifie de glacial, comme le souffle de la mort. La mort est d\u2019ailleurs \u00e9voqu\u00e9e plusieurs fois dans le morceau.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;J\u2019te raconte pas ce qu\u2019il m\u2019est pass\u00e9 par la te-t\u00ea hier, t\u2019fa\u00e7on j\u2019suis d\u00e9j\u00e0 mort \u00e0 l\u2019int\u00e9rieur j\u2019ai \u00e9teint la lumi\u00e8re&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du clip, <strong>Laylow<\/strong> se r\u00e9veille d\u2019un r\u00eave parano\u00efaque dans lequel il est tu\u00e9 par cette femme qu\u2019il aime, image qui d\u00e9crit encore une fois tr\u00e8s bien les pens\u00e9es sombres de l\u2019artiste.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;P\u00e9tasse quand tu me laisses je me sens seul \u00e0 la mort. Pourquoi t&#8217;es partie si vite ? Pourquoi t&#8217;as claqu\u00e9 la porte ? Comme le vent de l&#8217;est, tu m&#8217;as refroidi les os&nbsp;\u00bb<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"LAYLOW - VENT DE L&#039;EST\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/6YcYsk0lbjI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Enjoy &amp; Stay Tuned.<\/p>\n\n\n\n<p><strong><em>Loisel No\u00e9<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;Ton absence est la pire des pr\u00e9sences&nbsp;\u00bb, Nekfeu Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, compos\u00e9e uniquement de textes violents et haineux et faisant l\u2019apologie des drogues, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 cela. M\u00eame si la fronti\u00e8re entre le Rap et la Pop peut parfois para\u00eetre difficilement discernable, &#8230; <a title=\"Le Rap en Amour\" class=\"read-more\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/\">Lire la suite <span class=\"screen-reader-text\">Le Rap en Amour<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":12289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[1228,1227,44,787,12,639,41,58],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Rap en Amour - Start It<\/title>\n<meta name=\"description\" content=\"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Rap en Amour - Start It\" \/>\n<meta property=\"og:description\" content=\"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T16:26:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T09:22:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg\",\"contentUrl\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg\",\"width\":660,\"height\":330},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/\",\"name\":\"Le Rap en Amour - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#primaryimage\"},\"datePublished\":\"2021-11-12T16:26:39+00:00\",\"dateModified\":\"2021-11-15T09:22:58+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"description\":\"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.\",\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Rap en Amour\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"https:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Rap en Amour - Start It","description":"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Rap en Amour - Start It","og_description":"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.","og_url":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2021-11-12T16:26:39+00:00","article_modified_time":"2021-11-15T09:22:58+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg","contentUrl":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/11\/dams.jpg","width":660,"height":330},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/","name":"Le Rap en Amour - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#primaryimage"},"datePublished":"2021-11-12T16:26:39+00:00","dateModified":"2021-11-15T09:22:58+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"description":"Pour de nombreuses personnes, le Rap incarne une musique antisyst\u00e8me, cependant il semblerait qu\u2019il ne se r\u00e9sume pas qu\u2019\u00e0 \u00e7a.","breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2021\/11\/12\/12249\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Le Rap en Amour"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"https:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12249"}],"collection":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=12249"}],"version-history":[{"count":12,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12249\/revisions"}],"predecessor-version":[{"id":12290,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12249\/revisions\/12290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/12289"}],"wp:attachment":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=12249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=12249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=12249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}