{"id":12500,"date":"2021-12-04T13:13:33","date_gmt":"2021-12-04T12:13:33","guid":{"rendered":"http:\/\/startitkbs.org\/?p=12500"},"modified":"2022-01-19T19:06:28","modified_gmt":"2022-01-19T18:06:28","slug":"captaine-roshi-de-serpent-a-dragon","status":"publish","type":"post","link":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/","title":{"rendered":"Captaine Roshi: De serpent \u00e0 dragon"},"content":{"rendered":"\n<p><em>Deux ans apr\u00e8s notre live report lors de son concert&nbsp;\u00e0 l\u2019Iboat&nbsp;, nous&nbsp;avons d\u00e9cid\u00e9 de reparler de&nbsp;<strong>Captaine&nbsp;Roshi<\/strong>, de son personnage et de sa carri\u00e8re qui a bien \u00e9volu\u00e9 depuis.<\/em><\/p>\n\n\n\n<p>Le 28 octobre 2021 sortait&nbsp;l\u2019EP&nbsp;:&nbsp;<em>ROAD&nbsp;TO&nbsp;LAROSH<\/em>, plein de coh\u00e9rence, il fait suite \u00e0 ces quatre derni\u00e8res r\u00e9alisations&nbsp;(&#8220;<em>attaque<\/em>&#8220;, &#8220;<em>contre<\/em>&#8211;<em>attaque<\/em>&#8220;,&nbsp;&#8220;<em>W.A.R<\/em>&#8221;&nbsp;et &#8220;<em>attaque II<\/em>&#8220;).&nbsp;Avec ce&nbsp;projet, le&nbsp;rappeur de Pigalle impose son style, sa voix et ses visuels dans le paysage du rap&nbsp;Fran\u00e7ais.&nbsp;Revenons donc sur son \u00e9volution, de ses d\u00e9buts jusqu\u2019aux portes de &#8220;<em>LAROSH<\/em>&#8221; en r\u00e9f\u00e9rence \u00e0 son premier album qui sortira prochainement et qu\u2019il pr\u00e9pare depuis longtemps.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">\u26a0\ufe0f\u26a0\ufe0f\u26a0\ufe0fLe 29 c\u2019est bient\u00f4t c\u2019est dans 9 jours j\u2019ai l\u2019honneur de vous pr\u00e9sentez ROAD TO LAROSH le chemin avant l\u2019album LAROSH avec des artiste \u00e9norme comme <a href=\"https:\/\/twitter.com\/malty2bz?ref_src=twsrc%5Etfw\">@malty2bz<\/a> <a href=\"https:\/\/twitter.com\/Guy2Bezbar?ref_src=twsrc%5Etfw\">@Guy2Bezbar<\/a> <a href=\"https:\/\/twitter.com\/wit_213?ref_src=twsrc%5Etfw\">@wit_213<\/a> et <a href=\"https:\/\/twitter.com\/Lafeve7?ref_src=twsrc%5Etfw\">@Lafeve7<\/a> et des beatmaker \u00e9norme comme <a href=\"https:\/\/twitter.com\/Ponkovichiery?ref_src=twsrc%5Etfw\">@Ponkovichiery<\/a> , Cartier,Manrey et plus encore\u26a0\ufe0f\u26a0\ufe0f\u26a0\ufe0f <a href=\"https:\/\/t.co\/ON9EkG8Mgm\">pic.twitter.com\/ON9EkG8Mgm<\/a><\/p>&mdash; AU PORTE DE LAROSH! (@captaineroshi) <a href=\"https:\/\/twitter.com\/captaineroshi\/status\/1450896124022300674?ref_src=twsrc%5Etfw\">October 20, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2>Ses origines <\/h2>\n\n\n\n<p>Pour comprendre l\u2019\u00e9volution du rappeur, il faut s\u2019int\u00e9resser \u00e0 ses origines :&nbsp;<strong>Captaine&nbsp;Roshi<\/strong>&nbsp;est un rappeur franco-congolais, n\u00e9 \u00e0 Kinshasa le 16 juin 1996.&nbsp;D\u2019origine congolaise et s\u00e9n\u00e9galaise, il arrive en France entre Pigalle et Villeneuve-Saint-Georges, \u00e0 Paris \u00e0 la suite d\u2019un cancer de son fr\u00e8re.&nbsp;Issu d\u2019une famille tr\u00e8s catholique, il a connu une situation assez pr\u00e9caire.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.danstafaceb.com\/wp-content\/uploads\/2020\/12\/whatsapp-image-2020-10-15-at-21-21-19-800x1200.jpeg\" alt=\"Captaine Roshi se remet en ordre de bataille avec Attaque 2 - La Face B\" width=\"204\" height=\"306\"\/><\/figure>\n\n\n\n<p>Dans son&nbsp;adolescence<strong> Roshi<\/strong>&nbsp;a un cursus scolaire assez compliqu\u00e9, c\u2019est dans son lyc\u00e9e du&nbsp;17e&nbsp;qu\u2019il commence \u00e0 gratter des textes.&nbsp;Il ne&nbsp;rappe&nbsp;pas&nbsp;encore, mais&nbsp;rencontre des artistes comme&nbsp;<strong>guy2bezbar<\/strong>&nbsp;ou encore <strong>Leto<\/strong>.<\/p>\n\n\n\n<h2>Ses d\u00e9buts avec le collectif \u00ab <strong>ultimate&nbsp;boyz<\/strong>&nbsp;\u00bb <\/h2>\n\n\n\n<p>A&nbsp;18 ans, le rappeur n\u2019a plus vraiment d\u2019options dans ses \u00e9tudes et d\u00e9cide de se lancer avec le collectif \u00ab <strong>ultimate&nbsp;boyz<\/strong>&nbsp;\u00bb, un collectif constitu\u00e9 de&nbsp;<strong>Squidji<\/strong>&nbsp;et&nbsp;<strong>Big B<\/strong>, deux rappeurs qui sont \u00e9galement dans l\u2019actualit\u00e9. <\/p>\n\n\n\n<p><a href=\"https:\/\/genius.com\/artists\/Ultimate-boyz\">https:\/\/genius.com\/artists\/Ultimate-boyz<\/a><\/p>\n\n\n\n<p>Le collectif incarne la nouvelle vague de&nbsp;la&nbsp;trap qui arrive en France et ne s\u2019arr\u00eate pas&nbsp;la,&nbsp;niveau productivit\u00e9.&nbsp;\u00c0&nbsp;la m\u00eame&nbsp;p\u00e9riode, <strong>Roshi&nbsp;<\/strong>devient l\u2019\u00e9g\u00e9rie de la marque de&nbsp;streetwear&nbsp;parisienne &#8221; benibla &#8221;&nbsp;.&nbsp;Une marque pour laquelle le collectif va sortir plusieurs freestyles qui vont&nbsp;leurs&nbsp;permettrent&nbsp;de se faire conna\u00eetre&nbsp;par un&nbsp;public plus large, et permettre \u00e0 chacun de devenir plus ind\u00e9pendant.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ultimate Boyzzz - Benibla Freestyle #1 (clip officiel)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/4PiQxuy4wtQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2>Ses premiers pas en solo &#8230;<\/h2>\n\n\n\n<p><strong>Roshi<\/strong>&nbsp;va donc, petit \u00e0 petit se lancer en solo jusqu\u2019\u00e0 se s\u00e9parer totalement de son collectif, et cela lui r\u00e9ussit,&nbsp;avec des s\u00e9ries de freestyles ou&nbsp;morceaux&nbsp;comme sa s\u00e9rie &#8220;<em>#SDD<\/em>&#8221; pour Serpent Deviendra Dragon ou m\u00eame des sons de qualit\u00e9&nbsp;o\u00f9&nbsp;l\u2019on entrevoit d\u00e9j\u00e0 tout son potentiel, dont une petite p\u00e9pite :&nbsp;le son &#8220;<em>Rich<\/em>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Captaine Roshi - Rich\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/LcOH3C4Bcxo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le rappeur fait grimper sa notori\u00e9t\u00e9 petit&nbsp;a&nbsp;petit et devient un des artistes les plus suivis sur&nbsp;soundcloud&nbsp;avec un&nbsp;certain\u2026&nbsp;<strong>Freeze&nbsp;Corleone<\/strong>.<\/p>\n\n\n\n<p>Le natif congolais reste \u00e9gal \u00e0 lui-m\u00eame et parall\u00e8lement \u00e0 la musique, est passionn\u00e9 par le foot et les mangas.&nbsp;Deux passions qui l\u2019accompagnent encore aujourd\u2019hui.&nbsp;D\u2019abord le football, avec \u201ccaptaine\u201d dans son nom d\u2019artiste&nbsp;(\u201cC\u2019est par rapport au foot, mais surtout \u00e0 ma personnalit\u00e9.&nbsp;J\u2019aimais avoir le r\u00f4le de celui qui rel\u00e8ve son \u00e9quipe quand elle est \u00e0 terre, qui fait ressortir les qualit\u00e9s des autres.\u201d)&nbsp;ainsi que de nombreuses r\u00e9f\u00e9rences \u00e0 des joueurs comme&nbsp;Lewandowski.<\/p>\n\n\n\n<p>Le deuxi\u00e8me th\u00e8me dans lequel il a baign\u00e9 quand il \u00e9tait petit est celui des mangas, \u00ab&nbsp;roshi&nbsp;\u00bb vient d\u2019Orochimaru&nbsp;que l\u2019on trouve dans le manga&nbsp;Naruto, un personnage \u00e0 la recherche de la jeunesse \u00e9ternelle.&nbsp;On y retrouve \u00e9galement pas mal de r\u00e9f\u00e9rence dans ses&nbsp;gimmicks, il y attache beaucoup d\u2019importance, car&nbsp;ces derniers, lui&nbsp;permette&nbsp;de fuir une r\u00e9alit\u00e9 parfois dure et morose.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La premi\u00e8re \u00e9mission rap\/manga : Nekketsu, avec Captaine Roshi &amp; Raska\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/isiKpHTotQ8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>D\u00e9but 2019, la carri\u00e8re de&nbsp;<strong>Captaine&nbsp;Roshi<\/strong>&nbsp;fait un grand bond en avant gr\u00e2ce \u00e0 sa signature sur la maison de disques Caroline records.&nbsp;Dans cette m\u00eame fin d\u2019ann\u00e9e sort &#8220;<em>Attaque<\/em>&#8220;, avec&nbsp;des&nbsp;instrus&nbsp;travaill\u00e9es, des flows diff\u00e9rents et les invit\u00e9s&nbsp;(<strong>Key&nbsp;largo,&nbsp;Squidji,&nbsp;Youv&nbsp;dee<\/strong>)&nbsp;qui vont savoir s\u2019\u00e9lever au niveau de celui qu\u2019on surnomme \u00ab&nbsp;Larosh&nbsp;\u00bb.&nbsp;Le projet est un succ\u00e8s critique, on remarque vraiment une identit\u00e9 propre \u00e0&nbsp;<strong>Roshi&nbsp;<\/strong>avec une voix rauque et des&nbsp;prods&nbsp;faites par ses potes.&nbsp;Ceux qui rajoutent encore un peu plus d\u2019originalit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Captaine Roshi - Attaque (Feat Key Largo) [CLIP OFFICIEL]\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/mVoWFAJYitg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2>2020&nbsp;: une ann\u00e9e de quantit\u00e9 et de qualit\u00e9 pour l\u2019artiste<\/h2>\n\n\n\n<p>L\u2019ann\u00e9e 2020, est, une ann\u00e9e, fructueuse pour lui avec pas moins de 3 mixtape\/EP sorti.<\/p>\n\n\n\n<p>L\u2019artiste remet le couvert avec &#8220;<em>Contre-Attaque<\/em>&#8220;, la r\u00e9\u00e9dition et suite logique d\u2019 &#8220;<em>Attaque<\/em>&#8220;.&nbsp;Celle-ci est compos\u00e9e de 5&nbsp;tracks&nbsp;dont un&nbsp;featuring&nbsp;de&nbsp;<strong>Kaf\u00e9<\/strong>.<\/p>\n\n\n\n<p>Puis le projet&nbsp;&#8220;<em>W.A.R<\/em>&#8221;&nbsp;sort, avec des sons percutants et techniques, un EP qui change des pr\u00e9c\u00e9dents, en derni\u00e8re place et apr\u00e8s 8 morceaux de trap&nbsp;pure, l\u2019artiste s\u2019ouvre dans l\u2019introspectif&nbsp;<em>Journal de Bord<\/em>&#8220;.&nbsp;Sur ce&nbsp;titre, on&nbsp;retrouve certaines r\u00e9f\u00e9rences aux \u00e9checs que l\u2019artiste a d\u00fb endurer au cours de sa vie, l\u2019instrumentale est plus douce et la voix rauque de&nbsp;<strong>Roshi<\/strong>&nbsp;ressort avec des paroles o\u00f9 le rappeur se confie pour la premi\u00e8re fois, et c\u2019est une r\u00e9ussite, le son \u00e9tant&nbsp;\u00e0&nbsp;ce jour son morceau le plus \u00e9cout\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Captaine Roshi - Journal De Bord\/Guapene (CLIP OFFICIEL)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/OsJoXcUJCaQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Sur sa lanc\u00e9e, le Parisien sort &#8220;<em>Attaque II<\/em>&#8220;.&nbsp;Avec, sur cette&nbsp;mixtape&nbsp;des gros&nbsp;featurings&nbsp;(<strong>PLK<\/strong>,<strong>&nbsp;Gradur<\/strong>, <strong>Alpha&nbsp;Wann<\/strong>), et des morceaux plus vari\u00e9s qui s\u2019\u00e9loigne de&nbsp;la&nbsp;trap que l\u2019artiste r\u00e9ussit parfaitement.&nbsp;Plus&nbsp;mainstream&nbsp;que les pr\u00e9c\u00e9dents, il enregistrera 1262 ventes en premi\u00e8re semaine sans aucun exemplaire physique, le faisant ainsi rentrer dans la cour des grands.&nbsp;Au-del\u00e0, d\u2019un style plus vari\u00e9, on remarque vraiment un changement dans les visuels chez l&#8217;artiste avec un freestyle colors : &#8220;Pigalle&#8221; et des clips recherch\u00e9s :<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Captaine Roshi - Molotov [CLIP OFFICIEL]\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/-w_L661ft1E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le projet sera salu\u00e9 autant par le public que par la presse sp\u00e9cialis\u00e9e.<\/p>\n\n\n\n<h2>2021 : une confirmation et encore de belles perspectives d\u2019avenir<\/h2>\n\n\n\n<p>La suite on la&nbsp;conna\u00eet,&nbsp;ROAD&nbsp;TO&nbsp;LAROSH&nbsp;sort.&nbsp;Avec des&nbsp;sons trap, comme le morceau &#8220;les fous&#8221;, des&nbsp;feats&nbsp;avec des rappeurs qui \u00e9mergent au grand public comme<strong> Wit.<\/strong>&nbsp;ou<strong>&nbsp;La&nbsp;f\u00e8ve<\/strong>.&nbsp;Mais aussi des morceaux calmes comme sur l\u2019intro&nbsp;&#8220;<em>am\u00e8re<\/em>&#8220;, ou la track 9 &#8220;<em>pas comme hier<\/em>&#8221; sur lesquelles il excelle.&nbsp;Sur l\u2019interlude&nbsp;parl\u00e9&nbsp;et sur l\u2019outro&nbsp;&#8220;<em>nouveau voyage<\/em>&#8221;  il \u00e9voque clairement que&nbsp;c\u2019est&nbsp;son dernier EP&nbsp;avant l\u2019album.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nouveau voyage\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/VXKVjlxRjGU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>On voit donc toute la coh\u00e9rence dans ces projets qui tel un voyage accompagn\u00e9 de plusieurs escales apportent chacun leur pierre \u00e0 l\u2019\u00e9difice que sera l\u2019album.<\/p>\n\n\n\n<p>Enjoy&nbsp;&amp;&nbsp;Stay&nbsp;Tuned&nbsp;<\/p>\n\n\n\n<p>Antoine Fouassier<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 28 octobre 2021 sortait\u00a0l\u2019EP\u00a0:\u00a0ROAD\u00a0TO\u00a0LAROSH, plein de coh\u00e9rence, il fait suite \u00e0 ces quatre derni\u00e8res<br \/>\n r\u00e9alisations\u00a0(&#8220;attaque&#8221;, &#8220;contre-attaque&#8221;,\u00a0&#8220;W.A.R&#8221;\u00a0et &#8220;attaque II&#8221;).\u00a0Avec ce\u00a0projet, le\u00a0rappeur de Pigalle impose son style, sa voix et ses visuels dans le paysage du rap\u00a0Fran\u00e7ais.\u00a0Revenons donc sur son \u00e9volution, de ses d\u00e9buts jusqu\u2019aux portes de &#8220;LAROSH&#8221; en r\u00e9f\u00e9rence \u00e0 son premier album qui sortira prochainement et qu\u2019il pr\u00e9pare depuis longtemps.<\/p>\n","protected":false},"author":2,"featured_media":12508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[1304,1306,1302,1305,914,319,1283,41,1308,1303,876,1307,1301],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Captaine Roshi: De serpent \u00e0 dragon - Start It<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Captaine Roshi: De serpent \u00e0 dragon - Start It\" \/>\n<meta property=\"og:description\" content=\"Le 28 octobre 2021 sortait\u00a0l\u2019EP\u00a0:\u00a0ROAD\u00a0TO\u00a0LAROSH, plein de coh\u00e9rence, il fait suite \u00e0 ces quatre derni\u00e8res  r\u00e9alisations\u00a0(&quot;attaque&quot;, &quot;contre-attaque&quot;,\u00a0&quot;W.A.R&quot;\u00a0et &quot;attaque II&quot;).\u00a0Avec ce\u00a0projet, le\u00a0rappeur de Pigalle impose son style, sa voix et ses visuels dans le paysage du rap\u00a0Fran\u00e7ais.\u00a0Revenons donc sur son \u00e9volution, de ses d\u00e9buts jusqu\u2019aux portes de &quot;LAROSH&quot; en r\u00e9f\u00e9rence \u00e0 son premier album qui sortira prochainement et qu\u2019il pr\u00e9pare depuis longtemps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-04T12:13:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T18:06:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png\",\"contentUrl\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png\",\"width\":443,\"height\":443},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/\",\"name\":\"Captaine Roshi: De serpent \u00e0 dragon - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#primaryimage\"},\"datePublished\":\"2021-12-04T12:13:33+00:00\",\"dateModified\":\"2022-01-19T18:06:28+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Captaine Roshi: De serpent \u00e0 dragon\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"https:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Captaine Roshi: De serpent \u00e0 dragon - Start It","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/","og_locale":"fr_FR","og_type":"article","og_title":"Captaine Roshi: De serpent \u00e0 dragon - Start It","og_description":"Le 28 octobre 2021 sortait\u00a0l\u2019EP\u00a0:\u00a0ROAD\u00a0TO\u00a0LAROSH, plein de coh\u00e9rence, il fait suite \u00e0 ces quatre derni\u00e8res  r\u00e9alisations\u00a0(\"attaque\", \"contre-attaque\",\u00a0\"W.A.R\"\u00a0et \"attaque II\").\u00a0Avec ce\u00a0projet, le\u00a0rappeur de Pigalle impose son style, sa voix et ses visuels dans le paysage du rap\u00a0Fran\u00e7ais.\u00a0Revenons donc sur son \u00e9volution, de ses d\u00e9buts jusqu\u2019aux portes de \"LAROSH\" en r\u00e9f\u00e9rence \u00e0 son premier album qui sortira prochainement et qu\u2019il pr\u00e9pare depuis longtemps.","og_url":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2021-12-04T12:13:33+00:00","article_modified_time":"2022-01-19T18:06:28+00:00","og_image":[{"width":443,"height":443,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png","contentUrl":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/12\/72c43a6b871293d5bc702fd0bab68fa6.443x443x1-1.png","width":443,"height":443},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/","name":"Captaine Roshi: De serpent \u00e0 dragon - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#primaryimage"},"datePublished":"2021-12-04T12:13:33+00:00","dateModified":"2022-01-19T18:06:28+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2021\/12\/04\/captaine-roshi-de-serpent-a-dragon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Captaine Roshi: De serpent \u00e0 dragon"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"https:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12500"}],"collection":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=12500"}],"version-history":[{"count":10,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12500\/revisions"}],"predecessor-version":[{"id":12787,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/12500\/revisions\/12787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/12508"}],"wp:attachment":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=12500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=12500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=12500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}