{"id":13721,"date":"2022-11-11T11:15:09","date_gmt":"2022-11-11T10:15:09","guid":{"rendered":"http:\/\/startitkbs.org\/?p=13721"},"modified":"2022-11-14T13:26:42","modified_gmt":"2022-11-14T12:26:42","slug":"retour-sur-un-classique-suis-je-le-gardien-de-mon-frere","status":"publish","type":"post","link":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/","title":{"rendered":"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ?"},"content":{"rendered":"\n<p>D<em>epuis son arriv\u00e9e dans les ann\u00e9es 90, le rap en France s\u2019est d\u00e9velopp\u00e9 et devient de plus en plus pr\u00e9sent dans nos quotidiens.&nbsp;Apr\u00e8s les origines d\u2019une musique se voulant d\u00e9tendue et entrainante, le rap ressort, au fil des ann\u00e9es un c\u00f4t\u00e9 anti-social et d\u00e9nonciateur.&nbsp;Avec l\u2019ampleur que cela va prendre, son influence va grandir et permettre \u00e0 certains rappeurs de rester dans les m\u00e9moires \u00e9voquant toutes sortes de th\u00e8mes parfois peu abord\u00e9s dans les m\u00e9dias ou \u00e0 l\u2019\u00e9cole.&nbsp;De nombreux jeunes se reconna\u00eetront ainsi dans une certaine r\u00e9bellion face \u00e0 l\u2019ordre \u00e9tabli.<\/em><\/p>\n\n\n\n<h2>Contexte et origines<\/h2>\n\n\n\n<p>Insouciants mais r\u00e9alistes, de nombreux rappeurs vont faire leurs places au d\u00e9but des ann\u00e9es 2000.\u00a0<strong>Booba<\/strong>,\u00a0<strong>Rohff<\/strong>,\u00a0<strong>Salif<\/strong>,\u00a0<strong>Nessbeal\u00a0<\/strong>en font partie et vont se faire un nom pour devenir les t\u00eates d\u2019affiche de cette culture\u00a0\u00e9mergeant\u00a0au grand public.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Salif | Black Skin (Clip officiel) | Album : Prolongations\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/1saKm4wz23I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Parmi eux,&nbsp;<strong>Sefyu<\/strong>, et c\u2019est avec un classique de sa discographie que nous allons le d\u00e9couvrir \u00e0 travers cette chronique.<\/p>\n\n\n\n<p><strong>Sefyu<\/strong>, de son vrai nom Youssef&nbsp;Soukouna&nbsp;est un rappeur fran\u00e7ais d\u2019origine s\u00e9n\u00e9galaise.<\/p>\n\n\n\n<p>Personnage \u00e0 l\u2019histoire atypique, il se lance d\u2019abord dans une carri\u00e8re de footballeur, o\u00f9 il recevra des offres de grands clubs et notamment Arsenal.&nbsp;Suite \u00e0 des blessures, il mettra fin \u00e0 sa carri\u00e8re de footballeur et au d\u00e9but des ann\u00e9es 2000 se lancera dans le rap \u00e0 100 %.&nbsp;Ce n\u2019est qu\u2019en 2005 avec son CD Molotov 4 et en 2006 avec son premier album \u00ab qui suis-je \u00bb que le rappeur d\u2019Aulnay&nbsp;sous-bois va faire sa place dans le milieu ferm\u00e9 du rap.&nbsp;Fort de certains sons comme \u00ab noir et blanc \u00bb ou \u00ab&nbsp;senegalo&nbsp;ruskov&nbsp;\u00bb, le public attend beaucoup de son prochain projet qui se veut \u00eatre comme l\u2019album de la confirmation.<\/p>\n\n\n\n<h2>L&#8217;album<\/h2>\n\n\n\n<p>Ainsi, c\u2019est en 2008, apr\u00e8s deux ans d\u2019attente, que sort l\u2019album <em>Suis-je le gardien de Mon Fr\u00e8re ?<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"500\" height=\"500\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/artworks-s5P77pffeEC7-0-t500x500.jpg\" alt=\"\" class=\"wp-image-13724\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/artworks-s5P77pffeEC7-0-t500x500.jpg 500w, https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/artworks-s5P77pffeEC7-0-t500x500-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/artworks-s5P77pffeEC7-0-t500x500-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption>Cover du projet<\/figcaption><\/figure>\n\n\n\n<p>Morceau apr\u00e8s morceau, nous verrons comment&nbsp;<strong>Sefyu&nbsp;<\/strong>a construit de mani\u00e8re coh\u00e9rente et frappante un album qui reste dans les m\u00e9moires.<\/p>\n\n\n\n<p>D\u00e8s l\u2019intro&nbsp;nous sommes fix\u00e9s, la&nbsp;prod&nbsp;et les th\u00e8mes abord\u00e9s sont forts et imposent d\u2019embl\u00e9e une tension qui ne redescendra jamais vraiment.<\/p>\n\n\n\n<p>La deuxi\u00e8me track de l\u2019album r\u00e9pond directement \u00e0 la question du titre du projet, un titre qui parlera \u00e0 beaucoup de frangins, racontant l\u2019histoire d\u2019un petit fr\u00e8re qui veut imiter le vice et les prises de risques d\u00e9mesur\u00e9es de son grand fr\u00e8re.&nbsp;Le morceau rappelle \u00e0 la responsabilit\u00e9 de ce dernier et pose une question pertinente sur l\u2019influence envers les jeunes personnes.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"SEFYU - Suis-je le gardien de mon fr\u00e8re ?\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/iYEIw7F9es8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le son le plus connu du projet reste le 3\u00e8me&nbsp;morceau <em>molotov4<\/em> &#8216;&nbsp;qui a marqu\u00e9 les g\u00e9n\u00e9rations et dont les&nbsp;gimmicks&nbsp;r\u00e9sonnent encore chez les auditeurs de rap.&nbsp;Un morceau \u00e9nergique qui figure dans toutes les playlists de pousseurs de fonte.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"SEFYU - Molotov 4\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/Nzt7puchldA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>V\u00e9ritable ambassadeur du&nbsp;93, le&nbsp;featuring avec&nbsp;<strong>JoeyStar <\/strong><em>Seine&nbsp;Saint-Denis&nbsp;Style&nbsp;: Nouvelle&nbsp;Serie<\/em> &#8216; un morceau&nbsp;egotrip&nbsp;en forme de passation de pouvoir.<\/p>\n\n\n\n<p>Dans la continuit\u00e9 de l&#8217;album, le c\u00f4t\u00e9 hardcore et&nbsp;egotrip&nbsp;de <strong>Sefyu&nbsp;<\/strong>laisse de plus en plus de places \u00e0 d\u2019autres sujets.&nbsp;Il a le m\u00e9rite d\u2019apporter une vraie diversit\u00e9 dans les th\u00e8mes abord\u00e9s.<\/p>\n\n\n\n<p>Cru et souvent accompagn\u00e9 de bruitages et d\u2019effets sonores de la vie quotidienne, ajoutant du r\u00e9alisme et permettant de se plonger dans les sons.<\/p>\n\n\n\n<p>Avec la p\u00e9dophilie et la maltraitance dans <em>sac de bonbons<\/em> &#8216;, la cupidit\u00e9 et l\u2019ambition dans <em>Plus<\/em> &#8216;, ou encore l\u2019int\u00e9gration et l\u2019immigration post -45 dans <em>3\u00e8me Guerre<\/em>&nbsp;&#8216;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sefyu - 3\u00e8me Guerre\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/eVp_kARGQ18?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>R\u00e9aliste et brutal, l\u2019album est accompagn\u00e9 de plusieurs feats charg\u00e9s de nitroglyc\u00e9rine, rappelant une image de mafia d\u2019Europe de l\u2019Est dont le rappeur joue avec les morceaux<em> faits divers 2<\/em> &#8216; et<em> haute science<\/em> &#8216;. Les collaborations avec <strong>RR, Baba<\/strong> et <strong>ST4 <\/strong>dont l&#8217;alchimie ne fait aucun doute, apportent une vraie diversit\u00e9 par leurs voix et leur style singulier.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"599\" height=\"403\" src=\"http:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/2648096908_small_5.jpg\" alt=\"\" class=\"wp-image-13725\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/2648096908_small_5.jpg 599w, https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/2648096908_small_5-300x202.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><figcaption>Sefyu, Baba, RR apr\u00e8s la sortie de l&#8217;album<\/figcaption><\/figure>\n\n\n\n<p>Tous les autres morceaux se fondent parfaitement dans l\u2019ambiance de l\u2019album, m\u00eame si certains souffrent d\u2019un peu trop de r\u00e9p\u00e9titions et manquent de coh\u00e9rence.<\/p>\n\n\n\n<p>L\u2019outro&nbsp;<em>Zero&nbsp;<\/em>&#8216; prolonge le plaisir de l\u2019audition et, comme un symbole, nous encourage a r\u00e9it\u00e9rer l\u2019\u00e9coute.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sefyu - Zero\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/-J3ZwPW_e2Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2>Post\u00e9rit\u00e9<\/h2>\n\n\n\n<p>Un Album de qualit\u00e9 qui a bien vieilli et dont les sujets s\u00e9rieux auxquels il s\u2019est attaqu\u00e9 restent toujours d\u2019actualit\u00e9.&nbsp;Une habilit\u00e9&nbsp;lyricale&nbsp;et une&nbsp;ma\u00eetrise&nbsp;de la technique vocale ajoutent d&#8217;autant plus de valeur \u00e0 ce disque, qui a bient\u00f4t 15 ans !<\/p>\n\n\n\n<p>M\u00eame si la carri\u00e8re de&nbsp;<strong>Sefyu&nbsp;<\/strong>va petit&nbsp;\u00e0&nbsp;petit s\u2019estomper et que ses albums vont&nbsp;para\u00eetre&nbsp;un peu underground pour les nouvelles g\u00e9n\u00e9rations d\u2019auditeurs de rap, l\u2019album a inspir\u00e9 de nombreux rappeurs comme <strong>Sofiane<\/strong>,&nbsp;<strong>Vald<\/strong>,&nbsp;<strong>SCH <\/strong>et bien d\u2019autres.&nbsp;Le contexte, la qualit\u00e9 et l&#8217;h\u00e9ritage d\u2019un album ne sont-ils pas la preuve qu\u2019il figure parmi les classiques de son art?\u2026<\/p>\n\n\n\n<p>Enjoy &amp; Stay Tuned<\/p>\n\n\n\n<p>Antoine Fouassier<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s les origines d\u2019une musique se voulant d\u00e9tendue et entrainante, le rap ressort, au fil des ann\u00e9es un c\u00f4t\u00e9 anti-social et d\u00e9nonciateur.\u00a0Avec l\u2019ampleur que cela va prendre, son influence va grandir et permettre \u00e0 certains rappeurs de rester dans les m\u00e9moires. Insouciants mais r\u00e9alistes, Ils feront leurs places au d\u00e9but des ann\u00e9es 2000.\u00a0<br \/>\nParmi eux,\u00a0Sefyu, et c\u2019est avec un classique de sa discographie que nous allons le d\u00e9couvrir \u00e0 travers cette chronique.<\/p>\n","protected":false},"author":2,"featured_media":13723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":""},"categories":[840],"tags":[1629,363,1632,41,58,1628,1630,1627,1631],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s les origines d\u2019une musique se voulant d\u00e9tendue et entrainante, le rap ressort, au fil des ann\u00e9es un c\u00f4t\u00e9 anti-social et d\u00e9nonciateur.\u00a0Avec l\u2019ampleur que cela va prendre, son influence va grandir et permettre \u00e0 certains rappeurs de rester dans les m\u00e9moires. Insouciants mais r\u00e9alistes, Ils feront leurs places au d\u00e9but des ann\u00e9es 2000.\u00a0 Parmi eux,\u00a0Sefyu, et c\u2019est avec un classique de sa discographie que nous allons le d\u00e9couvrir \u00e0 travers cette chronique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-11T10:15:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-14T12:26:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"366\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Start It\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg\",\"contentUrl\":\"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg\",\"width\":366,\"height\":280},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/\",\"name\":\"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#primaryimage\"},\"datePublished\":\"2022-11-11T10:15:09+00:00\",\"dateModified\":\"2022-11-14T12:26:42+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\"},\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ?\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7\",\"name\":\"Start It\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g\",\"caption\":\"Start It\"},\"sameAs\":[\"http:\/\/startitkbs.org\/\",\"https:\/\/www.instagram.com\/startit_asso\/\"],\"url\":\"https:\/\/startitkbs.org\/index.php\/author\/start-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/","og_locale":"fr_FR","og_type":"article","og_title":"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It","og_description":"Apr\u00e8s les origines d\u2019une musique se voulant d\u00e9tendue et entrainante, le rap ressort, au fil des ann\u00e9es un c\u00f4t\u00e9 anti-social et d\u00e9nonciateur.\u00a0Avec l\u2019ampleur que cela va prendre, son influence va grandir et permettre \u00e0 certains rappeurs de rester dans les m\u00e9moires. Insouciants mais r\u00e9alistes, Ils feront leurs places au d\u00e9but des ann\u00e9es 2000.\u00a0 Parmi eux,\u00a0Sefyu, et c\u2019est avec un classique de sa discographie que nous allons le d\u00e9couvrir \u00e0 travers cette chronique.","og_url":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2022-11-11T10:15:09+00:00","article_modified_time":"2022-11-14T12:26:42+00:00","og_image":[{"width":366,"height":280,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Start It","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg","contentUrl":"https:\/\/startitkbs.org\/wp-content\/uploads\/2022\/11\/Sefyu-nantes1.jpg","width":366,"height":280},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/","name":"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ? - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#primaryimage"},"datePublished":"2022-11-11T10:15:09+00:00","dateModified":"2022-11-14T12:26:42+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7"},"breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2022\/11\/11\/retour-sur-un-classique-suis-je-le-gardien-de-mon-frere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Retour sur un classique : Suis-je le gardien de Mon Fr\u00e8re ?"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/e6547bfb2f056b56d41e21a1d4991de7","name":"Start It","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11862acbc548da566658503207ce57f4?s=96&d=mm&r=g","caption":"Start It"},"sameAs":["http:\/\/startitkbs.org\/","https:\/\/www.instagram.com\/startit_asso\/"],"url":"https:\/\/startitkbs.org\/index.php\/author\/start-it\/"}]}},"_links":{"self":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/13721"}],"collection":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=13721"}],"version-history":[{"count":6,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/13721\/revisions"}],"predecessor-version":[{"id":13743,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/13721\/revisions\/13743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/13723"}],"wp:attachment":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=13721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=13721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=13721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}