{"id":9019,"date":"2021-01-15T16:16:35","date_gmt":"2021-01-15T15:16:35","guid":{"rendered":"http:\/\/startitkbs.org\/?p=9019"},"modified":"2021-02-17T18:01:14","modified_gmt":"2021-02-17T17:01:14","slug":"retour-sur-nos-albums-preferes-de-2020","status":"publish","type":"post","link":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/","title":{"rendered":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9019\" class=\"elementor elementor-9019\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13d12e8 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"13d12e8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c2c2ea\" data-id=\"6c2c2ea\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8025712 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8025712\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73ec140\" data-id=\"73ec140\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4d2703 elementor-widget elementor-widget-heading\" data-id=\"a4d2703\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e 2020<\/b><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f121b09\" data-id=\"f121b09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bebbe41 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bebbe41\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:46}},&quot;motion_fx_blur_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6441485\" data-id=\"6441485\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbbf5c4 elementor-widget elementor-widget-image\" data-id=\"fbbf5c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_-1024x1024.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/91UYn-YKMgL._SL1500_.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a492af6\" data-id=\"a492af6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16a7f99 elementor-widget elementor-widget-image\" data-id=\"16a7f99\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-1024x1024.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-f799cf6\" data-id=\"f799cf6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eea38fc elementor-widget elementor-widget-image\" data-id=\"eea38fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-1024x1024.jpg 1024w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen.jpg 1218w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e10ee21\" data-id=\"e10ee21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acba1c0 elementor-widget elementor-widget-image\" data-id=\"acba1c0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a75d1f1\" data-id=\"a75d1f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e665842 elementor-widget elementor-widget-image\" data-id=\"e665842\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"969\" height=\"969\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-kings-disease-album.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-kings-disease-album.jpg 969w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-kings-disease-album-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-kings-disease-album-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-kings-disease-album-768x768.jpg 768w\" sizes=\"(max-width: 969px) 100vw, 969px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-4f69e92\" data-id=\"4f69e92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4294ef9 elementor-widget elementor-widget-image\" data-id=\"4294ef9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"599\" height=\"589\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/R-14629899-1578509580-6853.jpeg.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/R-14629899-1578509580-6853.jpeg.jpg 599w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/R-14629899-1578509580-6853.jpeg-300x295.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c635246 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c635246\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e88a300\" data-id=\"e88a300\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f86634 elementor-widget elementor-widget-spacer\" data-id=\"2f86634\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-922752d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"922752d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ecd651\" data-id=\"7ecd651\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20d4e37 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"20d4e37\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40ff3c0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40ff3c0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c429eb0\" data-id=\"c429eb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5704f26\" data-id=\"5704f26\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b22072e elementor-widget elementor-widget-heading\" data-id=\"b22072e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">En ce d\u00e9but d'ann\u00e9e 2021, Start It va te faire d\u00e9couvrir les albums qui ont le plus marqu\u00e9 notre ann\u00e9e 2020. Une ann\u00e9e qui a pourtant \u00e9t\u00e9 un peu sp\u00e9ciale et nous a tous plus ou moins touch\u00e9s mais qui, musicalement, a su nous g\u00e2ter.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecc9c1c\" data-id=\"ecc9c1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae6c947 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae6c947\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d78c3c\" data-id=\"3d78c3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52c011e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52c011e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5f71c6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5f71c6\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-622158a\" data-id=\"622158a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2878d30 elementor-widget elementor-widget-spacer\" data-id=\"2878d30\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10d59206 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10d59206\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a717681\" data-id=\"a717681\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20191884 elementor-widget elementor-widget-image\" data-id=\"20191884\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:6,&quot;end&quot;:94}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1218\" height=\"1218\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2.jpg 1218w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2-1024x1024.jpg 1024w\" sizes=\"(max-width: 1218px) 100vw, 1218px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fc8150e\" data-id=\"1fc8150e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3fa4a0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4f3fa4a0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6589b70b elementor-widget elementor-widget-text-editor\" data-id=\"6589b70b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Dix ans apr\u00e8s la sortie de <i>Man On the Moon II<\/i>, <b>Kid Cudi<\/b> surprend ses fans en cette fin d\u2019ann\u00e9e 2020 avec la sortie de <i>Man On The Moon III : The Chosen<\/i>. Cet \u00e9t\u00e9, l\u2019artiste avait laiss\u00e9 supposer la sortie de ce troisi\u00e8me volet dans son feat avec <b>Eminem<\/b>\u00a0&#8220;<i style=\"letter-spacing: 1.4px;\">The Adventures of the Moon Man <\/i><span style=\"letter-spacing: 1.4px;\">&amp;<\/span><i style=\"letter-spacing: 1.4px;\"> Slim Shady&#8221;<\/i><span style=\"letter-spacing: 1.4px;\">\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">dans lequel il annonce &#8220;<\/span><i style=\"letter-spacing: 1.4px;\">The trilogy continues&#8221;<\/i><span style=\"letter-spacing: 1.4px;\">. Dans cet album, le rappeur r\u00e9gale sa communaut\u00e9 avec 18 titres parmi lesquels nous retrouvons <\/span><b style=\"letter-spacing: 1.4px;\">Pop Smoke<\/b><span style=\"letter-spacing: 1.4px;\">, <\/span><b style=\"letter-spacing: 1.4px;\">Skepta<\/b><span style=\"letter-spacing: 1.4px;\"> ou encore <\/span><b style=\"letter-spacing: 1.4px;\">Trippie<\/b> <b style=\"letter-spacing: 1.4px;\">Redd<\/b><span style=\"letter-spacing: 1.4px;\"> qui\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">ont,\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">eux aussi marqu\u00e9 le rap game en 2020. Plus pr\u00e9cis\u00e9ment, l\u2019album est compos\u00e9 de 4 actes dans lesquels\u00a0<\/span><b style=\"letter-spacing: 1.4px;\">Kid<\/b> <b style=\"letter-spacing: 1.4px;\">Cudi<\/b><span style=\"letter-spacing: 1.4px;\"> manie avec talent diff\u00e9rents genres musicaux tels que la pop, le rap ou la trap. Fid\u00e8le \u00e0 lui-m\u00eame dans cet album, nous pouvons reconna\u00eetre cette \u00e9nergie toute particuli\u00e8re de l\u2019artiste avec son style quelque peu mystique et lunaire. Comme toujours, <\/span><b style=\"letter-spacing: 1.4px;\">Kid<\/b> <b style=\"letter-spacing: 1.4px;\">Cudi<\/b><span style=\"letter-spacing: 1.4px;\"> utilise la musique comme th\u00e9rapie afin de se lib\u00e9rer de ses d\u00e9mons et de ses pens\u00e9es obscures. Cependant, l\u2019album se cl\u00f4ture sur une note positive avec le titre &#8220;<\/span><i style=\"letter-spacing: 1.4px;\">Lord I Know&#8221;<\/i><span style=\"letter-spacing: 1.4px;\">\u00a0dans lequel l\u2019artiste semble rena\u00eetre de ses cendres et avoir retrouv\u00e9 le go\u00fbt de vivre comme l\u2019indiquent les paroles suivantes &#8220;<\/span><i style=\"letter-spacing: 1.4px;\">Every day\u2019s a blessing&#8221;<\/i><span style=\"letter-spacing: 1.4px;\">. Si habituellement vous aimez l\u2019univers de <\/span><b style=\"letter-spacing: 1.4px;\">Kid<\/b> <b style=\"letter-spacing: 1.4px;\">Cudi<\/b><span style=\"letter-spacing: 1.4px;\">, vous ne serez pas d\u00e9\u00e7us par son dernier album, et si vous souhaitez voyager sur la lune le temps d\u2019une heure, ce projet est \u00e9galement fait pour vous.<\/span><\/p><p>M\u00e9lissa<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51483d80 elementor-widget elementor-widget-heading\" data-id=\"51483d80\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kid Cudi<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2272a4bb elementor-widget elementor-widget-heading\" data-id=\"2272a4bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>man on the moon iii : the chosen<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14b9e00 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14b9e00\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3dcdf635\" data-id=\"3dcdf635\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-255c7882 elementor-widget elementor-widget-image\" data-id=\"255c7882\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8.9,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album.png 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album-150x150.png 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album-300x300.png 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album-768x768.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8edceda\" data-id=\"8edceda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55a2d912 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"55a2d912\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5621b1ae elementor-widget elementor-widget-text-editor\" data-id=\"5621b1ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Impossible de ne pas \u00e9voquer l\u2019album qui cl\u00f4ture le mieux l\u2019ann\u00e9e 2020, ne serait-ce que par l\u2019attente qu\u2019il a suscit\u00e9e.\u00a0<strong>Playboi Carti<\/strong> nous livre enfin, le 25 d\u00e9cembre 2020, <i>Whole Lotta Red<\/i>. Un album longuement teas\u00e9 sur les r\u00e9seaux sociaux et grandement attendu par les fans, qui, apr\u00e8s la sortie du single &#8220;<em>@ Meh&#8221;<\/em>\u00a0en avril dernier, avaient retrouv\u00e9 espoir de voir un jour l\u2019album sortir. <strong>Kanye West<\/strong> comme co-producteur, <strong>Kid Cudi<\/strong> et <strong>Future<\/strong> en featurings : <strong>Playboi Carti<\/strong> s\u2019est entour\u00e9 des plus grands pour enfin boucler son deuxi\u00e8me album studio. Bien que <i>WLR<\/i> ne fasse pas l\u2019unanimit\u00e9, il est difficile de s\u2019\u00e9tonner des allures punk, vampirique, rien qu\u2019\u00e0 en voir la couverture et le titre &#8220;<em>Vamp Anthem&#8221;<\/em>, et exp\u00e9rimentale de l\u2019album lorsqu\u2019on suit de pr\u00e8s le personnage de <strong>Playboi Carti<\/strong>. L\u2019artiste fait une proposition musicale diff\u00e9rente, surprenante pour les fans car probablement consid\u00e9r\u00e9e comme trop \u00e9loign\u00e9e de celle pr\u00e9sent\u00e9e dans son pr\u00e9c\u00e9dent album, <i>Die Lit<\/i>, sorti en 2018. Mais<strong> Carti<\/strong> a pens\u00e9 aux plus nostalgiques, en pla\u00e7ant des titres comme &#8220;<em>New N3on&#8221;<\/em>, produit par <strong>Maaly Raw<\/strong>, ou encore &#8220;<em>Place&#8221;<\/em>, avec cette fois <strong>Pi\u2019erre Bourne<\/strong> \u00e0 la prod, de quoi rassurer en prouvant que le Old<strong> Carti<\/strong> n\u2019a pas totalement disparu, mais ne se cantonne pas \u00e0 ce qu\u2019il ma\u00eetrise d\u00e9j\u00e0. <strong>Playboi Carti<\/strong> est d\u00e9finitivement l\u2019outsider, que peut-\u00eatre seuls quelques auditeurs comprendront, mais qu\u2019il ne faudrait surtout pas condamner pour ne pas \u00eatre rest\u00e9 dans sa zone de confort. Le meilleur conseil pour l\u2019\u00e9couter : se d\u00e9faire de tout a priori sur <strong>Playboi Carti<\/strong>. Il est important de se souvenir qu\u2019initialement, un artiste cr\u00e9\u00e9 un album en prenant la direction qui lui ressemble, et non pas celle que le public attend qu\u2019il prenne. Bon ou mauvais, <i>Whole Lotta Red<\/i> peut au moins se targuer d\u2019avoir \u00e9t\u00e9 l\u2019un des drops d\u2019album les plus attendus de l\u2019ann\u00e9e 2020, et l\u2019artiste semble laisser sous-entendre qu\u2019une version deluxe de l\u2019album sera \u00e9dit\u00e9e par la suite.<\/p><p>Mathilde<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308fb6f1 elementor-widget elementor-widget-heading\" data-id=\"308fb6f1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Playboi Carti<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d41f1 elementor-widget elementor-widget-heading\" data-id=\"a8d41f1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Whole lotta red<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73cf3312 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73cf3312\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54546ac8\" data-id=\"54546ac8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6258ca05 elementor-widget elementor-widget-image\" data-id=\"6258ca05\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:3,&quot;end&quot;:97}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1200\" height=\"1179\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover.jpg 1200w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover-300x295.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover-768x755.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover-1024x1006.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cf3f7e1\" data-id=\"2cf3f7e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-774afff8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"774afff8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72014ca6 elementor-widget elementor-widget-text-editor\" data-id=\"72014ca6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>AIROD<\/strong> entame 2020 avec un album incroyablement intense. Ce talent techno \u00e9mergent a annonc\u00e9 son premier album <em>Burn<\/em> <em>Injury<\/em> en Janvier 2020 avec le label fran\u00e7ais <strong>Molek\u00fcl<\/strong>. Si vous avez suivi le c\u00f4t\u00e9 plus underground de la techno, vous avez s\u00fbrement entendu sa musique ou vu son nom sur des gros line-ups. C&#8217;est non seulement son premier album, mais aussi le premier album \u00e0 \u00eatre publi\u00e9 sous sa marque. Avec le soutien <strong>d&#8217;Amelie<\/strong> <strong>Lens<\/strong>, <strong>Perc<\/strong>, <strong>Dax J<\/strong> et bien d&#8217;autres, son album arrive \u00e0 point nomm\u00e9. Adoub\u00e9 par des grandes pointures, les tracks de cet album ont \u00e9t\u00e9 jou\u00e9es d&#8217;innombrables fois dans des livestreams cette ann\u00e9e et seront repris dans les clubs et les soir\u00e9es \u00e0 coup s\u00fbr. Originaire de Paris, <strong>Dario<\/strong> <strong>Brkic<\/strong> aka <strong>AIROD<\/strong> fait partie des fers de lance de la nouvelle g\u00e9n\u00e9ration techno fran\u00e7aise. Il a forg\u00e9 sa propre ligne de techno, \u00e0 la fois sombre, muscl\u00e9e et inlassablement corrosive. L&#8217;album est une sorte d&#8217;introspection dans la vie d&#8217;un homme. Avec une atmosph\u00e8re sombre et m\u00e9lancolique, chaque morceau refl\u00e8te une \u00e9tape importante dans l&#8217;\u00e9volution d&#8217;une personne et symbolise diff\u00e9rents processus de la vie tels que l&#8217;apprentissage, la d\u00e9ception, le p\u00e9ch\u00e9. L&#8217;atmosph\u00e8re de l&#8217;album est assez noire, on y retrouve le son des flammes ou des voix froides. &#8220;<em>He<\/em> <em>Tried<\/em> <em>To<\/em> <em>Survive<\/em>&#8221; d\u00e9marre avec un morceau pi\u00e8ge nostalgique aux sonorit\u00e9s douces et aux leads obs\u00e9dants avant que &#8220;<em>Cant<\/em> <em>Fuck<\/em> <em>With<\/em> <em>Rave<\/em>&#8221; vienne frapper un grand coup avec des kicks puissants. L&#8217;album est plein de m\u00e9lodies entra\u00eenantes et vibrantes. Les sons sont percutants et oscillent entre des sonorit\u00e9s acid et groove, symboles du renouveau de la techno en 2020. On s&#8217;\u00e9loigne des sonorit\u00e9s old school et <strong>AIROD<\/strong> pose ici les bases de son identit\u00e9 artistique de la meilleure des mani\u00e8res. <strong>AIROD<\/strong> conclut cet album en trouvant la paix dans un monde finalement imaginaire qu&#8217;il d\u00e9finit comme &#8220;<em>Purple<\/em> <em>Paradise<\/em>&#8221; &#8211; un morceau optimiste, apaisant, aux sonorit\u00e9s futuristes sur un rythme breakbeat, qui compl\u00e8te ce voyage sonore puissant mais enivrant.<\/p><p>Thomas V<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5b26e2 elementor-widget elementor-widget-heading\" data-id=\"2e5b26e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AIROD<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796dfe78 elementor-widget elementor-widget-heading\" data-id=\"796dfe78\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Burn Injury<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3740add8 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3740add8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30a9597b\" data-id=\"30a9597b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6973e2ac elementor-widget elementor-widget-image\" data-id=\"6973e2ac\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5.8,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:1,&quot;end&quot;:99}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1200\" height=\"1200\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_.jpg 1200w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1024x1024.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4976661a\" data-id=\"4976661a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2246c0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4b2246c0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf46935 elementor-widget elementor-widget-text-editor\" data-id=\"5cf46935\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>La fuite de son album quelques semaines avant sa sortie officielle n\u2019a pas emp\u00each\u00e9 <strong>Dua Lipa<\/strong> de rebondir et d\u2019offrir de quoi \u00e9gayer l\u2019ann\u00e9e 2020. Avec son deuxi\u00e8me album <em>Future Nostalgia<\/em>, l\u2019artiste britannique se d\u00e9voile dans un style original aux sonorit\u00e9s pop, funk et disco qui n\u2019est pas sans rappeler celui des ann\u00e9es 80. En t\u00eate d\u2019affiche, le titre &#8220;<em>Don\u2019t Start Now&#8221;<\/em> acc\u00e8de \u00e0 la deuxi\u00e8me place du Billboard Hot 100 aux \u00c9tats-Unis et d\u00e9passe le milliard de streams sur Spotify. A ne pas n\u00e9gliger pour autant les morceaux &#8220;<em>Physical&#8221;, &#8220;Break My Heart&#8221;<\/em> et &#8220;<em>Levitating&#8221;\u00a0<\/em>qui ont eux aussi accompagn\u00e9 2020. Parmi plus de soixante titres enregistr\u00e9s pour l\u2019album, seuls onze auront leur place dans la version finale. Aucun d\u2019entre eux ne comporte de featuring hormis &#8220;<em>Fever&#8221;<\/em> avec <strong>Ang\u00e8le <\/strong>et &#8220;<em>Levitating&#8221;<\/em> avec <strong>DaBaby<\/strong>, qui ne figurent toutefois pas aux \u00e9ditions originales. Malgr\u00e9 tout, on retrouve \u00e0 l\u2019\u00e9criture des noms connus tels que <strong>Tove lo<\/strong> sur le titre &#8220;<em>Cool&#8221;<\/em> ou encore <strong>Julia Michaels<\/strong> pour &#8220;<em>Pretty Please&#8221;<\/em>. Sur cet album, <strong>Dua Lipa<\/strong> aborde entre autres les th\u00e8mes de la rupture, du f\u00e9minisme et des relations amoureuses. L\u2019artiste a fait appel \u00e0 des instrumentales moins \u00e9lectroniques que pour son premier album, afin de privil\u00e9gier des performances live avec de v\u00e9ritables musiciens. Apr\u00e8s avoir conquis 2020, <strong>Dua Lipa<\/strong> ne compte pas s\u2019arr\u00eater l\u00e0 et pr\u00e9voit pour septembre 2021 un <em>Future Nostalia Tour<\/em>.<\/p><p>Eva\u00a0<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25af6262 elementor-widget elementor-widget-heading\" data-id=\"25af6262\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dua Lipa<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac94f16 elementor-widget elementor-widget-heading\" data-id=\"2ac94f16\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Future nostalgia<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68e657bf elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68e657bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-161daae\" data-id=\"161daae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e051ec8 elementor-widget elementor-widget-image\" data-id=\"4e051ec8\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.7,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e5191a7\" data-id=\"1e5191a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c49a268 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5c49a268\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a90581 elementor-widget elementor-widget-text-editor\" data-id=\"29a90581\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Avez-vous un souvenir marquant de vos 23 ans ? Le rappeur <strong>Gianni<\/strong>, lui, fait un bilan rempli de m\u00e9lancolie de son presque quart de si\u00e8cle sur sa mixtape <em>XXIII : Bilan de vie<\/em>. Apr\u00e8s s\u2019\u00eatre fait remarquer avec ses pr\u00e9c\u00e9dents projets <em>D.D.M<\/em>, <em>D.D.M 2<\/em> et <em>G\u00e9henne<\/em>, le rappeur du 93 n\u2019en finit plus de grimper les \u00e9chelons pour s\u2019imposer petit \u00e0 petit comme le futur gratin du rap fran\u00e7ais. Et cette mixtape\u00a0<em>XXIII : Bilan de vie<\/em>\u00a0le confirme. En termes de popularit\u00e9 d\u00e9j\u00e0, avec un excellent featuring avec le rappeur de Houston <strong>Don<\/strong> <strong>Toliver<\/strong>, sign\u00e9 sur le label de <strong>Travis<\/strong> <strong>Scott<\/strong>, <strong>Cactus<\/strong> <strong>Jack<\/strong>. Et surtout, en termes de qualit\u00e9. Le projet est une splendide plong\u00e9e dans un univers m\u00e9lancolique, dans lequel <strong>Gianni<\/strong> nous explique et nous d\u00e9crit au mieux la vie de quartier dans ce qu\u2019elle peut avoir de plus morose. Ici, pas d\u2019artifices ni de surench\u00e8res. Seulement une r\u00e9alit\u00e9 qui sonne comme un constat de quelques ann\u00e9es, adoucie par quelques notes autotun\u00e9es. La plume de <strong>Gianni<\/strong> a ce quelque chose d\u2019imag\u00e9, complexe dans sa simplicit\u00e9, r\u00e9ussissant \u00e0 nous toucher en plein c\u0153ur. Et ce, tout le long des 12 titres d\u2019une extr\u00eame coh\u00e9rence composant le projet. Nous pouvons \u00e9galement souligner la qualit\u00e9 des prods de cette mixtape, sur lesquelles <strong>Gianni<\/strong> nous d\u00e9voile des m\u00e9lodies encore plus pouss\u00e9es et ma\u00eetris\u00e9es que sur les projets pr\u00e9c\u00e9dents. Si 2020 \u00e9tait l\u2019ann\u00e9e du \u00ab Bilan \u00bb, on esp\u00e8re pour 2021 la \u00ab confirmation \u00bb du statut de <strong>Gianni<\/strong> comme un gros du rap fran\u00e7ais. Quoi qu\u2019il en soit, la qualit\u00e9 est l\u00e0, et c\u2019est finalement le plus important.<\/p><p>R\u00e9mi<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4024d333 elementor-widget elementor-widget-heading\" data-id=\"4024d333\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gianni<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5be92c79 elementor-widget elementor-widget-heading\" data-id=\"5be92c79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>XXIII : Bilan de vie<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b0c8de3 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b0c8de3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-94fbb9d\" data-id=\"94fbb9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e735830 elementor-widget elementor-widget-image\" data-id=\"3e735830\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:97}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1400\" height=\"1400\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_.jpg 1400w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_-1024x1024.jpg 1024w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e518ba3\" data-id=\"5e518ba3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b32b490 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5b32b490\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4abd53 elementor-widget elementor-widget-text-editor\" data-id=\"e4abd53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>\u00c0 l\u2019aube d\u2019une pand\u00e9mie qui a compl\u00e8tement chang\u00e9 2020, le rappeur <strong>Laylow<\/strong> a peut-\u00eatre d\u00e9livr\u00e9 le 28 f\u00e9vrier 2020 l\u2019un des projets les plus ambitieux de l\u2019ann\u00e9e en termes de r\u00e9alisation : <em>TRINITY<\/em>. Pour cela, il a eu besoin d\u2019une direction artistique efficace autour d\u2019un parall\u00e8le entre sa vie et la trilogie Matrix, de bangers et de collaborations de qualit\u00e9. S\u2019il a su s\u2019entourer de vrais hit makers comme <strong>Alpha<\/strong> <strong>Wann<\/strong>, <strong>Dioscures<\/strong>, <strong>Jok\u2019air<\/strong>, <strong>Wit.<\/strong> ou encore <strong>Lomepal<\/strong>, ils ne sont pas les seuls \u00e9l\u00e9ments cl\u00e9s du projet. L\u2019album est d\u00e9coup\u00e9 en plusieurs actes gr\u00e2ce aux interludes, comme si <strong>Laylow<\/strong> tenait \u00e0 nous faire passer par une multitude d\u2019\u00e9motions au cours de l\u2019\u00e9coute de ses 22 morceaux. Une intention ambitieuse qui n\u00e9cessite plusieurs \u00e9coutes pour appr\u00e9cier et saisir l\u2019ensemble du travail fourni dans cet album. Cependant, c\u2019est une intention qui a fonctionn\u00e9 et qui place d\u00e9sormais le projet parmi les plus r\u00e9ussis de l\u2019ann\u00e9e. Si personne n\u2019attendait vraiment ce premier album du rappeur, il est maintenant certain que la suite de sa discographie sera observ\u00e9e de tr\u00e8s pr\u00e8s.<\/p><p>Augustin<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c9c5ba elementor-widget elementor-widget-heading\" data-id=\"34c9c5ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Laylow<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7248b7db elementor-widget elementor-widget-heading\" data-id=\"7248b7db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Trinity<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14ba2fdb elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14ba2fdb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60c1d72a\" data-id=\"60c1d72a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d70f67e elementor-widget elementor-widget-image\" data-id=\"1d70f67e\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.6,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:3,&quot;end&quot;:96}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60b27736\" data-id=\"60b27736\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38c63e82 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"38c63e82\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-414abb15 elementor-widget elementor-widget-text-editor\" data-id=\"414abb15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>2020 marque l\u2019apog\u00e9e d\u2019un tournant pour le rap italien, dont <strong>Sfera<\/strong> <strong>Ebbasta<\/strong> se fait le porte-parole \u00e0 l\u2019international. Par cet album, <em>Famoso<\/em>, <strong>Sfera<\/strong> semble annoncer que les <em>Giovani Re<\/em>, jeunes rois (du titre \u00e9ponyme) du rap sont aujourd\u2019hui italiens. Le jeune rappeur de Lombardie revient deux ans apr\u00e8s <em>Rockstar<\/em> avec un style encore plus affirm\u00e9 et singulier, reprenant avec intelligence les atouts de la culture italienne baroque\u00a0comme les couleurs vives et les dorures. La carri\u00e8re et les textes de <b>Sfera<\/b> sont aur\u00e9ol\u00e9s par le d\u00e9sir de revanche sociale et de c\u00e9l\u00e9brit\u00e9. Une soif de gloire totalement assum\u00e9e qu\u2019on retrouve aussi bien dans le titre &#8220;<em>Famoso&#8221;<\/em> que dans la cover de l\u2019album o\u00f9 <strong>Sfera<\/strong> appara\u00eet en <strong>Franck<\/strong> <strong>Sinatra<\/strong>. Si <strong>Ebbasta<\/strong> \u00e9tait d\u00e9j\u00e0 connu de la sc\u00e8ne fran\u00e7aise pour ses feats avec <strong>Lacrim<\/strong> et <strong>SCH<\/strong> il impressionne d\u2019autant plus en nous proposant des titres avec des stars du rap US, comme &#8220;<em>Abracadabra&#8221;\u00a0<\/em>avec <strong>Future<\/strong> et &#8220;<em>Macarena&#8221;<\/em> avec <strong>Offset<\/strong>, des piliers du reggaeton comme <strong>J Balvin<\/strong> dans &#8220;<em>Baby&#8221;<\/em>\u00a0ou encore des DJs cultes comme <strong>Steve<\/strong> <strong>Aoki<\/strong>. Dans cet album innovant, il n\u2019oublie pas totalement ses classiques en s\u2019associant \u00e0 travers <em>Tik Tok<\/em> \u00e0 <strong>Marracash<\/strong> et <strong>Gu\u00e9<\/strong> <strong>Pequeno<\/strong>, deux figures du rap old school italien, membres de l\u2019ancien collectif <strong>Dogo<\/strong> <strong>Gang<\/strong>. Enfin, au-del\u00e0 des bangers <strong>Sfera<\/strong> nous offre \u00e9galement des sons plus introspectifs comme &#8220;<em>Hollywood&#8221;<\/em>, mais surtout &#8220;<em>Bottiglie Priv\u00e8&#8221;<\/em>, aux accents m\u00e9lancoliques nous rappelant les premiers titres de <strong>Laura<\/strong> <strong>Pausini<\/strong> ou encore, plus r\u00e9cemment, de <strong>Mahmood<\/strong>.<\/p><p>Eva<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d93b592 elementor-widget elementor-widget-heading\" data-id=\"3d93b592\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sfera Ebbasta<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c2084b4 elementor-widget elementor-widget-heading\" data-id=\"2c2084b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Famoso<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ae5f220 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ae5f220\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cdb0045\" data-id=\"2cdb0045\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be7f1df elementor-widget elementor-widget-image\" data-id=\"5be7f1df\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7.3,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:4,&quot;end&quot;:96}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1200\" height=\"1200\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork.jpg 1200w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork-1024x1024.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70685a5b\" data-id=\"70685a5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c3a9d1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6c3a9d1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49745ff elementor-widget elementor-widget-text-editor\" data-id=\"49745ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Cette ann\u00e9e, aussi triste a-t-elle pu \u00eatre, nous a tout de m\u00eame procur\u00e9 des moments de joie. C\u2019est ce que nous a offert <strong>Claire<\/strong> <strong>Faravarjoo<\/strong> le 14 f\u00e9vrier dernier en d\u00e9voilant son premier album <em>Nightclub<\/em>. Depuis la sortie de son premier EP <em>Minuit<\/em>\u00a0en octobre 2017, tout s\u2019encha\u00eene pour la jeune strasbourgeoise\u00a0: finaliste du Prix Ricard SA Live 2018, s\u00e9lection Inou\u00efs du Printemps de Bourges 2018, S\u00e9lection Tremplin D\u00e9cibulles 2018, s\u00e9lection Pic d\u2019Or 2018, et bien d\u2019autres encore. Une succession de s\u00e9lections et de prix qui en disent donc long sur cette artiste qui m\u00e9ritait d\u2019\u00eatre suivie de plus pr\u00e8s. L\u2019annonce de son premier album f\u00fbt alors la cerise sur le g\u00e2teau. Et pas des moindres puisque <strong>Claire<\/strong> <strong>Faravarjoo<\/strong> nous d\u00e9voile une invitation \u00e0 faire la f\u00eate sous couverture de titres color\u00e9s aux influences french pop et disco. Ses 12 titres abordent des sujets quotidiens que l\u2019on a tous v\u00e9cus et que l\u2019on vivra encore\u00a0: des histoires d\u2019amour (\u00ab\u00a0<em>Tu sais me manquer<\/em>\u00a0\u00bb\u00a0; \u00ab\u00a0<em>Rod\u00e9o<\/em>\u00a0\u00bb\u00a0; \u00ab\u00a0<em>Amour<\/em> <em>de<\/em> <em>vacances<\/em>\u00a0\u00bb), l\u2019envie irr\u00e9m\u00e9diable de faire la f\u00eate (\u00ab\u00a0<em>Ivresse<\/em>\u00a0\u00bb), puis le verre de trop (\u00ab\u00a0<em>Tequila<\/em>\u00a0\u00bb), mais aussi des ruptures (\u00ab\u00a0<em>Mon<\/em> <em>ex<\/em>\u00a0\u00bb) et des \u00e9checs personnels. Et c\u2019est seule dans l\u2019intimit\u00e9 de sa chambre que <strong>Claire<\/strong> a concoct\u00e9 cet album qui se veut \u00eatre une v\u00e9ritable histoire. Pas \u00e9tonnant donc que son dernier single \u00ab\u00a0<em>Rod\u00e9o<\/em>\u00a0\u00bb ait \u00e9t\u00e9 r\u00e9compens\u00e9 \u00ab D\u00e9couverte francophone pour les m\u00e9dias publics francophones\u00a0\u00bb cette ann\u00e9e. En bref, <em>Nightclub,\u00a0<\/em>c\u2019est beaucoup de couleurs, une ode aux \u00e9pop\u00e9es nocturnes, des cocktails \u00e0 n\u2019en plus finir, des pas de danse effr\u00e9n\u00e9s, et surtout beaucoup d\u2019amour (pas \u00e9tonnant donc qu\u2019il soit sorti le jour de la Saint Valentin !).<\/p><p>M\u00e9lina<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36db8447 elementor-widget elementor-widget-heading\" data-id=\"36db8447\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Claire Faravarjoo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16966ad8 elementor-widget elementor-widget-heading\" data-id=\"16966ad8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Nightclub<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f724c41 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f724c41\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c135c58\" data-id=\"4c135c58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7343736f elementor-widget elementor-widget-image\" data-id=\"7343736f\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:99}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1638\" height=\"2048\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit.jpg 1638w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit-240x300.jpg 240w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit-768x960.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit-819x1024.jpg 819w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c8790af\" data-id=\"5c8790af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98f5c70 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"98f5c70\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4802757 elementor-widget elementor-widget-text-editor\" data-id=\"4802757\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Infinit\u2019<\/strong>, notre rappeur pr\u00e9f\u00e9r\u00e9 du Sud-Est, a sorti son premier album <em>Ma vie est un film II<\/em>\u00a0le 27 Mars 2020, sept ans apr\u00e8s son projet <em>Ma vie est un film<\/em>, et c\u2019est aussi percutant que technique, aussi planant que brutal. L\u2019artiste de <i>D<\/i><em>\u2019en bas fondation<\/em>\u00a0et de <i>Don dada<\/i>\u00a0a un style rapologique inspir\u00e9 des banlieues new-yorkaises, mais aussi de rappeurs fran\u00e7ais comme <strong>Dany Dan, Nubi <\/strong>ou encore <strong>Veust, <\/strong>son parrain musical que l\u2019on retrouve sur le projet. C\u2019est donc \u00e0 travers un album o\u00f9 la palette stylistique du rappeur a d\u00e9cupl\u00e9, que nous d\u00e9couvrons une nouvelle facette d\u2019<b>Infinit\u2019<\/b> qui ne fait qu\u2019exceller. <strong>Infinit\u2019 <\/strong>s\u2019amuse sur les prods avec l\u2019assurance de <b>Kim Jong-un<\/b>, la fermet\u00e9 de <b>Vladimir<\/b> et la dext\u00e9rit\u00e9 de <b>Mike Horn<\/b>. Le premier titre de l\u2019EP, r\u00e9f\u00e9rence \u00e0 son label <em>D\u2019en bas<\/em>\u00a0nous offre une musique o\u00f9\u00a0<strong>Infinit\u2019<\/strong> \u00e9crit comme <b>Guy de Maupassant<\/b>, il lui faut de l\u2019argent. Le refrain, aussi surprenant qu\u2019envo\u00fbtant, donne une nouvelle dimension au rappeur qui ma\u00eetrise d\u00e9sormais l\u2019exercice difficile du chant et offre un contraste int\u00e9ressant \u00e0 sa musique. On retrouve sur cet album le morceau \u201c<em>Programme<\/em>\u201d qui a fait l\u2019unanimit\u00e9 aupr\u00e8s de sa communaut\u00e9 tant la technique, l\u2019\u00e9nergie et les rimes du Ni\u00e7ois sont \u00e9blouissantes. Comment parler de <em>MVEUF2<\/em> sans parler de \u201c<em>Cigarette 2 haine<\/em>\u201d, qui est tout simplement une le\u00e7on de rap qui fait du bien \u00e0 cette musique\u00a0? Le feat avec <strong>Alpha Wann<\/strong>\u00a0clipp\u00e9 a raviv\u00e9 les yeux et les oreilles de chacun d\u2019entre nous. Vous l\u2019avez compris, <strong>Infinit\u2019<\/strong> expose l\u2019\u00e9tendue de son talent sur cet album, ou plut\u00f4t de ses talents qu\u2019il met en lumi\u00e8re en 14 titres, \u00e0 travers questionnement, d\u00e9termination et d\u00e9monstration dans un monde o\u00f9 nous ne sommes qu\u2019infiniment petit dans l\u2019infiniment grand.<\/p><p>Dimitri<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1753b0b elementor-widget elementor-widget-heading\" data-id=\"1753b0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Infinit'<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2589b6 elementor-widget elementor-widget-heading\" data-id=\"4f2589b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Ma vie est un film ii<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65f8ec3a elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65f8ec3a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48185604\" data-id=\"48185604\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c658fab elementor-widget elementor-widget-image\" data-id=\"5c658fab\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:10,&quot;end&quot;:97}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"1482\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek.jpg 1500w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek-300x296.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek-768x759.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek-1024x1012.jpg 1024w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-49b54b99\" data-id=\"49b54b99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-305240b1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"305240b1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739fa13b elementor-widget elementor-widget-text-editor\" data-id=\"739fa13b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Le mois de Mars a peut-e\u0302tre de\u0301bute\u0301 avec un confinement mais n\u2019a pas e\u0301te\u0301 un frein pour l\u2019artiste <b>The Weeknd<\/b> qui a maintenu la sortie de son quatrie\u0300me album <em>After Hours<\/em>. Pour celles et ceux qui suivent <strong>The Weeknd<\/strong>, l\u2019album a su marquer les esprits avec un disque surprenant. En effet, le co\u0302te\u0301 artistique du disque a suscite\u0301 la curiosite\u0301 des internautes. En plus de la couverture repre\u0301sente\u0301e par un visage ab\u00eeme\u0301, l\u2019album e\u0301volue au fil des musiques. Celui-ci est repre\u0301sente\u0301 par des titres qui se suivent comme une histoire de\u0301crivant plusieurs e\u0301motions. <strong>Abel Tesfaye<\/strong> a cherche\u0301 a\u0300 captiver son public par le biais de plusieurs e\u0301pisodes en re\u0301inventant ses morceaux dans une ambiance cine\u0301matographique violente. L\u2019artiste canadien nous a cuisine\u0301 des titres plus travaille\u0301s et personnels afin d\u2019en connai\u0302tre davantage sur celui-ci ainsi que ses diffe\u0301rentes facettes a\u0300 l\u2019aide de vide\u0301o clips, en plus des morceaux inspire\u0301s des anne\u0301es 1980. Vous l\u2019aurez bien compris, contrairement aux albums pre\u0301ce\u0301dents <strong>The Weeknd<\/strong> n\u2019a pas voulu faire danser son public mais a pre\u0301fe\u0301re\u0301 le plonger dans une histoire bien plus profonde.<\/p><p>Marie<\/p><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79a60500 elementor-widget elementor-widget-heading\" data-id=\"79a60500\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Weeknd<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-525b0f2 elementor-widget elementor-widget-heading\" data-id=\"525b0f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>After Hours<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4efb25b5 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4efb25b5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-100cb844\" data-id=\"100cb844\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ddc455e elementor-widget elementor-widget-image\" data-id=\"1ddc455e\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.5,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:2,&quot;end&quot;:99}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1400\" height=\"1400\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king.jpeg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king.jpeg 1400w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king-150x150.jpeg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king-300x300.jpeg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king-768x768.jpeg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king-1024x1024.jpeg 1024w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3335ac3d\" data-id=\"3335ac3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10a968c2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"10a968c2\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69b108d elementor-widget elementor-widget-text-editor\" data-id=\"69b108d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"page\" title=\"Page 1\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Au milieu d\u2019une anne\u0301e 2020 charge\u0301e en sortie de projets attendus par le public, le rappeur new-yorkais <strong>Nas<\/strong> a d\u00e9voil\u00e9 son 12e\u0300me album <em>King\u2019s Disease<\/em>. Un vrai re\u0301gal pour les fans de classique du rap, ce projet arrive pre\u0300s de 25 ans apre\u0300s la pie\u0300ce mai\u0302tresse de sa discographie <em>Illmatic<\/em>, et nous montre a\u0300 quel point <strong>Nas<\/strong> est toujours aussi percutant. En effet <em>King\u2019s Disease<\/em> se veut pointu mais tre\u0300s agre\u0301able a\u0300 e\u0301couter, avec 13 titres pour 38 minutes, nous permettant de nous approprier facilement l\u2019enchai\u0302nement des sons et des ambiances variant d\u2019instrumentales boom-bap et vaporeuses a\u0300 des sons plus traps et actuels. Dans cet album,\u00a0<strong>Nas<\/strong> nous propose un contenu de qualite\u0301 et varie\u0301, qui colle a\u0300 son identite\u0301 mais aussi en collaborant avec d\u2019autres artistes tels que <strong>Don Toliver<\/strong>, <strong>Anderson Paak<\/strong>, <strong>Lil Durk<\/strong> ou encore <strong>A$AP Ferg<\/strong>. Bref, cet album est complet et ne manque de rien mais c\u2019est aussi parce que <strong>Nas<\/strong> ne fait rien au hasard : il a fait appel a\u0300 <b>Hit-Boy<\/b> (qui a de\u0301ja\u0300 participe\u0301 aux productions de <i>&#8220;Sicko Mode&#8221;<\/i>\u00a0de <strong>Travis Scott<\/strong> , &#8220;<i>Clique&#8221;<\/i>\u00a0de <strong>Kanye West<\/strong> et me\u0302me &#8220;<i>1Train&#8221;<\/i>\u00a0de <strong>A$AP Rocky<\/strong> pour la production de l\u2019album) et c\u2019est re\u0301ussi ! Le 24 aou\u0302t, trois jours apre\u0300s sa sortie, l\u2019album s\u2019est me\u0302me retrouve\u0301 a\u0300 la 5e\u0300me place du Billboard 200 et c\u2019est amplement me\u0301rite\u0301 ! En ce qui me concerne, cet album a ensoleille\u0301 la fin de mon e\u0301te\u0301, j\u2019ai pu l\u2019e\u0301couter en toute circonstances. Que vous soyez fan de longues dates ou simplement curieux, je ne pourrais que vous recommander d\u2019e\u0301couter <em>King\u2019s Disease<\/em>.<\/p><p>Benjamin<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d25ef4 elementor-widget elementor-widget-heading\" data-id=\"58d25ef4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7578b6f4 elementor-widget elementor-widget-heading\" data-id=\"7578b6f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>King's disease<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-640cd866 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"640cd866\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78b05f67\" data-id=\"78b05f67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a4f48 elementor-widget elementor-widget-image\" data-id=\"8a4f48\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7.2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:2,&quot;end&quot;:98}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1200\" height=\"1200\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts.jpeg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts.jpeg 1200w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts-150x150.jpeg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts-300x300.jpeg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts-768x768.jpeg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts-1024x1024.jpeg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14a0149b\" data-id=\"14a0149b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40564ae8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"40564ae8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5af9d315 elementor-widget elementor-widget-text-editor\" data-id=\"5af9d315\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Apr\u00e8s avoir sorti son EP <em>She is coming<\/em> en 2019, c\u2019est le 27 novembre 2020 que <strong>Miley<\/strong> <strong>Cyrus<\/strong> nous a surpris avec son dernier album <em>Plastic Hearts<\/em>. Inspir\u00e9 du rock et du pop-rock des ann\u00e9es 80 et 90, cet album semble \u00eatre un m\u00e9lange de tous les styles musicaux de chacun de ses pr\u00e9c\u00e9dents albums. Mais ce dernier semble r\u00e9ellement lui correspondre et montrer des facettes de sa personnalit\u00e9 que nous ne connaissions pas. Elle dit s\u2019\u00eatre trouv\u00e9e dans celui-ci et laisse para\u00eetre ses faiblesses, tout comme ses forces. D\u00e8s cet \u00e9t\u00e9, elle a pos\u00e9 les bases en s\u2019affirmant avec la sortie de &#8220;<em>Midnight Sky&#8221;<\/em>, avec notamment des sonorit\u00e9s orient\u00e9es ann\u00e9es 80, tr\u00e8s rock. A travers ses paroles, elle prouve qu\u2019elle est une femme libre et ind\u00e9pendante, qui n\u2019a besoin de personne. Dans son feat avec <strong>Dua<\/strong> <strong>Lipa<\/strong>, &#8220;<em>Prisoner&#8221;<\/em>, elle met en avant son \u00e9nergie pop rock que l\u2019on retrouve dans ses autres feats avec des artistes l\u00e9gendaires comme <strong>Billy<\/strong> <strong>Idol<\/strong>, <strong>Stevie<\/strong> <strong>Nicks<\/strong> et <strong>Joan<\/strong> <strong>Jett<\/strong>, pionni\u00e8re du rock f\u00e9minin. Dans l\u2019\u00e9dition num\u00e9rique de son album, on retrouve \u00e9galement ses r\u00e9centes reprises &#8220;<em>Heart of Glass&#8221;<\/em> de <b>Blondie<\/b>, &#8220;<em>Zombie&#8221;<\/em> des <strong>Cranberries<\/strong> ainsi que &#8220;<em>Edge of Midnight&#8221;<\/em>, un mashup de &#8220;<em>Midnight Sky&#8221;<\/em> et &#8220;<em>Edge of Seventeen&#8221;<\/em> de <strong>Stevie<\/strong> <strong>Nicks<\/strong>. <strong>Miley<\/strong> <strong>Cyrus<\/strong> a longtemps \u00e9t\u00e9 \u00e0 la recherche du parfait \u00e9quilibre entre la rock attitude et les sonorit\u00e9s pop tout au long de sa carri\u00e8re. Dans <em>Plastic Hearts<\/em>, elle semble enfin avoir trouv\u00e9 un registre qui lui appartient : c\u2019est l&#8217;album que <strong>Miley<\/strong> avait en elle depuis le d\u00e9but et qu\u2019elle a fait m\u00fbrir au fil des ann\u00e9es, un \u00e9quilibre confortable entre son univers rock et ses bases pop.<\/p><p>Mathilda<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3989a624 elementor-widget elementor-widget-heading\" data-id=\"3989a624\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Miley Cyrus<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b67471 elementor-widget elementor-widget-heading\" data-id=\"70b67471\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Plastic hearts<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4be78c84 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4be78c84\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-263fbcea\" data-id=\"263fbcea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72d2f96c elementor-widget elementor-widget-image\" data-id=\"72d2f96c\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8.1,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:4,&quot;end&quot;:96}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1af1d745\" data-id=\"1af1d745\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3637021f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3637021f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc80c2c elementor-widget elementor-widget-text-editor\" data-id=\"2bc80c2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Malgr\u00e9 un contexte particulier aux vues des \u00e9v\u00e8nements que l\u2019on conna\u00eet tous, 2020 a \u00e9t\u00e9 une ann\u00e9e plut\u00f4t prolifique en rap fran\u00e7ais avec certains projets tr\u00e8s int\u00e9ressants, notamment celui de l\u2019artiste le plus stream\u00e9 du continent africain\u00a0: <strong>Soolking<\/strong>. En effet, le 20 mars 2020, en plein d\u00e9but de confinement le deuxi\u00e8me album solo de <strong><em>Soolking<\/em><\/strong> intitul\u00e9 <em>Vintage<\/em> est d\u00e9voil\u00e9 et il passe presque inaper\u00e7u au moment de sa sortie car le climat n\u2019\u00e9tait pas forc\u00e9ment \u00e0 la musique \u00e0 ce moment-l\u00e0. Pour moi, cet album est tr\u00e8s abouti et il permet de se rendre compte de la grande polyvalence de l\u2019artiste avec des sons tr\u00e8s m\u00e9lodieux, des sons dansants ou encore des sons tr\u00e8s rapp\u00e9s. En bref, un excellent \u00e9quilibre et une ma\u00eetrise de presque tous les registres qui est assez impressionnante. Par ailleurs, si l\u2019on regarde les feats, on remarque que <strong>Soolking<\/strong> a r\u00e9uni un nombre cons\u00e9quent d\u2019artistes avec notamment <strong>Dadju<\/strong>, <strong>SCH<\/strong>, <strong>Jul<\/strong>, <strong>Heuss l\u2019Enfoir\u00e9<\/strong>, <strong>Gambi<\/strong>, <strong>13 Block<\/strong> ou encore le prince du Ra\u00ef en la personne de <strong><em>Cheb Mami<\/em><\/strong>. De ce fait, l\u2019album est un vrai r\u00e9gal et il s\u2019\u00e9coute tr\u00e8s facilement avec une tracklist bien contrast\u00e9e entre featurings et sons solos. Pour ma part, si je devais faire un top de mes sons pr\u00e9f\u00e9r\u00e9s, je pense que les sons &#8220;<em style=\"letter-spacing: 1.4px;\">Marbella&#8221;<\/em><span style=\"letter-spacing: 1.4px;\">, &#8220;<\/span><em style=\"letter-spacing: 1.4px;\">Marilyne&#8221;<\/em><span style=\"letter-spacing: 1.4px;\"> (en feat avec <\/span><strong style=\"letter-spacing: 1.4px;\">SCH<\/strong><span style=\"letter-spacing: 1.4px;\">) et &#8220;<\/span><em style=\"letter-spacing: 1.4px;\">Business&#8221;<\/em><span style=\"letter-spacing: 1.4px;\"> sont tr\u00e8s repr\u00e9sentatifs de cet album et sont tr\u00e8s r\u00e9ussis. Pour terminer, il est aussi important de rappeler qu\u2019une r\u00e9\u00e9dition de cet album est sortie le 16 septembre 2020 avec encore d\u2019autres feats tels que <\/span><strong style=\"letter-spacing: 1.4px;\">Hamza<\/strong><span style=\"letter-spacing: 1.4px;\">, <\/span><strong style=\"letter-spacing: 1.4px;\">Sofiane<\/strong><span style=\"letter-spacing: 1.4px;\"> ou encore <\/span><strong style=\"letter-spacing: 1.4px;\">Zed<\/strong><span style=\"letter-spacing: 1.4px;\">. Enfin, je pense que cet album m\u00e9rite largement le d\u00e9tour, notamment pour sa grande vari\u00e9t\u00e9 en termes de sons ainsi que pour ses featurings qui sont in\u00e9dits mais presque naturels aux vues de la polyvalence de <\/span><strong style=\"letter-spacing: 1.4px;\">Soolking<\/strong><span style=\"letter-spacing: 1.4px;\">.<\/span><\/p><p>Paul<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c40476 elementor-widget elementor-widget-heading\" data-id=\"32c40476\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soolking<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36de83ae elementor-widget elementor-widget-heading\" data-id=\"36de83ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Vintage<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-728afe15 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"728afe15\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e4e5ddf\" data-id=\"5e4e5ddf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6608972c elementor-widget elementor-widget-image\" data-id=\"6608972c\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7.7,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:6,&quot;end&quot;:94}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Eg08uD_XYAId3Re.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Eg08uD_XYAId3Re.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Eg08uD_XYAId3Re-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Eg08uD_XYAId3Re-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Eg08uD_XYAId3Re-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d0c0b64\" data-id=\"7d0c0b64\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60154855 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"60154855\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14013536 elementor-widget elementor-widget-text-editor\" data-id=\"14013536\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Sorti en septembre dernier, <em>LMF<\/em> aka <em>La<\/em> <em>Menace<\/em> <em>Fant\u00f4me<\/em> a fait le bruit d\u2019un s\u00e9isme sur le terrain du rap fran\u00e7ais. Apr\u00e8s <em>Projet<\/em> <em>Blue<\/em> <em>Beam<\/em>, EP d\u00e9voil\u00e9\u00a0en 2018, <strong>Freeze<\/strong> <strong>Corleone<\/strong> a d\u00e9cid\u00e9 que dans ce projet, il allait faire intervenir des gros noms du rap fran\u00e7ais comme <strong>Alpha<\/strong> <strong>Wann<\/strong>, <strong>Stavo<\/strong> de <strong>13<\/strong> <strong>Block<\/strong>, <strong>Le<\/strong> <strong>Roi<\/strong> <strong>Hennok<\/strong>, <strong>Ashe<\/strong> <strong>22<\/strong>, <strong>Despo<\/strong> <strong>Rutti<\/strong> et <strong>Alpha<\/strong> <strong>5.20<\/strong>. On peut alors dire que cet album a \u00e9t\u00e9 r\u00e9alis\u00e9 en \u00ab\u00a0<i>Ekip<\/i>\u00a0<span style=\"letter-spacing: 1.4px;\">\u00bb<\/span><span style=\"letter-spacing: 1.4px;\">, qui est s\u00fbrement le mot le plus r\u00e9p\u00e9t\u00e9 dans le projet, qui pourrait m\u00eame rendre l\u2019\u00e9coute \u00e9trange pour une personne ne connaissant pas le personnage. Mais cela ne r\u00e9pond pas \u00e0 la question\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">\u00ab\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">Pourquoi est-il le meilleur album de 2020 ?\u00a0<\/span><span style=\"letter-spacing: 1.4px;\">\u00bb<\/span><span style=\"letter-spacing: 1.4px;\">. D\u2019un part, on va pouvoir retrouver le <\/span><strong style=\"letter-spacing: 1.4px;\">Freeze<\/strong> <strong style=\"letter-spacing: 1.4px;\">Corleone<\/strong><span style=\"letter-spacing: 1.4px;\"> sombre avec des instrus toujours autant explosives. En effet, lorsqu\u2019on \u00e9coute la qualit\u00e9 de cet album et en tant que pionnier de la drill fran\u00e7aise, <\/span><strong style=\"letter-spacing: 1.4px;\">Freeze Corleone<\/strong><span style=\"letter-spacing: 1.4px;\"> n&#8217;oublie de faire r\u00e9f\u00e9rence aux anciens du rap fran\u00e7ais en utilisant ses fameux \u00ab <i>S\/o<\/i> \u00bb pour parler de la <\/span><strong style=\"letter-spacing: 1.4px;\">Black<\/strong> <strong style=\"letter-spacing: 1.4px;\">Mafia<\/strong><span style=\"letter-spacing: 1.4px;\"> ou bien d&#8217;<\/span><strong style=\"letter-spacing: 1.4px;\">Oxmo Puccino<\/strong><span style=\"letter-spacing: 1.4px;\">. Mais ce n\u2019est pas tout car tout y passe : on va aller des jeux-vid\u00e9o en passant par les anim\u00e9s. Comme premier album, on peut dire que c\u2019est un franc succ\u00e8s et ce n\u2019est pas pr\u00eat de s\u2019arr\u00eater pour un rappeur qui sait comment f\u00e9d\u00e9rer un public et cristalliser un nouveau style, en oubliant le basique couplet-refrain et en y ajoutant son propre ADN. Malgr\u00e9 toutes les pol\u00e9miques et les discussions autour de cet album, particuli\u00e8rement sur certaines lyrics jug\u00e9es antis\u00e9mites, on peut dire que pour un premier album a su trouver son public aux vues des diff\u00e9rents chiffres de ventes et streams qu&#8217;il a atteint d\u00e8s les premi\u00e8res semaines de sa sortie.<\/span><\/p><p>Louis<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2344f6 elementor-widget elementor-widget-heading\" data-id=\"c2344f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Freeze Corleone<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8778b elementor-widget elementor-widget-heading\" data-id=\"f8778b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>LMF<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32a424f1 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32a424f1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ef66f4\" data-id=\"7ef66f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6428ac71 elementor-widget elementor-widget-image\" data-id=\"6428ac71\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8.5,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:5,&quot;end&quot;:96}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"600\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/600x600bb.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/600x600bb.jpg 600w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/600x600bb-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/600x600bb-300x300.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28cf2943\" data-id=\"28cf2943\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37674d8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"37674d8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8e576c elementor-widget elementor-widget-text-editor\" data-id=\"2d8e576c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Denise<\/strong> est une artiste, auteure-compositrice et interpr\u00e8te malgache, originaire du nord de Tamatave. Gagnante en 2014 du concours \u00ab\u00a0Island Africa Talent\u00a0\u00bb organis\u00e9 par Universal Music Group, un projet \u00e9tait alors attendu par la suite de sa part. Cela venait \u00e0 se pr\u00e9ciser car courant 2019, elle commence \u00e0 sortir diff\u00e9rents titres devenus des hits comme \u00ab\u00a0<em>Jalousie\u00a0\u00bb<\/em>, \u00ab\u00a0<em>Efa Niova\u00a0\u00bb<\/em> ou encore \u00ab\u00a0<em>Karan-Jegny\u00a0\u00bb<\/em>. La cons\u00e9cration est arriv\u00e9e en fin d\u2019ann\u00e9e avec la sortie, le 11 d\u00e9cembre 2020, de son tout premier album intitul\u00e9 <em>Tsara Joro<\/em>.\u00a0Formule pour signifier une b\u00e9n\u00e9diction en malgache, ce titre s\u2019accorde avec ce que l\u2019artiste veut transmettre \u00e0 travers les treize morceaux qui composent l\u2019album. En effet, ce dernier est un voyage en immersion dans son univers o\u00f9 elle y raconte sa vie, de son enfance \u00e0 sa vie d\u2019adulte. Elle tenait alors dans sa musique \u00e0 rendre hommage \u00e0 sa famille, \u00e0 ses a\u00een\u00e9s, qui l\u2019ont accompagn\u00e9e jusque-l\u00e0.\u00a0<span style=\"letter-spacing: 1.4px;\">\u00ab\u00a0<\/span><em style=\"letter-spacing: 1.4px;\">Tsara Joro\u00a0\u00bb<\/em><span style=\"letter-spacing: 1.4px;\">, qui fait \u00e9galement office d\u2019intro pour l\u2019album, donne des frissons d\u00e8s la premi\u00e8re \u00e9coute en venant scander l\u2019afrof\u00e9minisme, en plus du respect des a\u00een\u00e9s, repr\u00e9sentant par la m\u00eame un avant-go\u00fbt de ce qui s\u2019en suit : une ode \u00e0 la splendeur de la femme en g\u00e9n\u00e9ral. R\u00e9f\u00e9renc\u00e9e entre R&amp;B et soul, <\/span><strong style=\"letter-spacing: 1.4px;\">Denise<\/strong><span style=\"letter-spacing: 1.4px;\"> ne se limite pourtant pas qu\u2019\u00e0 ces deux genres pour son album, car des sonorit\u00e9s trap et techno peuvent, entre autres, \u00e9galement \u00eatre appr\u00e9ci\u00e9es sur des titres comme \u00ab\u00a0<\/span><em style=\"letter-spacing: 1.4px;\">Money\u00a0<\/em><span style=\"letter-spacing: 1.4px;\">\u00bb ou \u00ab\u00a0<\/span><em style=\"letter-spacing: 1.4px;\">All Eyes on Me<\/em><span style=\"letter-spacing: 1.4px;\">\u00a0\u00bb. Cette recherche dans la diversit\u00e9 musicale co\u00efncide avec le travail de longue haleine \u2013 pr\u00e8s de deux ans selon la chanteuse &#8211; pour cet album qui, bien que tr\u00e8s personnel, veut que chacun y trouve son compte. Il se conclut avec le titre \u00ab\u00a0<\/span><em style=\"letter-spacing: 1.4px;\">Tsara Tsara<\/em><span style=\"letter-spacing: 1.4px;\">\u00a0\u00bb en featuring avec le roi du salegy <\/span><strong style=\"letter-spacing: 1.4px;\">Jaojoby<\/strong><span style=\"letter-spacing: 1.4px;\">, une autre reconnaissance en somme.<\/span><\/p><p>Ibonia<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d9da6 elementor-widget elementor-widget-heading\" data-id=\"d8d9da6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Denise<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bfa774b elementor-widget elementor-widget-heading\" data-id=\"1bfa774b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Tsara joro<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-299a292a elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"299a292a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d47d3f3\" data-id=\"1d47d3f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a363918 elementor-widget elementor-widget-image\" data-id=\"5a363918\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3.8,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"2048\" height=\"2048\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6.jpeg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6.jpeg 2048w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6-150x150.jpeg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6-300x300.jpeg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6-768x768.jpeg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/EdDqommXgAIG3D6-1024x1024.jpeg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b0ce83e\" data-id=\"4b0ce83e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a28ee67 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a28ee67\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4832c52c elementor-widget elementor-widget-text-editor\" data-id=\"4832c52c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Parmi les albums qui ont marqu\u00e9 2020, nous pouvons retenir l\u2019album <em>No future<\/em>\u00a0de <strong>Wit.<\/strong> sorti au mois de juillet. Dans cet album \u00ab innovant\u00a0\u00bb compos\u00e9 de 11 titres, <b>Wit.<\/b> prouve encore une fois son talent et sa volont\u00e9 de livrer un rap diff\u00e9rent. A l\u2019image de la cover, <strong>Wit.<\/strong> nous emm\u00e8ne dans un nouvel univers travaill\u00e9 m\u00e9ticuleusement. Nous retrouvons <strong>Wit.<\/strong> au premier plan de la cover, le visage d\u00e9figur\u00e9 et avec un air mena\u00e7ant sur un fond compl\u00e8tement noir. En effet, apr\u00e8s l\u2019album <em>N\u00e9o<\/em>, c\u2019est une tout autre couleur musicale qui est pr\u00e9sente sur <em>No<\/em> <em>future<\/em>. Avec des sonorit\u00e9s \u00e0 la fois sombres et nouvelles, <strong>Wit.<\/strong> nous plonge dans un espace-temps incertain et myst\u00e9rieux. Avec une \u00e9criture travaill\u00e9e sur des m\u00e9lodies venant d\u2019ailleurs, <strong>Wit.<\/strong> n\u2019en finit plus de nous montrer son talent. Bref, cet album est un r\u00e9el coup de c\u0153ur de l\u2019ann\u00e9e 2020, alors n\u2019h\u00e9sitez pas \u00e0 vous replonger dedans ou d\u2019aller le d\u00e9couvrir si vous ne l\u2019avez encore jamais \u00e9cout\u00e9\u00a0!<\/p><p>Quentin<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61538c48 elementor-widget elementor-widget-heading\" data-id=\"61538c48\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wit.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-929ea05 elementor-widget elementor-widget-heading\" data-id=\"929ea05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>No future<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-201063af elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"201063af\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-782df747\" data-id=\"782df747\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eaddf4e elementor-widget elementor-widget-image\" data-id=\"1eaddf4e\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.3,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1000\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1.jpg 1000w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a640215\" data-id=\"7a640215\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62946b02 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"62946b02\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc9b513 elementor-widget elementor-widget-text-editor\" data-id=\"3fc9b513\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Membre du groupe <strong>Les Gars Laxistes<\/strong>, <strong>N\u00e9pal<\/strong> a su imposer sa plume et son style \u00e0 travers les projets <em>444<\/em> et <em>445Nuits<\/em> qui ont fait na\u00eetre quelques classiques comme le morceau &#8220;<em>Rien de sp\u00e9cial&#8221;<\/em>. Le 10 janvier 2020, l\u2019album post-mortem <em>Adios Bahamas<\/em> du regrett\u00e9 <strong>N\u00e9pal<\/strong> voyait le jour et marquait le d\u00e9but d\u2019une ann\u00e9e riche en proposition artistique. Ce nouvel opus porte sur lui une symbolique forte, celle du premier et dernier album de l\u2019artiste. Le rappeur originaire de Paris nous livre un projet tr\u00e8s optimiste qui aborde des th\u00e8mes tel que \u00ab\u00a0l\u2019ennui b\u00e9n\u00e9fique\u00a0\u00bb, la spiritualit\u00e9, le retour \u00e0 des valeurs simples ou encore l\u2019id\u00e9e de faire de sa diff\u00e9rence un atout. Les instrus de l\u2019album donnent \u00e0 chacun des titres une identit\u00e9 marqu\u00e9e tout en assurant une coh\u00e9rence globale entre m\u00e9lodie et m\u00e9lancolie. Les collaborations apportent une r\u00e9elle valeur ajout\u00e9e \u00e0 l\u2019univers du projet. On retrouve des artistes bien connus de la sc\u00e8ne rap comme <strong>Nekfeu<\/strong> et <strong>Doums<\/strong>, et d\u2019autres moins populaires mais tout aussi talentueux comme <strong>Sheldon<\/strong> qui se d\u00e9marque gr\u00e2ce \u00e0 sa voix et son flow. Cette recette unique nous transmet au fil des titres de l\u2019\u00e9motion et un regard neuf sur soi-m\u00eame et sur le monde qui nous entoure. <strong>N\u00e9pal<\/strong> nous offre en conclusion de carri\u00e8re une \u0153uvre forte, pleine de musicalit\u00e9 et de messages optimistes. Peu importe si vous l\u2019\u00e9coutez pour son ambiance, ses paroles ou ses id\u00e9es, <em>Adios Bahamas<\/em> saura vous toucher.<\/p><p>Thomas Q<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-345c9069 elementor-widget elementor-widget-heading\" data-id=\"345c9069\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">N\u00e9pal<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307aa0a1 elementor-widget elementor-widget-heading\" data-id=\"307aa0a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Adios bahamas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1be51b91 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1be51b91\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-568fe44d\" data-id=\"568fe44d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-457e34c9 elementor-widget elementor-widget-image\" data-id=\"457e34c9\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1200\" height=\"1200\" src=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9.jpg 1200w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9-150x150.jpg 150w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9-300x300.jpg 300w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9-768x768.jpg 768w, https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9-1024x1024.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-747ae931\" data-id=\"747ae931\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53e4584b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"53e4584b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d876e79 elementor-widget elementor-widget-text-editor\" data-id=\"2d876e79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>En ao\u00fbt dernier sortait <em>Enna<\/em>, le deuxi\u00e8me album du rappeur <strong>PLK<\/strong>. <em>Enna<\/em>\u00a0seconde son album <em>Polak<\/em>\u00a0sorti en 2018 et sa mixtape\u00a0<em>Mental<\/em>, certifi\u00e9e\u00a0disque de platine\u00a0apr\u00e8s 10 mois d&#8217;exploitation. Le titre du projet,\u00a0<em>Enna<\/em>, r\u00e9sulte de la fusion des pr\u00e9noms de son fr\u00e8re et de sa s\u0153ur, <strong>Enzo<\/strong> et <strong>Lena<\/strong>,\u00a0pr\u00e9sents sur la pochette. En f\u00e9vrier 2015, <strong>PLK<\/strong> avait d&#8217;ailleurs d\u00e9j\u00e0 sorti\u00a0un morceau du m\u00eame nom, sur le projet\u00a0<em>Peur<\/em><i> de me tromper<\/i>. Sous licence chez\u00a0<strong>Panenka<\/strong> <strong>Music<\/strong>,\u00a0<em>Enna<\/em>\u00a0est aussi le nom du label qui produit <strong>PLK<\/strong>. D\u00e9voil\u00e9 le 28 ao\u00fbt, l\u2019album\u00a0s&#8217;est \u00e9coul\u00e9 \u00e0\u00a034 739 exemplaires en une semaine et devient disque d\u2019or seulement 14 jours apr\u00e8s sa sortie, alors qu&#8217;il \u00e9tait \u00e0 plus de\u00a019\u00a0000 ventes en seulement trois jours.\u00a0Avec ce score, il signe ainsi la meilleure premi\u00e8re semaine de sa carri\u00e8re puisque son premier album <em>Polak<\/em> s&#8217;\u00e9tait \u00e9coul\u00e9 \u00e0 un peu plus de 12\u00a0000 ventes. L\u2019album est compos\u00e9 de 18 morceaux, dont 4 feats tr\u00e8s prometteurs avec : <strong>Niska<\/strong>, <strong>Hamza<\/strong>, <strong>Rim\u2019k<\/strong> ou encore <strong>Heuss<\/strong> <strong>l\u2019Enfoir\u00e9<\/strong>. On retrouve donc <strong>Niska<\/strong> d\u00e8s le second morceau, \u201c<em>On<\/em> <em>sait<\/em> <em>jamais<\/em>\u201d, dont la m\u00e9lodie du morceau est guid\u00e9e par une fl\u00fbte qui enchante l\u2019auditeur coupl\u00e9e aux cuts et drumbass, <strong>Heuss<\/strong> <strong>l\u2019Enfoir\u00e9<\/strong> apporte ensuite sa touche de saxophone dans \u201c<em>Chandon<\/em> <em>et<\/em> <em>Mo\u00ebt<\/em>\u201d. <strong>PLK<\/strong> a laiss\u00e9 libre court \u00e0 <strong>Rim\u2019K<\/strong>, qui offre m\u00eame\u00a0un couplet clin d\u2019oeil \u00e0 son titre \u201c<em>Pour<\/em> <em>ceux<\/em>\u201d. Pour finir <strong>Hamza<\/strong> est pr\u00e9sent sur \u201c<em>Pilote<\/em>\u201d, avant-dernier morceau de l\u2019opus, et ce titre est certainement le plus pertinent, au rythme endiabl\u00e9, puisque compl\u00e8tement assimil\u00e9 \u00e0 l\u2019ambiance festive de\u00a0<em>Enna<\/em>. Un sans-faute, donc, et une belle revanche sur quelques d\u00e9tracteurs qui voyaient difficilement la pertinence de certains noms dans cet album tant attendu puisqu\u2019en effet, \u00e0 seulement 23 ans, le rappeur fran\u00e7ais semble devenir une v\u00e9ritable star nationale. <em>Enna<\/em> refl\u00e8te assez bien les diff\u00e9rents traits de la personnalit\u00e9 de <strong>PLK<\/strong> : le bad-boy lover, le petit-fils sensible ou le rappeur teint\u00e9 d\u2019ego-trip. Il y \u00e9voque son enfance, sa famille, son \u00e9volution, le tout en s&#8217;attaquant \u00e0 la trap, au boom bap, \u00e0 la zumba et \u00e0 la drill, avec une aisance d\u00e9concertante. Seul regret : des promesses autour de la direction artistique qui s\u2019\u00e9vaporent \u00e0 la premi\u00e8re \u00e9coute\u2026 Cette esp\u00e8ce de course-poursuite dans un monde futuriste, qui pr\u00e9sentait l\u2019album via son trailer, a compl\u00e8tement disparu du projet. S\u2019il s\u2019av\u00e8re coh\u00e9rent et plaisant,\u00a0<em>Enna<\/em>\u00a0aurait peut-\u00eatre m\u00e9rit\u00e9 quelques interludes, intro ou outro sc\u00e9naris\u00e9es, pour r\u00e9ellement immerger au c\u0153ur de l\u2019univers personnel de <strong>PLK<\/strong>. Jusque-l\u00e0, l\u2019introspection pr\u00e9sent\u00e9e est rest\u00e9e en surface. Dans l&#8217;attente d\u2019\u00e9ventuels clips, pouvant prolonger cette direction artistique, qui s\u2019av\u00e9rait prometteuse.<\/p><p>Lilian<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598ec97 elementor-widget elementor-widget-heading\" data-id=\"598ec97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PLK<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380035dc elementor-widget elementor-widget-heading\" data-id=\"380035dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Enna<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f0e841 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f0e841\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5beea09\" data-id=\"5beea09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a88d235 elementor-widget elementor-widget-spacer\" data-id=\"a88d235\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d3f035 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d3f035\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17da428\" data-id=\"17da428\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0001d0 elementor-widget elementor-widget-heading\" data-id=\"b0001d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Enjoy 2021 &amp; Stay Tuned<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd8992b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd8992b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e9e297\" data-id=\"9e9e297\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecaf6c1 elementor-widget elementor-widget-spacer\" data-id=\"ecaf6c1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a4a0a7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a4a0a7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4df472\" data-id=\"d4df472\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f2fe3a elementor-widget elementor-widget-gallery\" data-id=\"0f2fe3a\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:5,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;custom&quot;,&quot;image_hover_animation&quot;:&quot;grow&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;url&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Man_on_the_Moon_III_The_Chosen-2-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/1bc2c297a4dec86a17eafcf1ad8254fb.1000x1000x1-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/witt-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/f1162d013287c31d9bd33e6baf355401.1000x1000x1-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/cover-whole-lotta-red-album-300x300.png\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/nas-king-300x300.jpeg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Infinit-240x300.jpg\" data-width=\"240\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/theweek-300x296.jpg\" data-width=\"300\" data-height=\"296\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Claire-Faravarjoo-Nightclub-par-Naissa-B.-Artwork-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/80740718c2b95bf5aa5c7037ff0cb711.1000x1000x1-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/600x600bb-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/airod-burn-injury-cover-300x295.jpg\" data-width=\"300\" data-height=\"295\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/sfera-ebbasta-famoso-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71zqQLosx6L._SL1400_-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Ef9xZkHXYAYza6Z-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/Egq92EIXcAApZt9-300x300.jpg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/miley-cyrus-plastic-hearts-300x300.jpeg\" data-width=\"300\" data-height=\"300\" alt=\"\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020 En ce d\u00e9but d&#8217;ann\u00e9e 2021, Start It va te faire d\u00e9couvrir les albums qui ont le plus marqu\u00e9 notre ann\u00e9e 2020. Une ann\u00e9e qui a pourtant \u00e9t\u00e9 un peu sp\u00e9ciale et nous a tous plus ou moins touch\u00e9s mais qui, musicalement, a su nous g\u00e2ter. Dix ans &#8230; <a title=\"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020\" class=\"read-more\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/\">Lire la suite <span class=\"screen-reader-text\">Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":9049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"cybocfi_hide_featured_image":"yes"},"categories":[840],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#039;ann\u00e9e 2020 - Start It<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#039;ann\u00e9e 2020 - Start It\" \/>\n<meta property=\"og:description\" content=\"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020 En ce d\u00e9but d&#8217;ann\u00e9e 2021, Start It va te faire d\u00e9couvrir les albums qui ont le plus marqu\u00e9 notre ann\u00e9e 2020. Une ann\u00e9e qui a pourtant \u00e9t\u00e9 un peu sp\u00e9ciale et nous a tous plus ou moins touch\u00e9s mais qui, musicalement, a su nous g\u00e2ter. Dix ans ... Lire la suite Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Start It\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T15:16:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T17:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin2897\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/startitkbs.org\/#website\",\"url\":\"http:\/\/startitkbs.org\/\",\"name\":\"Start It\",\"description\":\"Association musicale Bordelaise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/startitkbs.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#webpage\",\"url\":\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/\",\"name\":\"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e 2020 - Start It\",\"isPartOf\":{\"@id\":\"http:\/\/startitkbs.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#primaryimage\"},\"datePublished\":\"2021-01-15T15:16:35+00:00\",\"dateModified\":\"2021-02-17T17:01:14+00:00\",\"author\":{\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/8c88adfb2a5b438d677c5af9c9a39911\"},\"breadcrumb\":{\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/startitkbs.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/startitkbs.org\/#\/schema\/person\/8c88adfb2a5b438d677c5af9c9a39911\",\"name\":\"admin2897\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/startitkbs.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d10c7dbba691436d15270e320ee1de0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d10c7dbba691436d15270e320ee1de0d?s=96&d=mm&r=g\",\"caption\":\"admin2897\"},\"url\":\"https:\/\/startitkbs.org\/index.php\/author\/admin2897\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e 2020 - Start It","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e 2020 - Start It","og_description":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020 En ce d\u00e9but d&#8217;ann\u00e9e 2021, Start It va te faire d\u00e9couvrir les albums qui ont le plus marqu\u00e9 notre ann\u00e9e 2020. Une ann\u00e9e qui a pourtant \u00e9t\u00e9 un peu sp\u00e9ciale et nous a tous plus ou moins touch\u00e9s mais qui, musicalement, a su nous g\u00e2ter. Dix ans ... Lire la suite Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020","og_url":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/","og_site_name":"Start It","article_publisher":"https:\/\/www.facebook.com\/startitkedgebs\/?ref=br_rs","article_published_time":"2021-01-15T15:16:35+00:00","article_modified_time":"2021-02-17T17:01:14+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/startitkbs.org\/wp-content\/uploads\/2021\/01\/71KcaBR6hPL._SL1200_-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin2897","Dur\u00e9e de lecture estim\u00e9e":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/startitkbs.org\/#website","url":"http:\/\/startitkbs.org\/","name":"Start It","description":"Association musicale Bordelaise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/startitkbs.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#webpage","url":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/","name":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e 2020 - Start It","isPartOf":{"@id":"http:\/\/startitkbs.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#primaryimage"},"datePublished":"2021-01-15T15:16:35+00:00","dateModified":"2021-02-17T17:01:14+00:00","author":{"@id":"http:\/\/startitkbs.org\/#\/schema\/person\/8c88adfb2a5b438d677c5af9c9a39911"},"breadcrumb":{"@id":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/startitkbs.org\/index.php\/2021\/01\/15\/retour-sur-nos-albums-preferes-de-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/startitkbs.org\/"},{"@type":"ListItem","position":2,"name":"Retour sur nos albums pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e 2020"}]},{"@type":"Person","@id":"http:\/\/startitkbs.org\/#\/schema\/person\/8c88adfb2a5b438d677c5af9c9a39911","name":"admin2897","image":{"@type":"ImageObject","@id":"http:\/\/startitkbs.org\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/d10c7dbba691436d15270e320ee1de0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d10c7dbba691436d15270e320ee1de0d?s=96&d=mm&r=g","caption":"admin2897"},"url":"https:\/\/startitkbs.org\/index.php\/author\/admin2897\/"}]}},"_links":{"self":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/9019"}],"collection":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/comments?post=9019"}],"version-history":[{"count":47,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/9019\/revisions"}],"predecessor-version":[{"id":12709,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/posts\/9019\/revisions\/12709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media\/9049"}],"wp:attachment":[{"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/media?parent=9019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/categories?post=9019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startitkbs.org\/index.php\/wp-json\/wp\/v2\/tags?post=9019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}